{"text_format":"1","workbook":"xlsx","n_sheets":26,"sheets":["Change Log","Inputs","Outputs","Allocation Summary","DNO - Final Allocation","Calc - DNO Opex Allocation","Calc-Units","Calc-Drivers","Calc-MEAV","Calc-Net capex","Summary of revenue","Allowed revenue -DPCR4","FBPQ T4","FBPQ LR1","FBPQ LR1 - V5 opt3","FBPQ LR4","FBPQ LR6","FBPQ NL1 0309","NL9 - Legal & Safety","FBPQ C2","RRP 1.3","RRP 2.3","RRP 2.4","RRP 2.6","RRP 5.1","LR1 Refs"],"not_rendered":{"charts":0,"images":3,"macros":1,"external_links":10,"defined_names":65,"comments":1,"pivot_tables":0},"unopened":[],"bounds":{"document_bytes":16777216,"sheet_cells":100000,"rows_first":2000,"rows_last":500,"rows_between":2000,"halvings":0,"cell_chars":16384,"cell_head_chars":4096},"cells_cut":0,"cells_raw":0,"read":"whole","date_system":"1900"}

{"sheet":"Change Log","index":0,"n_rows":13,"n_cols":4,"rows_kept":13,"cut":false,"hidden":false,"merged":[]}
[]
["Method M Version No.",null,"[Extended Disaggregation Model PB LZ v1.0]"]
["Release Date:",null,"[01 April 2013]"]
[]
[]
[]
[]
["This version of Method M incorporates the following change proposals:"]
[]
["Ref","Approval Date","Implementation Date","Title"]
["DCP 071A","2011-06-20","2011-10-01","Allocation of Costs to HV Connected IDNOs with LV End Users"]
["DCP 095","2011-12-09","2012-04-01","Not included in this model"]
["DCP 096","2011-12-09","2012-04-01","Treatment of Transmission Exit Charges in CDCM Price Control Disaggregation Model (Method M)"]

{"sheet":"Inputs","index":1,"n_rows":41,"n_cols":6,"rows_kept":41,"cut":false,"hidden":false,"merged":[]}
[{"$f":"\"Extended Method M for \"&B5&\" in \"&B6&\"  Status: \"&B7&\"\"","v":"Extended Method M for WPD West Midlands in 2014/15  Status: Indicative"}]
[]
[]
["1000. Company, charging year, data version"]
["DNO","WPD West Midlands"]
["Charging Year","2014/15"]
["Version","Indicative"]
[]
[]
["1001. LV/HV Split"]
["Sources: HV main usage value provided each year by the Nominated Calculation Agent"]
["DNO LV Main usage",0.182]
["DNO HV Main usage",0.4]
["DNO 33kV split",1]
["DNO 132kV split",1]
[]
[]
["1002. Method M input data"]
["Each DNO selects one of the options below to calculate the LDNO discounts:"]
["'LR1 opt 3' is an extended version of LR1, which contains all information from LR1, but breaks down certain lines into more detail."]
["Version LR1"]
["Version LR1, Option 3"]
[]
[]
[null,"This spreadsheet is currently using version: ","LR1"]
[]
["1003. Depreciation Factor"]
["Depreciation Factor",5.5449999999999999E-2]
[]
[]
["1004. CDCM Discounts"]
["Sources: CDCM Table 1037. (Embedded network (LDNO) discounts)"]
[null,"No discount","LDNO LV: LV user","LDNO HV: LV user","LDNO HV: LV sub user","LDNO HV: HV user"]
["LDNO discount using data in this model",null,0.312473568523504,0.52746731858934703,0.29011342615872981,0.19111577149774819]
[]
["Additional Input Links"]
["Calc-Net capex'!K5","Suggest these values are set to 0 for those using LR1"]
["Calc-Net capex'!O6 to O10","Suggest these values are set to 0 for those using LR1"]
[]
["Notes"]
[" - Where DNOs do not hold asset data required by the Method M model within the RRP data tables, the DNO can substitute equivalent data within the Method M input tables."]

{"sheet":"Outputs","index":2,"n_rows":30,"n_cols":7,"rows_kept":30,"cut":false,"hidden":false,"merged":[[4,1,4,4]]}
[{"$f":"\"Extended Method M for \"&Inputs!B5&\" in \"&Inputs!B6&\"  Status: \"&Inputs!B7&\"\"","v":"Extended Method M for WPD West Midlands in 2014/15  Status: Indicative"},null,null,null,null,null,"Index"]
[]
["The data table below is used to populate EDCM table 1181 (LDNO discounts)"]
[]
[]
["Boundary category","LV demand end user","LV Sub demand or LV generation end user","HV demand or LV Sub generation end user","HV generation end user"]
["Boundary 0000",{"$f":"IF((SUM('Allocation Summary'!B$13:H$13)-SUMPRODUCT('Allocation Summary'!B22:E22,'Allocation Summary'!E$13:H$13))/(1-SUMPRODUCT('Allocation Summary'!F22:I22,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!B$13:H$13)-SUMPRODUCT('Allocation Summary'!B22:E22,'Allocation Summary'!E$13:H$13))/(1-SUMPRODUCT('Allocation Summary'!F22:I22,'Allocation Summary'!E$13:H$13)))","v":0.95477119186788706},{"$f":"IF((SUM('Allocation Summary'!C$13:H$13)-SUMPRODUCT('Allocation Summary'!B22:E22,'Allocation Summary'!E$13:H$13))/(1-'Allocation Summary'!B$13-SUMPRODUCT('Allocation Summary'!F22:I22,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!C$13:H$13)-SUMPRODUCT('Allocation Summary'!B22:E22,'Allocation Summary'!E$13:H$13))/(1-'Allocation Summary'!B$13-SUMPRODUCT('Allocation Summary'!F22:I22,'Allocation Summary'!E$13:H$13)))","v":0.93243870530807393},{"$f":"IF((SUM('Allocation Summary'!D$13:H$13)-SUMPRODUCT('Allocation Summary'!B22:E22,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:C$13)-SUMPRODUCT('Allocation Summary'!F22:I22,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!D$13:H$13)-SUMPRODUCT('Allocation Summary'!B22:E22,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:C$13)-SUMPRODUCT('Allocation Summary'!F22:I22,'Allocation Summary'!E$13:H$13)))","v":0.92319812835406889},{"$f":"IF((SUM('Allocation Summary'!E$13:H$13)-SUMPRODUCT('Allocation Summary'!B22:E22,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:D$13)-SUMPRODUCT('Allocation Summary'!F22:I22,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!E$13:H$13)-SUMPRODUCT('Allocation Summary'!B22:E22,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:D$13)-SUMPRODUCT('Allocation Summary'!F22:I22,'Allocation Summary'!E$13:H$13)))","v":0.89258561156060345}]
["Boundary 132kV",{"$f":"IF((SUM('Allocation Summary'!B$13:H$13)-SUMPRODUCT('Allocation Summary'!B23:E23,'Allocation Summary'!E$13:H$13))/(1-SUMPRODUCT('Allocation Summary'!F23:I23,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!B$13:H$13)-SUMPRODUCT('Allocation Summary'!B23:E23,'Allocation Summary'!E$13:H$13))/(1-SUMPRODUCT('Allocation Summary'!F23:I23,'Allocation Summary'!E$13:H$13)))","v":0.78418940312139573},{"$f":"IF((SUM('Allocation Summary'!C$13:H$13)-SUMPRODUCT('Allocation Summary'!B23:E23,'Allocation Summary'!E$13:H$13))/(1-'Allocation Summary'!B$13-SUMPRODUCT('Allocation Summary'!F23:I23,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!C$13:H$13)-SUMPRODUCT('Allocation Summary'!B23:E23,'Allocation Summary'!E$13:H$13))/(1-'Allocation Summary'!B$13-SUMPRODUCT('Allocation Summary'!F23:I23,'Allocation Summary'!E$13:H$13)))","v":0.67762928240853715},{"$f":"IF((SUM('Allocation Summary'!D$13:H$13)-SUMPRODUCT('Allocation Summary'!B23:E23,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:C$13)-SUMPRODUCT('Allocation Summary'!F23:I23,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!D$13:H$13)-SUMPRODUCT('Allocation Summary'!B23:E23,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:C$13)-SUMPRODUCT('Allocation Summary'!F23:I23,'Allocation Summary'!E$13:H$13)))","v":0.63353759593027703},{"$f":"IF((SUM('Allocation Summary'!E$13:H$13)-SUMPRODUCT('Allocation Summary'!B23:E23,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:D$13)-SUMPRODUCT('Allocation Summary'!F23:I23,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!E$13:H$13)-SUMPRODUCT('Allocation Summary'!B23:E23,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:D$13)-SUMPRODUCT('Allocation Summary'!F23:I23,'Allocation Summary'!E$13:H$13)))","v":0.48746906584970257}]
["Boundary 132kV/EHV",{"$f":"IF((SUM('Allocation Summary'!B$13:H$13)-SUMPRODUCT('Allocation Summary'!B24:E24,'Allocation Summary'!E$13:H$13))/(1-SUMPRODUCT('Allocation Summary'!F24:I24,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!B$13:H$13)-SUMPRODUCT('Allocation Summary'!B24:E24,'Allocation Summary'!E$13:H$13))/(1-SUMPRODUCT('Allocation Summary'!F24:I24,'Allocation Summary'!E$13:H$13)))","v":0.67384444767452001},{"$f":"IF((SUM('Allocation Summary'!C$13:H$13)-SUMPRODUCT('Allocation Summary'!B24:E24,'Allocation Summary'!E$13:H$13))/(1-'Allocation Summary'!B$13-SUMPRODUCT('Allocation Summary'!F24:I24,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!C$13:H$13)-SUMPRODUCT('Allocation Summary'!B24:E24,'Allocation Summary'!E$13:H$13))/(1-'Allocation Summary'!B$13-SUMPRODUCT('Allocation Summary'!F24:I24,'Allocation Summary'!E$13:H$13)))","v":0.5127996448258334},{"$f":"IF((SUM('Allocation Summary'!D$13:H$13)-SUMPRODUCT('Allocation Summary'!B24:E24,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:C$13)-SUMPRODUCT('Allocation Summary'!F24:I24,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!D$13:H$13)-SUMPRODUCT('Allocation Summary'!B24:E24,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:C$13)-SUMPRODUCT('Allocation Summary'!F24:I24,'Allocation Summary'!E$13:H$13)))","v":0.44616367530313128},{"$f":"IF((SUM('Allocation Summary'!E$13:H$13)-SUMPRODUCT('Allocation Summary'!B24:E24,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:D$13)-SUMPRODUCT('Allocation Summary'!F24:I24,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!E$13:H$13)-SUMPRODUCT('Allocation Summary'!B24:E24,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:D$13)-SUMPRODUCT('Allocation Summary'!F24:I24,'Allocation Summary'!E$13:H$13)))","v":0.22540963080827564}]
["Boundary EHV",{"$f":"IF((SUM('Allocation Summary'!B$13:H$13)-SUMPRODUCT('Allocation Summary'!B25:E25,'Allocation Summary'!E$13:H$13))/(1-SUMPRODUCT('Allocation Summary'!F25:I25,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!B$13:H$13)-SUMPRODUCT('Allocation Summary'!B25:E25,'Allocation Summary'!E$13:H$13))/(1-SUMPRODUCT('Allocation Summary'!F25:I25,'Allocation Summary'!E$13:H$13)))","v":0.65955024574323806},{"$f":"IF((SUM('Allocation Summary'!C$13:H$13)-SUMPRODUCT('Allocation Summary'!B25:E25,'Allocation Summary'!E$13:H$13))/(1-'Allocation Summary'!B$13-SUMPRODUCT('Allocation Summary'!F25:I25,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!C$13:H$13)-SUMPRODUCT('Allocation Summary'!B25:E25,'Allocation Summary'!E$13:H$13))/(1-'Allocation Summary'!B$13-SUMPRODUCT('Allocation Summary'!F25:I25,'Allocation Summary'!E$13:H$13)))","v":0.49144743969488364},{"$f":"IF((SUM('Allocation Summary'!D$13:H$13)-SUMPRODUCT('Allocation Summary'!B25:E25,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:C$13)-SUMPRODUCT('Allocation Summary'!F25:I25,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!D$13:H$13)-SUMPRODUCT('Allocation Summary'!B25:E25,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:C$13)-SUMPRODUCT('Allocation Summary'!F25:I25,'Allocation Summary'!E$13:H$13)))","v":0.42189105996468118},{"$f":"IF((SUM('Allocation Summary'!E$13:H$13)-SUMPRODUCT('Allocation Summary'!B25:E25,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:D$13)-SUMPRODUCT('Allocation Summary'!F25:I25,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!E$13:H$13)-SUMPRODUCT('Allocation Summary'!B25:E25,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:D$13)-SUMPRODUCT('Allocation Summary'!F25:I25,'Allocation Summary'!E$13:H$13)))","v":0.19146217514698563}]
["Boundary HVplus",{"$f":"IF((SUM('Allocation Summary'!B$13:H$13)-SUMPRODUCT('Allocation Summary'!B26:E26,'Allocation Summary'!E$13:H$13))/(1-SUMPRODUCT('Allocation Summary'!F26:I26,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!B$13:H$13)-SUMPRODUCT('Allocation Summary'!B26:E26,'Allocation Summary'!E$13:H$13))/(1-SUMPRODUCT('Allocation Summary'!F26:I26,'Allocation Summary'!E$13:H$13)))","v":0.57893156783524258},{"$f":"IF((SUM('Allocation Summary'!C$13:H$13)-SUMPRODUCT('Allocation Summary'!B26:E26,'Allocation Summary'!E$13:H$13))/(1-'Allocation Summary'!B$13-SUMPRODUCT('Allocation Summary'!F26:I26,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!C$13:H$13)-SUMPRODUCT('Allocation Summary'!B26:E26,'Allocation Summary'!E$13:H$13))/(1-'Allocation Summary'!B$13-SUMPRODUCT('Allocation Summary'!F26:I26,'Allocation Summary'!E$13:H$13)))","v":0.3710219303622968},{"$f":"IF((SUM('Allocation Summary'!D$13:H$13)-SUMPRODUCT('Allocation Summary'!B26:E26,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:C$13)-SUMPRODUCT('Allocation Summary'!F26:I26,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!D$13:H$13)-SUMPRODUCT('Allocation Summary'!B26:E26,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:C$13)-SUMPRODUCT('Allocation Summary'!F26:I26,'Allocation Summary'!E$13:H$13)))","v":0.28499456393346306},{"$f":"IF((SUM('Allocation Summary'!E$13:H$13)-SUMPRODUCT('Allocation Summary'!B26:E26,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:D$13)-SUMPRODUCT('Allocation Summary'!F26:I26,'Allocation Summary'!E$13:H$13))>1,1,(SUM('Allocation Summary'!E$13:H$13)-SUMPRODUCT('Allocation Summary'!B26:E26,'Allocation Summary'!E$13:H$13))/(1-SUM('Allocation Summary'!B$13:D$13)-SUMPRODUCT('Allocation Summary'!F26:I26,'Allocation Summary'!E$13:H$13)))","v":0}]
[]
[]
[]
[]
["Input data reconciliation check"]
["Compares results to current CDCM Method M*"]
[null,"LDNO LV: LV user","LDNO HV: LV user","LDNO HV: LV sub user","LDNO HV: HV user"]
["LDNO discount using data in this model",{"$f":"'Allocation Summary'!B9*(1-'Allocation Summary'!B10*Inputs!B12)","v":0.29590724585640876},{"$f":"'Allocation Summary'!B9+'Allocation Summary'!C9+'Allocation Summary'!D9*(1-'Allocation Summary'!D10*Inputs!B13)","v":0.52104089389720865},{"$f":"('Allocation Summary'!C9+'Allocation Summary'!D9*(1-'Allocation Summary'!D10*Inputs!B13))/(1-'Allocation Summary'!B9)","v":0.28454676014739239},{"$f":"'Allocation Summary'!D9*(1-'Allocation Summary'!D10*Inputs!B13)/(1-'Allocation Summary'!B9-'Allocation Summary'!C9)","v":0.18669190478979777}]
["LDNO discount using Method M",{"$f":"+Inputs!C34","v":0.312473568523504},{"$f":"+Inputs!D34","v":0.52746731858934703},{"$f":"+Inputs!E34","v":0.29011342615872981},{"$f":"+Inputs!F34","v":0.19111577149774819}]
["*Note variances at LV:LV are expected as this version of extended Method M does not implement DCP095"]
[]
[]
[]
[]
["Comparrison to 2013 discounts",{"$f":"B7-'[9]Allocation Summary'!B25","v":0},{"$f":"C7-'[9]Allocation Summary'!C25","v":0},{"$f":"D7-'[9]Allocation Summary'!D25","v":0},{"$f":"E7-'[9]Allocation Summary'!E25","v":0}]
[null,{"$f":"B8-'[9]Allocation Summary'!B26","v":0},{"$f":"C8-'[9]Allocation Summary'!C26","v":0},{"$f":"D8-'[9]Allocation Summary'!D26","v":0},{"$f":"E8-'[9]Allocation Summary'!E26","v":0}]
[null,{"$f":"B9-'[9]Allocation Summary'!B27","v":0},{"$f":"C9-'[9]Allocation Summary'!C27","v":0},{"$f":"D9-'[9]Allocation Summary'!D27","v":0},{"$f":"E9-'[9]Allocation Summary'!E27","v":0}]
[null,{"$f":"B10-'[9]Allocation Summary'!B28","v":0},{"$f":"C10-'[9]Allocation Summary'!C28","v":0},{"$f":"D10-'[9]Allocation Summary'!D28","v":0},{"$f":"E10-'[9]Allocation Summary'!E28","v":0}]
[null,{"$f":"B11-'[9]Allocation Summary'!B29","v":0},{"$f":"C11-'[9]Allocation Summary'!C29","v":0},{"$f":"D11-'[9]Allocation Summary'!D29","v":0},{"$f":"E11-'[9]Allocation Summary'!E29","v":0}]

{"sheet":"Allocation Summary","index":3,"n_rows":26,"n_cols":9,"rows_kept":26,"cut":false,"hidden":false,"merged":[[2,1,2,5],[19,1,19,4],[19,5,19,8],[19,9,19,12]]}
[null,null,null,null,null,null,"Index"]
[]
["Category","% by network tier "]
[null,"LV","LV/HV","HV","EHV","Unallocated"]
["Opex and transmission exit charges",{"$f":"'DNO - Final Allocation'!I47","v":0.4614642843545223},{"$f":"'DNO - Final Allocation'!H47","v":8.969831053672904E-2},{"$f":"'DNO - Final Allocation'!G47","v":0.19859307439590398},{"$f":"'DNO - Final Allocation'!E47","v":0.25024433071284463}]
["Depreciation",{"$f":"'DNO - Final Allocation'!I46","v":0.1758419357288819},{"$f":"'DNO - Final Allocation'!H46","v":5.3178230445720967E-2},{"$f":"'DNO - Final Allocation'!G46","v":0.20608048808998844},{"$f":"'DNO - Final Allocation'!E46","v":0.56489934573540879}]
["Return",{"$f":"'DNO - Final Allocation'!I45","v":0.1758419357288819},{"$f":"'DNO - Final Allocation'!H45","v":5.3178230445720967E-2},{"$f":"'DNO - Final Allocation'!G45","v":0.20608048808998844},{"$f":"'DNO - Final Allocation'!E45","v":0.56489934573540879}]
["Weighted Average",{"$f":"'DNO - Final Allocation'!N50","v":0.26504377258192241},{"$f":"'DNO - Final Allocation'!M50","v":6.458370428841323E-2},{"$f":"'DNO - Final Allocation'!L50","v":0.20374211695760083},{"$f":"'DNO - Final Allocation'!K50","v":0.46663040617206353}]
["Weighted Average (after incentive and pension deficit costs removed and weighted by units flowing)",{"$f":"'DNO - Final Allocation'!O79","v":0.33055148900931242},{"$f":"'DNO - Final Allocation'!N79","v":8.0546090218639538E-2},{"$f":"'DNO - Final Allocation'!M79","v":0.1678339886072906},{"$f":"'DNO - Final Allocation'!L79","v":0.37583962403264448},{"$f":"'DNO - Final Allocation'!P79","v":4.5228808132113156E-2}]
["Direct cost %",{"$f":"'Calc - DNO Opex Allocation'!AA48","v":0.57586485218117034},{"$f":"'Calc - DNO Opex Allocation'!Z48","v":0.86079455692519979},{"$f":"'Calc - DNO Opex Allocation'!Y48","v":0.86232047540576717},{"$f":"'Calc - DNO Opex Allocation'!X48","v":0.70477800593723305},"N/A"]
[]
[null,"LV","HV/LV","HV","EHV/HV","EHV","132kV/EHV","132kV"]
["Weighted by units flowing",{"$f":"B9","v":0.33055148900931242},8.0546090218639538E-2,0.1678339886072906,{"$f":"E9*'Calc-MEAV'!$N28","v":7.4631029652603112E-2},{"$f":"E9*'Calc-MEAV'!$N29","v":2.0281850186674333E-2},{"$f":"E9*'Calc-MEAV'!$N30","v":3.8890546540395435E-2},{"$f":"E9*'Calc-MEAV'!$N31","v":0.2420361976529716}]
["Direct cost %",0.57586485218117034,0.86079455692519979,0.86232047540576717,{"$f":"E10","v":0.70477800593723305},{"$f":"E10","v":0.70477800593723305},{"$f":"E10","v":0.70477800593723305},{"$f":"E10","v":0.70477800593723305}]
[]
["Options","DCP071"]
[null,true]
["Discount matrix"]
[]
[null,"Network levels provided or bypassed by the DNO",null,null,null,"Network levels bypassed by the DNO"]
["Boundary category","EHV/HV","EHV","132kV/EHV","132kV","EHV/HV","EHV","132kV/EHV","132kV"]
["Boundary 0000",0,0,0,0,0,0,0,0]
["Boundary 132kV",0,0,0,{"$f":"IF($B$17,Inputs!$B$15*$H$14,1)","v":0.70477800593723305},0,0,0,0]
["Boundary 132kV/EHV",0,0,1,1,0,0,0,0]
["Boundary EHV",0,{"$f":"IF($B$17,Inputs!$B$14*$F$14,1)","v":0.70477800593723305},1,1,0,0,0,0]
["Boundary HVplus",1,1,1,1,0,0,0,0]

{"sheet":"DNO - Final Allocation","index":4,"n_rows":81,"n_cols":19,"rows_kept":81,"cut":false,"hidden":false,"merged":[[69,3,69,9],[69,11,69,17],[42,4,42,8],[42,10,42,13],[42,15,42,19],[68,3,68,10],[68,11,68,17]]}
["Step 1. Format price control allowed revenue data"]
["Index"]
[]
[null,"I) DPCR3 type presentation",null,null,null,null,null,null,null,null,null,"ii) DPCR4 type presentation"]
[]
[null,null,null,"2005/06","2006/07",null,"2007/08","2008/09","2009/10",null,null,null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10"]
[null,null,null,null,null,null,null,null,null,null,null,"Opening asset value",null,null,{"$f":"'Allowed revenue -DPCR4'!D3","v":964.7},{"$f":"'Allowed revenue -DPCR4'!E3","v":1013.2},{"$f":"'Allowed revenue -DPCR4'!F3","v":1057.4000000000001},{"$f":"'Allowed revenue -DPCR4'!G3","v":1095.0999999999999},{"$f":"'Allowed revenue -DPCR4'!H3","v":1126.5}]
[null,"Allowed revenue",null,{"$f":"O33","v":238.75220365682705},{"$f":"P33","v":240.42346908242482},null,{"$f":"Q33","v":242.33348671167943},{"$f":"R33","v":244.00475213727725},{"$f":"S33","v":245.67601756287502},null,null,"Total capex",null,null,{"$f":"'Allowed revenue -DPCR4'!D4","v":120.8},{"$f":"'Allowed revenue -DPCR4'!E4","v":120.4},{"$f":"'Allowed revenue -DPCR4'!F4","v":120},{"$f":"'Allowed revenue -DPCR4'!G4","v":119.5},{"$f":"'Allowed revenue -DPCR4'!H4","v":119.3}]
[null,null,null,null,null,null,null,null,null,null,null,"Depreciation",null,null,{"$f":"'Allowed revenue -DPCR4'!D5","v":-72.3},{"$f":"'Allowed revenue -DPCR4'!E5","v":-76.2},{"$f":"'Allowed revenue -DPCR4'!F5","v":-82.2},{"$f":"'Allowed revenue -DPCR4'!G5","v":-88.2},{"$f":"'Allowed revenue -DPCR4'!H5","v":-94.2}]
[null,"Opex (incl pensions after  57.7% capitalized)",null,{"$f":"O14+(1-0.577)*O16","v":79.352599999999995},{"$f":"P14+(1-0.577)*P16","v":76.852599999999995},null,{"$f":"Q14+(1-0.577)*Q16","v":74.852599999999995},{"$f":"R14+(1-0.577)*R16","v":73.45259999999999},{"$f":"S14+(1-0.577)*S16","v":72.852599999999995},null,null,"Closing asset value",null,null,{"$f":"'Allowed revenue -DPCR4'!D6","v":1013.2},{"$f":"'Allowed revenue -DPCR4'!E6","v":1057.4000000000001},{"$f":"'Allowed revenue -DPCR4'!F6","v":1095.0999999999999},{"$f":"'Allowed revenue -DPCR4'!G6","v":1126.5},{"$f":"'Allowed revenue -DPCR4'!H6","v":1151.5999999999999}]
[null,"Quality Reward",null,{"$f":"O20","v":""},{"$f":"P20","v":""},{"$f":"Q20","v":""},{"$f":"Q20","v":""},{"$f":"R20","v":""},{"$f":"S20","v":""},null,null,"Present value of opening/closing RAV",null,null,{"$f":"'Allowed revenue -DPCR4'!D7","v":964.7},null,{"$f":"'Allowed revenue -DPCR4'!F7","v":0},null,{"$f":"'Allowed revenue -DPCR4'!H7","v":879.3}]
[null,"DPCR3 costs",null,{"$f":"O21","v":0.9},null,null,null,null,null,null,null,"5 year movement in closing RAV",null,null,null,{"$f":"'Allowed revenue -DPCR4'!E8","v":0},null,null,{"$f":"'Allowed revenue -DPCR4'!H8","v":85.4}]
[null,"Total Opex",null,{"$f":"SUM(D10:D12)","v":80.252600000000001},{"$f":"SUM(E10:E12)","v":76.852599999999995},null,{"$f":"SUM(G10:G12)","v":74.852599999999995},{"$f":"SUM(H10:H12)","v":73.45259999999999},{"$f":"SUM(I10:I12)","v":72.852599999999995}]
[null,null,null,null,null,null,null,null,null,null,null,"Operating costs (excl pensions)",null,null,{"$f":"'Allowed revenue -DPCR4'!D10","v":72.5},{"$f":"'Allowed revenue -DPCR4'!E10","v":70},{"$f":"'Allowed revenue -DPCR4'!F10","v":68},{"$f":"'Allowed revenue -DPCR4'!G10","v":66.599999999999994},{"$f":"'Allowed revenue -DPCR4'!H10","v":66}]
[null,"Capital elements",null,null,null,null,null,null,null,null,null,"Capex (excl pensions)",null,null,{"$f":"'Allowed revenue -DPCR4'!D11","v":111.5},{"$f":"'Allowed revenue -DPCR4'!E11","v":111.1},{"$f":"'Allowed revenue -DPCR4'!F11","v":110.7},{"$f":"'Allowed revenue -DPCR4'!G11","v":110.2},{"$f":"'Allowed revenue -DPCR4'!H11","v":110}]
[null,"Depreciation",null,{"$f":"-O9","v":72.3},{"$f":"-P9","v":76.2},null,{"$f":"-Q9","v":82.2},{"$f":"-R9","v":88.2},{"$f":"-S9","v":94.2},null,null,"Pensions",null,null,{"$f":"'Allowed revenue -DPCR4'!D12","v":16.2},{"$f":"'Allowed revenue -DPCR4'!E12","v":16.2},{"$f":"'Allowed revenue -DPCR4'!F12","v":16.2},{"$f":"'Allowed revenue -DPCR4'!G12","v":16.2},{"$f":"'Allowed revenue -DPCR4'!H12","v":16.2}]
[null,"Tax allowance",null,{"$f":"O17","v":25.9},26.7,null,{"$f":"Q17","v":26.9},27,26.7,null,null,"Tax allowance",null,null,{"$f":"'Allowed revenue -DPCR4'!D13","v":25.9},{"$f":"'Allowed revenue -DPCR4'!E13","v":26.7},{"$f":"'Allowed revenue -DPCR4'!F13","v":26.9},{"$f":"'Allowed revenue -DPCR4'!G13","v":27},{"$f":"'Allowed revenue -DPCR4'!H13","v":26.7}]
[null,"Capital incentive",null,1.2,0.9,null,1,0.5,0.6,null,null,"Capex incentive",null,null,{"$f":"'Allowed revenue -DPCR4'!D14","v":1.2},{"$f":"'Allowed revenue -DPCR4'!E14","v":0.9},{"$f":"'Allowed revenue -DPCR4'!F14","v":1},{"$f":"'Allowed revenue -DPCR4'!G14","v":0.5},{"$f":"'Allowed revenue -DPCR4'!H14","v":0.6}]
[null,"Sliding scale",null,1.4,1.5,null,1.5,1.6,1.6,null,null,"Sliding scale addn income",null,null,{"$f":"'Allowed revenue -DPCR4'!D15","v":1.4},{"$f":"'Allowed revenue -DPCR4'!E15","v":1.5},{"$f":"'Allowed revenue -DPCR4'!F15","v":1.5},{"$f":"'Allowed revenue -DPCR4'!G15","v":1.6},{"$f":"'Allowed revenue -DPCR4'!H15","v":1.6}]
[null,"Return",null,{"$f":"D8-D13-D16-D17-D18-D19","v":57.699603656827051},{"$f":"E8-E13-E16-E17-E18-E19","v":58.270869082424817},null,{"$f":"G8-G13-G16-G17-G18-G19","v":55.88088671167943},{"$f":"H8-H13-H16-H17-H18-H19","v":53.252152137277257},{"$f":"I8-I13-I16-I17-I18-I19","v":49.723417562875014},null,null,"Quality reward/Opex incentive & Other Adjustments",null,null,{"$f":"IF(ISNUMBER('Allowed revenue -DPCR4'!D16+'Allowed revenue -DPCR4'!D17),'Allowed revenue -DPCR4'!D16+'Allowed revenue -DPCR4'!D17,\"\")","v":""},{"$f":"IF(ISNUMBER('Allowed revenue -DPCR4'!E16+'Allowed revenue -DPCR4'!E17),'Allowed revenue -DPCR4'!E16+'Allowed revenue -DPCR4'!E17,\"\")","v":""},{"$f":"IF(ISNUMBER('Allowed revenue -DPCR4'!F16+'Allowed revenue -DPCR4'!F17),'Allowed revenue -DPCR4'!F16+'Allowed revenue -DPCR4'!F17,\"\")","v":""},{"$f":"IF(ISNUMBER('Allowed revenue -DPCR4'!G16+'Allowed revenue -DPCR4'!G17),'Allowed revenue -DPCR4'!G16+'Allowed revenue -DPCR4'!G17,\"\")","v":""},{"$f":"IF(ISNUMBER('Allowed revenue -DPCR4'!H16+'Allowed revenue -DPCR4'!H17),'Allowed revenue -DPCR4'!H16+'Allowed revenue -DPCR4'!H17,\"\")","v":""}]
[null,"Total capital",null,{"$f":"SUM(D16:D20)","v":158.49960365682705},{"$f":"SUM(E16:E20)","v":163.57086908242482},null,{"$f":"SUM(G16:G20)","v":167.48088671167943},{"$f":"SUM(H16:H20)","v":170.55215213727726},{"$f":"SUM(I16:I20)","v":172.82341756287502},null,null,"DPCR3 costs",null,null,{"$f":"'Allowed revenue -DPCR4'!D18","v":0.9},{"$f":"'Allowed revenue -DPCR4'!E18","v":"-"},{"$f":"'Allowed revenue -DPCR4'!F18","v":"-"},{"$f":"'Allowed revenue -DPCR4'!G18","v":"-"},{"$f":"'Allowed revenue -DPCR4'!H18","v":"-"}]
[null,"Total capital ex depreciation",null,{"$f":"D21-D16","v":86.199603656827051},{"$f":"E21-E16","v":87.370869082424818},null,{"$f":"G21-G16","v":85.280886711679429},{"$f":"H21-H16","v":82.352152137277258},{"$f":"I21-I16","v":78.623417562875019},null,null,"Total allowed items",null,null,{"$f":"'Allowed revenue -DPCR4'!D19","v":229.6},{"$f":"'Allowed revenue -DPCR4'!E19","v":226.4},{"$f":"'Allowed revenue -DPCR4'!F19","v":224.3},{"$f":"'Allowed revenue -DPCR4'!G19","v":222.1},{"$f":"'Allowed revenue -DPCR4'!H19","v":221.1}]
[null,null,null,null,null,null,null,null,null,null,null,"PV of allowed items",null,null,{"$f":"'Allowed revenue -DPCR4'!D20","v":223.5},{"$f":"'Allowed revenue -DPCR4'!E20","v":208.8},{"$f":"'Allowed revenue -DPCR4'!F20","v":196},{"$f":"'Allowed revenue -DPCR4'!G20","v":183.9},{"$f":"'Allowed revenue -DPCR4'!H20","v":173.5}]
[null,"Allocation of allowed revenue to:-",null,null,null,null,null,null,null,null,null,"5 year movement in closing RAV",null,null,null,null,null,null,{"$f":"'Allowed revenue -DPCR4'!H21","v":85.4}]
[null,null,null,null,null,null,null,null,null,null,null,"TOTAL PV OVER 5 YEARS",null,null,null,null,null,null,{"$f":"'Allowed revenue -DPCR4'!H22","v":1071.0999999999999}]
[null,"Opex",null,{"$f":"D13","v":80.252600000000001},{"$f":"E13","v":76.852599999999995},null,{"$f":"G13","v":74.852599999999995},{"$f":"H13","v":73.45259999999999},{"$f":"I13","v":72.852599999999995}]
[null,"Depreciation",null,{"$f":"D16","v":72.3},{"$f":"E16","v":76.2},null,{"$f":"G16","v":82.2},{"$f":"H16","v":88.2},{"$f":"I16","v":94.2},null,null,null,null,null,{"$f":"1/(1+Inputs!B28)","v":0.94746316736936853},{"$f":"O27/(1+Inputs!B28)","v":0.89768645352159604},{"$f":"P27/(1+Inputs!B28)","v":0.85052485055814675},{"$f":"Q27/(1+Inputs!B28)","v":0.8058409688361805},{"$f":"R27/(1+Inputs!B28)","v":0.76350463672952817}]
[null,"Return",null,{"$f":"D20","v":57.699603656827051},{"$f":"E20","v":58.270869082424817},null,{"$f":"G20","v":55.88088671167943},{"$f":"H20","v":53.252152137277257},{"$f":"I20","v":49.723417562875014},null,null,null,null,null,1,{"$f":"O27","v":0.94746316736936853},{"$f":"P27","v":0.89768645352159604},{"$f":"Q27","v":0.85052485055814675},{"$f":"R27","v":0.8058409688361805}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,{"$f":"1/(1+Inputs!B28)^0.5","v":0.97337719686120061},{"$f":"1/(1+Inputs!B28)^1.5","v":0.92223904198323059},{"$f":"1/(1+Inputs!B28)^2.5","v":0.87378752378912361},{"$f":"1/(1+Inputs!B28)^3.5","v":0.82788149489708041},{"$f":"1/(1+Inputs!B28)^4.5","v":0.78438722336167555}]
[]
[null,null,null,null,null,null,null,null,null,null,null,"Revenue index",null,null,{"$f":"'Allowed revenue -DPCR4'!D24","v":1},{"$f":"'Allowed revenue -DPCR4'!E24","v":1.0069999999999999},{"$f":"'Allowed revenue -DPCR4'!F24","v":1.0149999999999999},{"$f":"'Allowed revenue -DPCR4'!G24","v":1.022},{"$f":"'Allowed revenue -DPCR4'!H24","v":1.0289999999999999}]
[null,null,null,null,null,null,null,null,null,null,null,"Discounted revenue index",null,null,{"$f":"O31*O29","v":0.97337719686120061},{"$f":"P31*P29","v":0.92869471527711311},{"$f":"Q31*Q29","v":0.8868943366459604},{"$f":"R31*R29","v":0.84609488778481623},{"$f":"S31*S29","v":0.80713445283916407}]
[null,null,null,null,null,null,null,null,null,null,null,"Price control revenue",null,null,{"$f":"($S$25-$N$39)/SUM($O$32:$U$32)*O31","v":238.75220365682705},{"$f":"($S$25-$N$39)/SUM($O$32:$U$32)*P31","v":240.42346908242482},{"$f":"($S$25-$N$39)/SUM($O$32:$U$32)*Q31","v":242.33348671167943},{"$f":"($S$25-$N$39)/SUM($O$32:$U$32)*R31","v":244.00475213727725},{"$f":"($S$25-$N$39)/SUM($O$32:$U$32)*S31","v":245.67601756287502}]
[null,null,null,null,null,null,null,null,null,null,null,"Excluded services revenue",null,null,{"$f":"'Allowed revenue -DPCR4'!D27","v":2.4},{"$f":"'Allowed revenue -DPCR4'!E27","v":2.4},{"$f":"'Allowed revenue -DPCR4'!F27","v":2.4},{"$f":"'Allowed revenue -DPCR4'!G27","v":2.4},{"$f":"'Allowed revenue -DPCR4'!H27","v":2.4}]
[null,null,null,null,null,null,null,null,null,null,null,"Total revenue",null,null,{"$f":"O34+O33","v":241.15220365682706},{"$f":"P34+P33","v":242.82346908242482},{"$f":"Q34+Q33","v":244.73348671167943},{"$f":"R34+R33","v":246.40475213727726},{"$f":"S34+S33","v":248.07601756287502}]
[null,null,null,null,null,null,null,null,null,null,null,"PV of total revenue",null,null,{"$f":"O35*O29","v":234.73205601238368},{"$f":"P35*P29","v":223.94128349762008},{"$f":"Q35*Q29","v":213.84506734207676},{"$f":"R35*R29","v":203.99393454915366},{"$f":"S35*S29","v":194.58765859876578}]
[null,null,null,null,null,null,null,null,null,null,null,"TOTAL PV OVER 5 YEARS",null,null,null,null,null,null,{"$f":"SUM(O36:S36)","v":1071.0999999999999}]
[]
[null,null,null,null,null,null,null,null,null,null,null,"PV of excluded service revenue",null,{"$f":"SUM(O39:S39)","v":10.516013954141545},{"$f":"O34*O29","v":2.3361052724668814},{"$f":"P34*P29","v":2.2133737007597531},{"$f":"Q34*Q29","v":2.0970900570938964},{"$f":"R34*R29","v":1.9869155877529929},{"$f":"S34*S29","v":1.8825293360680213}]
[]
["Step 2. Allocate price control revenues to network tiers "]
[]
[null,"Hence DPCR4 revenue made up of","Total DPCR4","Basis of allocation","% used",null,null,null,null,null,"£m"]
[null,null,null,null,"EHV",null,"HV","HV/LV","LV",null,"EHV","HV","HV/LV","LV"]
[null,"Return",{"$f":"SUM(D22:I22)","v":419.82692915108356},"Net Capex",{"$f":"VLOOKUP($D45,'Calc-Drivers'!$B$17:$F$27,E$51,FALSE)","v":0.56489934573540879},null,{"$f":"VLOOKUP($D45,'Calc-Drivers'!$B$17:$F$27,G$51,FALSE)","v":0.20608048808998844},{"$f":"VLOOKUP($D45,'Calc-Drivers'!$B$17:$F$27,H$51,FALSE)","v":5.3178230445720967E-2},{"$f":"VLOOKUP($D45,'Calc-Drivers'!$B$17:$F$27,I$51,FALSE)","v":0.1758419357288819},null,{"$f":"$C45*E45","v":237.15995759955291},{"$f":"$C45*G45","v":86.5181384727763},22.325653185715691,73.823179893038699]
[null,"Depreciation",{"$f":"SUM(D16:I16)","v":413.09999999999997},"Net Capex",{"$f":"VLOOKUP($D46,'Calc-Drivers'!$B$17:$F$27,E$51,FALSE)","v":0.56489934573540879},null,{"$f":"VLOOKUP($D46,'Calc-Drivers'!$B$17:$F$27,G$51,FALSE)","v":0.20608048808998844},{"$f":"VLOOKUP($D46,'Calc-Drivers'!$B$17:$F$27,H$51,FALSE)","v":5.3178230445720967E-2},{"$f":"VLOOKUP($D46,'Calc-Drivers'!$B$17:$F$27,I$51,FALSE)","v":0.1758419357288819},null,{"$f":"$C46*E46","v":233.35991972329734},85.131849629974212,21.967926997127329,72.640303649601108]
[null,"Operating costs",{"$f":"SUM(D13:I13)","v":378.26299999999998},"Overall Opex split",{"$f":"'Calc - DNO Opex Allocation'!AN41","v":0.25024433071284463},null,{"$f":"'Calc - DNO Opex Allocation'!AO41","v":0.19859307439590398},{"$f":"'Calc - DNO Opex Allocation'!AP41","v":8.969831053672904E-2},{"$f":"'Calc - DNO Opex Allocation'!AQ41","v":0.4614642843545223},null,{"$f":"$C47*E47","v":94.658171268432739},75.12041210021782,33.929552038554732,{"$f":"$C47*I47","v":174.55486459279467}]
[]
[null,"Total",{"$f":"SUM(C45:C47)","v":1211.1899291510836},null,null,null,null,null,null,null,{"$f":"SUM(K45:K48)","v":565.17804859128296},{"$f":"SUM(L45:L48)","v":246.77040020296835},{"$f":"SUM(M45:M48)","v":78.223132221397748},{"$f":"SUM(N45:N48)","v":321.01834813543451}]
[null,null,null,null,null,null,null,null,null,null,{"$f":"K49/SUM($K$49:$N$49)","v":0.46663040617206353},{"$f":"L49/SUM($K$49:$N$49)","v":0.20374211695760083},{"$f":"M49/SUM($K$49:$N$49)","v":6.458370428841323E-2},{"$f":"N49/SUM($K$49:$N$49)","v":0.26504377258192241}]
[null,null,null,null,5,null,4,3,2]
[]
[null,null,null,"NET CAPEX SPLIT FROM \"CALC -NET CAPEX\" SHEET"]
[null,null,null,"OVERALL OPEX SPLIT FROM \"CALC DNO OPEX ALLOCATION\" SHEET"]
[]
["Step 3. Remove incentive revenue and pension deficit payment from allocations"]
[]
[null,"2007/08 allowed revenue source from page \"summary allowed revenue\""]
[null,"Base revenue",null,null,null,{"$f":"'Summary of revenue'!J11","v":274.19156400000003},{"$f":"F59/$F$64","v":0.96084277039972421},null,null,null,null,null,null,null,null,"£m"]
[null,"Allowed pass through items",null,null,null,{"$f":"'Summary of revenue'!J12","v":-3.6379950000000001},{"$f":"F60/$F$64","v":-1.274853661982228E-2}]
[null,"Incentive revenue",null,null,null,{"$f":"'Summary of revenue'!J13","v":7.1725950000000003},{"$f":"F61/$F$64","v":2.5134748677954254E-2},null,null,null,null,null,"Total allowed income",null,null,{"$f":"F64","v":285.36569400000008},"From 2007/08 revenue summary"]
[null,"Under/over revoery",null,null,null,{"$f":"'Summary of revenue'!J21","v":-0.97047000000000005},{"$f":"F62/$F$64","v":-3.4007942103930679E-3}]
[null,"Excluded",null,null,null,{"$f":"'Summary of revenue'!J46+'Summary of revenue'!J47","v":8.61},{"$f":"F63/$F$64","v":3.017181175253672E-2},null,null,null,null,null,"Less incentive revenue ?",null,"Y",{"$f":"IF(O63=\"Y\",-F61,0)","v":-7.1725950000000003},"From 2007/08 revenue summary"]
[null,"Total",null,null,null,{"$f":"SUM(F59:F63)","v":285.36569400000008},{"$f":"SUM(G59:G63)","v":0.99999999999999989},null,null,null,null,null,"Less Pension deficit payment?",null,"N",{"$f":"IF(O64=\"Y\",-F66,0)","v":0}]
[null,null,null,null,null,null,null,null,null,null,null,null,"Less transmission exit charges?",null,"Y",{"$f":"IF(O65=\"Y\",-'RRP 1.3'!AH12,0)","v":-8}]
[null,"Input pension deficit payment",null,null,null,0]
[null,null,null,null,null,null,null,null,null,null,null,null,"Total revenue to share",null,null,{"$f":"P61+P63+P64+P65","v":270.19309900000007}]
[]
[null,null,null,"Step 3.a. Split out pension deficit and incentive payments",null,null,null,null,null,null,null,"Step 2.b. Divide cost by units flowing - effectively adjust the cost because of electricity lost as it flows thorugh the network meaning that there is more cost in the lower tiers"]
[null,"SPLIT OF TARIFFS",null,"£m",null,null,null,null,null,null,null,"p/kWh"]
[null,null,null,"Total",null,"EHV","HV","HV/LV","LV","Not to be split",null,"EHV","HV","HV/LV","LV","Not to be split",null,"Total"]
[]
[null,"Income",null,{"$f":"SUM(F73:J73)","v":285.36569400000008},null,{"$f":"$P$67*K50","v":126.08031553125861},{"$f":"$P$67*L50","v":55.049713977594635},{"$f":"$P$67*M50","v":17.450071206585964},{"$f":"$P$67*N50","v":71.612998284560874},{"$f":"P61-P67","v":15.172595000000001},null,{"$f":"F73*100000000/'Calc-Units'!E21","v":0.47661284372409585},{"$f":"G73*100000000/'Calc-Units'!D21","v":0.21283502182497496},{"$f":"H73*100000000/'Calc-Units'!C21","v":0.10214277222305058},{"$f":"I73*100000000/'Calc-Units'!C21","v":0.41918168042941273},{"$f":"J73*100000000/'Calc-Units'!E21","v":5.7355929188098613E-2}]
[]
[null,"All LV Tariffs",null,null,null,null,null,null,null,null,null,{"$f":"L73","v":0.47661284372409585},{"$f":"M73","v":0.21283502182497496},{"$f":"N73","v":0.10214277222305058},{"$f":"O73","v":0.41918168042941273},{"$f":"P73","v":5.7355929188098613E-2},null,{"$f":"SUM(L75:P75)","v":1.2681282473896325}]
[null,"HV Tariffs"]
[null,"EHV Tariffs"]
[]
[null,"All LV Tariffs",null,null,null,null,null,null,null,null,null,{"$f":"L75/$R75","v":0.37583962403264448},{"$f":"M75/$R75","v":0.1678339886072906},{"$f":"N75/$R75","v":8.0546090218639538E-2},{"$f":"O75/$R75","v":0.33055148900931242},{"$f":"P75/$R75","v":4.5228808132113156E-2},null,{"$f":"SUM(L79:P79)","v":1.0000000000000002}]
[null,"HV Tariffs"]
[null,"EHV Tariffs"]

{"sheet":"Calc - DNO Opex Allocation","index":5,"n_rows":49,"n_cols":49,"rows_kept":49,"cut":false,"hidden":false,"merged":[[1,34,1,48],[1,3,1,8],[1,10,1,14],[1,17,1,20],[1,23,1,26],[1,29,1,32],[2,4,2,8],[5,0,10,0],[5,1,10,1],[11,1,25,1],[38,45,38,48],[38,29,38,32],[3,11,3,14],[38,23,38,26],[38,39,38,42],[2,17,2,20],[2,23,2,26],[2,45,2,48],[2,34,2,36],[2,39,2,42],[2,29,2,32],[2,10,2,14],[41,38,41,42],[41,0,61,0],[41,1,46,1],[47,1,61,1],[3,4,3,7]]}
["Index"]
[null,null,null,"Step 1 - extract total activity costs from cost report",null,null,null,null,null,null,"Step 2. Identify costs included in price control revenues to be allocated by MEAV",null,null,null,null,null,null,"Step 3.  Allocate costs not directly attributable to network teirs to network tiers using MEAV",null,null,null,null,null,"Step 4.  Sum directly attributed and allocated costs",null,null,null,null,null,"Step 5. Divide cost by units flowing - effectively adjust the cost because of electricity lost as it flows through the network meaning that there is more cost in the lower tiers",null,null,null,null,"Step 6.   Adjust costs so that they are aligned with the definition of opex in the allowed price control revenues"]
[null,null,null,null,"Costs extracted from RRP Tables",null,null,null,null,null,"Cost drivers - lookup from \"Calc-Drivers\"",null,null,null,null,null,null,"Allocation of \"Unallocated\" costs by cost driver to network tiers",null,null,null,null,null,"Sum of allocated and \"unallocated\" costs",null,null,null,null,null,"Sum of allocated and \"unallocated\" costs expressed per unit throughput (p/kWh)",null,null,null,null,"Proportion of costs allocated to Opex and Capex",null,null,null,null,"Operating costs = sum of allocated and unallocated multiplied by 1 minus capitalised proportion",null,null,null,null,null,"Opex only on p/kWh throughput"]
[null,null,null,"Total activity cost - from RRP 1.3","Costs allocated to network tiers in RRP - from 2.2 amd 2.3",null,null,null,"Unallocated costs = Total - costs allocated to network tiers",null,"Insert name of cost driver","Proportion of cost allocated to each network tier",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"% Cost capitalised (from DCPR settlement - same for all DNOs)","Capex","Opex",null,null,"EHV","HV","HV/LV","LV",null,null,"EHV","HV","HV/LV","LV"]
[null,null,null,null,"EHV","HV","HV/LV","LV",null,null,null,"EHV","HV","HV/LV","LV",null,null,"EHV","HV","HV/LV","LV",null,null,"EHV","HV","HV/LV","LV",null,null,"EHV","HV","HV/LV","LV"]
["Cash typical costs (excluding disallowed related party margins)","Direct activities - From RRP 2.2 Detailed Cost Matrix","Load related new connections & reinforcement (net of contributions)",{"$f":"'RRP 1.3'!D$12","v":11.260750888044793},{"$f":"'RRP 2.4'!L13+'RRP 2.4'!L14+'RRP 2.4'!L18+'RRP 2.4'!L19","v":10.20303592994216},{"$f":"'RRP 2.4'!L12+'RRP 2.4'!L17-'Calc - DNO Opex Allocation'!G6","v":11.92},0,{"$f":"'RRP 2.4'!L11+'RRP 2.4'!L16+'RRP 2.4'!L24","v":-16.479999999999997},{"$f":"D6-E6-F6-G6-H6","v":5.6177149581026296},null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K6,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K6,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K6,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K6,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K6,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K6,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K6,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K6,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,{"$f":"IF(ISERROR($I6*L6),\" \",$I6*L6)","v":2.1172270206467538},0.73865908072099562,0.19854251422814856,2.5632863425067312,null,null,{"$f":"IF($K6=\"Do not allocate\",\" \",R6+E6)","v":12.320262950588914},{"$f":"IF($K6=\"Do not allocate\",\" \",S6+F6)","v":12.658659080720996},{"$f":"IF($K6=\"Do not allocate\",\" \",T6+G6)","v":0.19854251422814856},{"$f":"IF($K6=\"Do not allocate\",\" \",U6+H6)","v":-13.916713657493265},null,null,{"$f":"IF(ISERROR(X6*100000000/'Calc-Units'!$E$21),\" \",X6*100000000/'Calc-Units'!$E$21)","v":4.6573452291630568E-2},{"$f":"IF(ISERROR(Y6*100000000/'Calc-Units'!$D$21),\" \",Y6*100000000/'Calc-Units'!$D$21)","v":4.8941325704557143E-2},{"$f":"IF(ISERROR(Z6*100000000/'Calc-Units'!$C$21),\" \",Z6*100000000/'Calc-Units'!$C$21)","v":1.1621547309069807E-3},{"$f":"IF(ISERROR(AA6*100000000/'Calc-Units'!$C$21),\" \",AA6*100000000/'Calc-Units'!$C$21)","v":-8.1460510755638399E-2},null,1,{"$f":"AI6*D6","v":11.260750888044793},{"$f":"D6*(1-AI6)","v":0},null,null,{"$f":"IF(ISERROR(X6*(1-$AI6)),\" \",X6*(1-$AI6))","v":0},{"$f":"IF(ISERROR(Y6*(1-$AI6)),\" \",Y6*(1-$AI6))","v":0},{"$f":"IF(ISERROR(Z6*(1-$AI6)),\" \",Z6*(1-$AI6))","v":0},{"$f":"IF(ISERROR(AA6*(1-$AI6)),\" \",AA6*(1-$AI6))","v":0},null,null,{"$f":"IF(ISERROR(AN6*100000000/'Calc-Units'!$E$21),\" \",AN6*100000000/'Calc-Units'!$E$21)","v":0},{"$f":"IF(ISERROR(AO6*100000000/'Calc-Units'!$D$21),\" \",AO6*100000000/'Calc-Units'!$D$21)","v":0},{"$f":"IF(ISERROR(AP6*100000000/'Calc-Units'!$C$21),\" \",AP6*100000000/'Calc-Units'!$C$21)","v":0},{"$f":"IF(ISERROR(AQ6*100000000/'Calc-Units'!$C$21),\" \",AQ6*100000000/'Calc-Units'!$C$21)","v":0}]
[null,null,"Non-load new & replacement assets (net of contributions)",{"$f":"'RRP 1.3'!E$12","v":86.73865287324719},{"$f":"SUM('RRP 2.4'!G44:G55)+'RRP 2.4'!G71+'RRP 2.4'!H71","v":33.944558974318987},{"$f":"SUM('RRP 2.4'!G38:G40)+'RRP 2.4'!F71","v":25.847964559544309},{"$f":"'RRP 2.4'!G41+'RRP 2.4'!G42+'RRP 2.4'!G43","v":6.9283782203391073},{"$f":"SUM('RRP 2.4'!G31:G37)+'RRP 2.4'!E71","v":15.964378159526383},4.0533729595184056,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K7,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K7,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K7,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K7,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K7,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K7,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K7,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K7,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,1.527651512875938,0.53296772200568254,0.14325519619439428,1.8494985284423906,null,null,35.472210487194928,26.380932281549992,7.0716334165335013,17.813876687968772,null,null,{"$f":"IF(ISERROR(X7*100000000/'Calc-Units'!$E$21),\" \",X7*100000000/'Calc-Units'!$E$21)","v":0.1340931853021109},{"$f":"IF(ISERROR(Y7*100000000/'Calc-Units'!$D$21),\" \",Y7*100000000/'Calc-Units'!$D$21)","v":0.10199483143894464},{"$f":"IF(ISERROR(Z7*100000000/'Calc-Units'!$C$21),\" \",Z7*100000000/'Calc-Units'!$C$21)","v":4.1393311967533958E-2},{"$f":"IF(ISERROR(AA7*100000000/'Calc-Units'!$C$21),\" \",AA7*100000000/'Calc-Units'!$C$21)","v":0.10427228218197596},null,1,86.73865287324719,0,null,null,{"$f":"IF(ISERROR(X7*(1-$AI7)),\" \",X7*(1-$AI7))","v":0},0,0,0,null,null,{"$f":"IF(ISERROR(AN7*100000000/'Calc-Units'!$E$21),\" \",AN7*100000000/'Calc-Units'!$E$21)","v":0},{"$f":"IF(ISERROR(AO7*100000000/'Calc-Units'!$D$21),\" \",AO7*100000000/'Calc-Units'!$D$21)","v":0},{"$f":"IF(ISERROR(AP7*100000000/'Calc-Units'!$C$21),\" \",AP7*100000000/'Calc-Units'!$C$21)","v":0},{"$f":"IF(ISERROR(AQ7*100000000/'Calc-Units'!$C$21),\" \",AQ7*100000000/'Calc-Units'!$C$21)","v":0}]
[null,null,"Non-operational capex",{"$f":"'RRP 1.3'!F$12","v":2.2901999883199999},0,0,0,0,2.2901999883199999,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K8,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K8,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K8,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K8,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K8,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K8,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K8,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K8,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,0.86313978799552338,0.30113258338245169,8.0940750315303261E-2,1.0449868666267217,null,null,0.86313978799552338,0.30113258338245169,8.0940750315303261E-2,1.0449868666267217,null,null,{"$f":"IF(ISERROR(X8*100000000/'Calc-Units'!$E$21),\" \",X8*100000000/'Calc-Units'!$E$21)","v":3.2628686496740792E-3},{"$f":"IF(ISERROR(Y8*100000000/'Calc-Units'!$D$21),\" \",Y8*100000000/'Calc-Units'!$D$21)","v":1.1642487367418588E-3},{"$f":"IF(ISERROR(Z8*100000000/'Calc-Units'!$C$21),\" \",Z8*100000000/'Calc-Units'!$C$21)","v":4.7378102502518884E-4},{"$f":"IF(ISERROR(AA8*100000000/'Calc-Units'!$C$21),\" \",AA8*100000000/'Calc-Units'!$C$21)","v":6.1167575897138936E-3},null,0.23499999999999999,0.53819699725519998,1.7520029910648001,null,null,0.66030193781657542,0.23036642628757556,6.1919673991206993E-2,0.79941495296944209,null,null,{"$f":"IF(ISERROR(AN8*100000000/'Calc-Units'!$E$21),\" \",AN8*100000000/'Calc-Units'!$E$21)","v":2.4960945170006705E-3},{"$f":"IF(ISERROR(AO8*100000000/'Calc-Units'!$D$21),\" \",AO8*100000000/'Calc-Units'!$D$21)","v":8.9065028360752201E-4},{"$f":"IF(ISERROR(AP8*100000000/'Calc-Units'!$C$21),\" \",AP8*100000000/'Calc-Units'!$C$21)","v":3.6244248414426947E-4},{"$f":"IF(ISERROR(AQ8*100000000/'Calc-Units'!$C$21),\" \",AQ8*100000000/'Calc-Units'!$C$21)","v":4.6793195561311294E-3}]
[null,null,"Faults",{"$f":"'RRP 1.3'!G$12","v":23.607461477008215},{"$f":"SUM('RRP 2.3'!I20:I27)","v":2.7149327240017325},{"$f":"SUM('RRP 2.3'!I17:I18)","v":5.2791708589435222},{"$f":"SUM('RRP 2.3'!I19)","v":0.58234466945385643},{"$f":"SUM('RRP 2.3'!I11:I16)","v":15.272426893891403},-0.24141366928230212,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K9,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K9,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K9,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K9,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K9,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K9,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K9,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K9,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,-9.098495519441617E-2,-3.1742870607620814E-2,-8.5320948509889447E-3,-0.11015374862927618,null,null,2.6239477688073163,5.2474279883359012,0.5738125746028675,15.162273145262127,null,null,{"$f":"IF(ISERROR(X9*100000000/'Calc-Units'!$E$21),\" \",X9*100000000/'Calc-Units'!$E$21)","v":9.9191313299393929E-3},{"$f":"IF(ISERROR(Y9*100000000/'Calc-Units'!$D$21),\" \",Y9*100000000/'Calc-Units'!$D$21)","v":2.0287779349353406E-2},{"$f":"IF(ISERROR(Z9*100000000/'Calc-Units'!$C$21),\" \",Z9*100000000/'Calc-Units'!$C$21)","v":3.3587718017025728E-3},{"$f":"IF(ISERROR(AA9*100000000/'Calc-Units'!$C$21),\" \",AA9*100000000/'Calc-Units'!$C$21)","v":8.8751306165196248E-2},null,0.23499999999999999,5.5477534470969303,18.059708029911285,null,null,2.007320043137597,4.0142824110769642,0.43896661957119365,11.599138956125527,null,null,{"$f":"IF(ISERROR(AN9*100000000/'Calc-Units'!$E$21),\" \",AN9*100000000/'Calc-Units'!$E$21)","v":7.588135467403636E-3},{"$f":"IF(ISERROR(AO9*100000000/'Calc-Units'!$D$21),\" \",AO9*100000000/'Calc-Units'!$D$21)","v":1.5520151202255356E-2},{"$f":"IF(ISERROR(AP9*100000000/'Calc-Units'!$C$21),\" \",AP9*100000000/'Calc-Units'!$C$21)","v":2.5694604283024681E-3},{"$f":"IF(ISERROR(AQ9*100000000/'Calc-Units'!$C$21),\" \",AQ9*100000000/'Calc-Units'!$C$21)","v":6.789474921637513E-2}]
[null,null,"Inspections, & Maintenance",{"$f":"'RRP 1.3'!H$12","v":11.683384510026801},{"$f":"SUM('RRP 2.3'!G20:G27)","v":2.7042198642422459},{"$f":"SUM('RRP 2.3'!G17:G18)","v":0.43626357364726914},{"$f":"SUM('RRP 2.3'!G19)","v":5.2840504964611927},{"$f":"SUM('RRP 2.3'!G11:G16)","v":1.5441125756760909},1.7147380000000032,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K10,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K10,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K10,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K10,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K10,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K10,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K10,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K10,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,0.64625735801945527,0.22546654720002998,6.0602646503362868E-2,0.78241144827715503,null,null,3.3504772222617012,0.6617301208472991,5.3446531429645558,2.3265240239532461,null,null,{"$f":"IF(ISERROR(X10*100000000/'Calc-Units'!$E$21),\" \",X10*100000000/'Calc-Units'!$E$21)","v":1.2665581221035654E-2},{"$f":"IF(ISERROR(Y10*100000000/'Calc-Units'!$D$21),\" \",Y10*100000000/'Calc-Units'!$D$21)","v":2.5584028423853425E-3},{"$f":"IF(ISERROR(Z10*100000000/'Calc-Units'!$C$21),\" \",Z10*100000000/'Calc-Units'!$C$21)","v":3.128455363477263E-2},{"$f":"IF(ISERROR(AA10*100000000/'Calc-Units'!$C$21),\" \",AA10*100000000/'Calc-Units'!$C$21)","v":1.361814577354979E-2},null,0.23499999999999999,2.7455953598562983,8.937789150170504,null,null,2.5631150750302014,0.50622354244818379,4.088659654367885,1.7797908783242333,null,null,{"$f":"IF(ISERROR(AN10*100000000/'Calc-Units'!$E$21),\" \",AN10*100000000/'Calc-Units'!$E$21)","v":9.6891696340922744E-3},{"$f":"IF(ISERROR(AO10*100000000/'Calc-Units'!$D$21),\" \",AO10*100000000/'Calc-Units'!$D$21)","v":1.9571781744247871E-3},{"$f":"IF(ISERROR(AP10*100000000/'Calc-Units'!$C$21),\" \",AP10*100000000/'Calc-Units'!$C$21)","v":2.3932683530601059E-2},{"$f":"IF(ISERROR(AQ10*100000000/'Calc-Units'!$C$21),\" \",AQ10*100000000/'Calc-Units'!$C$21)","v":1.0417881516765589E-2}]
[null,null,"Tree Cutting",{"$f":"'RRP 1.3'!I$12","v":4.9082775940000003},{"$f":"'RRP 2.3'!G46+'RRP 2.3'!G47","v":0.54126135383944951},{"$f":"'RRP 2.3'!G45","v":5.2820475418532782},0,{"$f":"'RRP 2.3'!G44","v":3.1008321843072717},-4.0158634859999989,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K11,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K11,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K11,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K11,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K11,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K11,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K11,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K11,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,-1.5135147915478366,-0.52803569654086746,-0.14192952815405036,-1.8323834697572443,null,null,-0.97225343770838712,4.7540118453124105,-0.14192952815405036,1.2684487145500274,null,null,{"$f":"IF(ISERROR(X11*100000000/'Calc-Units'!$E$21),\" \",X11*100000000/'Calc-Units'!$E$21)","v":-3.6753435602866675E-3},{"$f":"IF(ISERROR(Y11*100000000/'Calc-Units'!$D$21),\" \",Y11*100000000/'Calc-Units'!$D$21)","v":1.8380117565462189E-2},{"$f":"IF(ISERROR(Z11*100000000/'Calc-Units'!$C$21),\" \",Z11*100000000/'Calc-Units'!$C$21)","v":-8.3077457360132491E-4},{"$f":"IF(ISERROR(AA11*100000000/'Calc-Units'!$C$21),\" \",AA11*100000000/'Calc-Units'!$C$21)","v":7.4247758987943538E-3},null,0.23499999999999999,1.1534452345899999,3.7548323594100004,null,null,-0.74377387984691612,3.6368190616639939,-0.10857608903784852,0.97036326663077099,null,null,{"$f":"IF(ISERROR(AN11*100000000/'Calc-Units'!$E$21),\" \",AN11*100000000/'Calc-Units'!$E$21)","v":-2.8116378236193004E-3},{"$f":"IF(ISERROR(AO11*100000000/'Calc-Units'!$D$21),\" \",AO11*100000000/'Calc-Units'!$D$21)","v":1.4060789937578574E-2},{"$f":"IF(ISERROR(AP11*100000000/'Calc-Units'!$C$21),\" \",AP11*100000000/'Calc-Units'!$C$21)","v":-6.3554254880501359E-4},{"$f":"IF(ISERROR(AQ11*100000000/'Calc-Units'!$C$21),\" \",AQ11*100000000/'Calc-Units'!$C$21)","v":5.6799535625776812E-3}]
[null,"Indirect activities - From RRP 2.2 Detailed Cost Matrix","Network Policy",{"$f":"'RRP 1.3'!J$12","v":0.77486938446319986},0,0,0,0,0.77486938446319986,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K12,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K12,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K12,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K12,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K12,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K12,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K12,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K12,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,0.29203589190497214,0.10188560855706814,2.7385603744071452E-2,0.35356228025708808,null,null,0.29203589190497214,0.10188560855706814,2.7385603744071452E-2,0.35356228025708808,null,null,{"$f":"IF(ISERROR(X12*100000000/'Calc-Units'!$E$21),\" \",X12*100000000/'Calc-Units'!$E$21)","v":1.1039634246142339E-3},{"$f":"IF(ISERROR(Y12*100000000/'Calc-Units'!$D$21),\" \",Y12*100000000/'Calc-Units'!$D$21)","v":3.9391350388705439E-4},{"$f":"IF(ISERROR(Z12*100000000/'Calc-Units'!$C$21),\" \",Z12*100000000/'Calc-Units'!$C$21)","v":1.6029971753729486E-4},{"$f":"IF(ISERROR(AA12*100000000/'Calc-Units'!$C$21),\" \",AA12*100000000/'Calc-Units'!$C$21)","v":2.0695520970328268E-3},null,0.52569999999999995,0.4073488354123041,0.36752054905089576,null,null,0.13851262353052832,4.8324344138617428E-2,1.2988991855813091E-2,0.16769458952593688,null,null,{"$f":"IF(ISERROR(AN12*100000000/'Calc-Units'!$E$21),\" \",AN12*100000000/'Calc-Units'!$E$21)","v":5.2360985229453125E-4},{"$f":"IF(ISERROR(AO12*100000000/'Calc-Units'!$D$21),\" \",AO12*100000000/'Calc-Units'!$D$21)","v":1.8683317489362992E-4},{"$f":"IF(ISERROR(AP12*100000000/'Calc-Units'!$C$21),\" \",AP12*100000000/'Calc-Units'!$C$21)","v":7.6030156027938944E-5},{"$f":"IF(ISERROR(AQ12*100000000/'Calc-Units'!$C$21),\" \",AQ12*100000000/'Calc-Units'!$C$21)","v":9.8158855962266964E-4}]
[null,null,"Network Design & Engineering",{"$f":"'RRP 1.3'!K$12","v":5.6235967952637829},0,0,0,0,5.6235967952637829,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K13,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K13,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K13,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K13,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K13,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K13,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K13,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K13,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,2.1194437911061872,0.73943246855978972,0.19875039140720899,2.5659701441905969,null,null,2.1194437911061872,0.73943246855978972,0.19875039140720899,2.5659701441905969,null,null,{"$f":"IF(ISERROR(X13*100000000/'Calc-Units'!$E$21),\" \",X13*100000000/'Calc-Units'!$E$21)","v":8.011989247774803E-3},{"$f":"IF(ISERROR(Y13*100000000/'Calc-Units'!$D$21),\" \",Y13*100000000/'Calc-Units'!$D$21)","v":2.8588182247063234E-3},{"$f":"IF(ISERROR(Z13*100000000/'Calc-Units'!$C$21),\" \",Z13*100000000/'Calc-Units'!$C$21)","v":1.1633715254460841E-3},{"$f":"IF(ISERROR(AA13*100000000/'Calc-Units'!$C$21),\" \",AA13*100000000/'Calc-Units'!$C$21)","v":1.5019726903480432E-2},null,0.52569999999999995,2.9563248352701703,2.6672719599936126,null,null,1.0052521901216647,0.35071281983790831,9.4267310644439231E-2,1.2170396393896001,null,null,{"$f":"IF(ISERROR(AN13*100000000/'Calc-Units'!$E$21),\" \",AN13*100000000/'Calc-Units'!$E$21)","v":3.8000865002195895E-3},{"$f":"IF(ISERROR(AO13*100000000/'Calc-Units'!$D$21),\" \",AO13*100000000/'Calc-Units'!$D$21)","v":1.3559374839782093E-3},{"$f":"IF(ISERROR(AP13*100000000/'Calc-Units'!$C$21),\" \",AP13*100000000/'Calc-Units'!$C$21)","v":5.5178711451907769E-4},{"$f":"IF(ISERROR(AQ13*100000000/'Calc-Units'!$C$21),\" \",AQ13*100000000/'Calc-Units'!$C$21)","v":7.1238564703207689E-3}]
[null,null,"Project Management",{"$f":"'RRP 1.3'!L$12","v":4.1962810579107463},0,0,0,0,4.1962810579107463,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K14,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K14,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K14,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K14,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K14,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K14,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K14,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K14,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,1.5815112920997136,0.55175834512795729,0.14830588555296614,1.9147055351301092,null,null,1.5815112920997136,0.55175834512795729,0.14830588555296614,1.9147055351301092,null,null,{"$f":"IF(ISERROR(X14*100000000/'Calc-Units'!$E$21),\" \",X14*100000000/'Calc-Units'!$E$21)","v":5.9784795995575912E-3},{"$f":"IF(ISERROR(Y14*100000000/'Calc-Units'!$D$21),\" \",Y14*100000000/'Calc-Units'!$D$21)","v":2.1332263320244784E-3},{"$f":"IF(ISERROR(Z14*100000000/'Calc-Units'!$C$21),\" \",Z14*100000000/'Calc-Units'!$C$21)","v":8.680981359925436E-4},{"$f":"IF(ISERROR(AA14*100000000/'Calc-Units'!$C$21),\" \",AA14*100000000/'Calc-Units'!$C$21)","v":1.1207595031199422E-2},null,0.52569999999999995,2.205984952143679,1.9902961057670672,null,null,0.75011080584289425,0.26169898309419015,7.0341481517771851E-2,0.90814483531221091,null,null,{"$f":"IF(ISERROR(AN14*100000000/'Calc-Units'!$E$21),\" \",AN14*100000000/'Calc-Units'!$E$21)","v":2.8355928740701661E-3},{"$f":"IF(ISERROR(AO14*100000000/'Calc-Units'!$D$21),\" \",AO14*100000000/'Calc-Units'!$D$21)","v":1.01178924927921E-3},{"$f":"IF(ISERROR(AP14*100000000/'Calc-Units'!$C$21),\" \",AP14*100000000/'Calc-Units'!$C$21)","v":4.1173894590126349E-4},{"$f":"IF(ISERROR(AQ14*100000000/'Calc-Units'!$C$21),\" \",AQ14*100000000/'Calc-Units'!$C$21)","v":5.3157623232978866E-3}]
[null,null,"Engineering Mgt & Clerical Support",{"$f":"'RRP 1.3'!M$12","v":23.39222530593641},0,0,0,0,23.39222530593641,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K15,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K15,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K15,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K15,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K15,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K15,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K15,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K15,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,8.8161560100786716,3.0757843303493817,0.82673315756849208,10.673551807939866,null,null,8.8161560100786716,3.0757843303493817,0.82673315756849208,10.673551807939866,null,null,{"$f":"IF(ISERROR(X15*100000000/'Calc-Units'!$E$21),\" \",X15*100000000/'Calc-Units'!$E$21)","v":3.332711509305443E-2},{"$f":"IF(ISERROR(Y15*100000000/'Calc-Units'!$D$21),\" \",Y15*100000000/'Calc-Units'!$D$21)","v":1.1891698934989281E-2},{"$f":"IF(ISERROR(Z15*100000000/'Calc-Units'!$C$21),\" \",Z15*100000000/'Calc-Units'!$C$21)","v":4.8392247574835642E-3},{"$f":"IF(ISERROR(AA15*100000000/'Calc-Units'!$C$21),\" \",AA15*100000000/'Calc-Units'!$C$21)","v":6.2476889533714969E-2},null,0.52569999999999995,12.297292843330769,11.094932462605641,null,null,4.1815027955803146,1.4588445078847119,0.39211953663473587,5.0624656225058793,null,null,{"$f":"IF(ISERROR(AN15*100000000/'Calc-Units'!$E$21),\" \",AN15*100000000/'Calc-Units'!$E$21)","v":1.5807050688635721E-2},{"$f":"IF(ISERROR(AO15*100000000/'Calc-Units'!$D$21),\" \",AO15*100000000/'Calc-Units'!$D$21)","v":5.6402328048654176E-3},{"$f":"IF(ISERROR(AP15*100000000/'Calc-Units'!$C$21),\" \",AP15*100000000/'Calc-Units'!$C$21)","v":2.2952443024744549E-3},{"$f":"IF(ISERROR(AQ15*100000000/'Calc-Units'!$C$21),\" \",AQ15*100000000/'Calc-Units'!$C$21)","v":2.9632788705841018E-2}]
[null,null,"Control Centre",{"$f":"'RRP 1.3'!N$12","v":3.9932671215815496},0,0,0,0,3.9932671215815496,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K16,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K16,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K16,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K16,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K16,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K16,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K16,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K16,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,1.5049985827917982,0.52506455793852624,0.14113092248653006,1.8220730583646951,null,null,1.5049985827917982,0.52506455793852624,0.14113092248653006,1.8220730583646951,null,null,{"$f":"IF(ISERROR(X16*100000000/'Calc-Units'!$E$21),\" \",X16*100000000/'Calc-Units'!$E$21)","v":5.6892438071928456E-3},{"$f":"IF(ISERROR(Y16*100000000/'Calc-Units'!$D$21),\" \",Y16*100000000/'Calc-Units'!$D$21)","v":2.030021930610765E-3},{"$f":"IF(ISERROR(Z16*100000000/'Calc-Units'!$C$21),\" \",Z16*100000000/'Calc-Units'!$C$21)","v":8.260999911410095E-4},{"$f":"IF(ISERROR(AA16*100000000/'Calc-Units'!$C$21),\" \",AA16*100000000/'Calc-Units'!$C$21)","v":1.0665377302532751E-2},null,0.52569999999999995,2.0992605258154202,1.8940065957661292,null,null,0.71382082781814993,0.24903811983024302,6.6938396535361211E-2,0.86420925158237505,null,null,{"$f":"IF(ISERROR(AN16*100000000/'Calc-Units'!$E$21),\" \",AN16*100000000/'Calc-Units'!$E$21)","v":2.698408337751567E-3},{"$f":"IF(ISERROR(AO16*100000000/'Calc-Units'!$D$21),\" \",AO16*100000000/'Calc-Units'!$D$21)","v":9.6283940168868595E-4},{"$f":"IF(ISERROR(AP16*100000000/'Calc-Units'!$C$21),\" \",AP16*100000000/'Calc-Units'!$C$21)","v":3.9181922579818084E-4},{"$f":"IF(ISERROR(AQ16*100000000/'Calc-Units'!$C$21),\" \",AQ16*100000000/'Calc-Units'!$C$21)","v":5.058588454591284E-3}]
[null,null,"System Mapping - Cartographical",{"$f":"'RRP 1.3'!O$12","v":1.8430952204672004},0,0,0,0,1.8430952204672004,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K17,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K17,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K17,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K17,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K17,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K17,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K17,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K17,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,0.69463314381404984,0.24234391231757677,6.5139075542742508E-2,0.84097908879283134,null,null,0.69463314381404984,0.24234391231757677,6.5139075542742508E-2,0.84097908879283134,null,null,{"$f":"IF(ISERROR(X17*100000000/'Calc-Units'!$E$21),\" \",X17*100000000/'Calc-Units'!$E$21)","v":2.6258744406151328E-3},{"$f":"IF(ISERROR(Y17*100000000/'Calc-Units'!$D$21),\" \",Y17*100000000/'Calc-Units'!$D$21)","v":9.3695803557224957E-4},{"$f":"IF(ISERROR(Z17*100000000/'Calc-Units'!$C$21),\" \",Z17*100000000/'Calc-Units'!$C$21)","v":3.8128702612235136E-4},{"$f":"IF(ISERROR(AA17*100000000/'Calc-Units'!$C$21),\" \",AA17*100000000/'Calc-Units'!$C$21)","v":4.9226123202577342E-3},null,0.52569999999999995,0.96891515739960721,0.87418006306759322,null,null,0.32946450011100387,0.11494371761222667,3.0895463529922774E-2,0.39887638181443996,null,null,{"$f":"IF(ISERROR(AN17*100000000/'Calc-Units'!$E$21),\" \",AN17*100000000/'Calc-Units'!$E$21)","v":1.2454522471837576E-3},{"$f":"IF(ISERROR(AO17*100000000/'Calc-Units'!$D$21),\" \",AO17*100000000/'Calc-Units'!$D$21)","v":4.4439919627191799E-4},{"$f":"IF(ISERROR(AP17*100000000/'Calc-Units'!$C$21),\" \",AP17*100000000/'Calc-Units'!$C$21)","v":1.8084443648983128E-4},{"$f":"IF(ISERROR(AQ17*100000000/'Calc-Units'!$C$21),\" \",AQ17*100000000/'Calc-Units'!$C$21)","v":2.3347950234982439E-3}]
[null,null,"Customer Call Centre",{"$f":"'RRP 1.3'!P$12","v":1.4394826722359997},0,0,0,0,1.4394826722359997,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K18,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K18,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K18,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K18,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K18,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K18,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K18,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K18,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,0.54251802238827207,0.18927392281696837,5.0874512335548808E-2,0.65681621469521034,null,null,0.54251802238827207,0.18927392281696837,5.0874512335548808E-2,0.65681621469521034,null,null,{"$f":"IF(ISERROR(X18*100000000/'Calc-Units'!$E$21),\" \",X18*100000000/'Calc-Units'!$E$21)","v":2.0508439904557544E-3},{"$f":"IF(ISERROR(Y18*100000000/'Calc-Units'!$D$21),\" \",Y18*100000000/'Calc-Units'!$D$21)","v":7.3177708988722133E-4},{"$f":"IF(ISERROR(Z18*100000000/'Calc-Units'!$C$21),\" \",Z18*100000000/'Calc-Units'!$C$21)","v":2.9779040233873105E-4},{"$f":"IF(ISERROR(AA18*100000000/'Calc-Units'!$C$21),\" \",AA18*100000000/'Calc-Units'!$C$21)","v":3.8446278078623879E-3},null,0.52569999999999995,0.75673604079446499,0.68274663144153469,null,null,0.25731629801875749,8.9772621592088112E-2,2.4129781200750801E-2,0.31152793062993828,null,null,{"$f":"IF(ISERROR(AN18*100000000/'Calc-Units'!$E$21),\" \",AN18*100000000/'Calc-Units'!$E$21)","v":9.7271530467316449E-4},{"$f":"IF(ISERROR(AO18*100000000/'Calc-Units'!$D$21),\" \",AO18*100000000/'Calc-Units'!$D$21)","v":3.4708187373350916E-4},{"$f":"IF(ISERROR(AP18*100000000/'Calc-Units'!$C$21),\" \",AP18*100000000/'Calc-Units'!$C$21)","v":1.4124198782926013E-4},{"$f":"IF(ISERROR(AQ18*100000000/'Calc-Units'!$C$21),\" \",AQ18*100000000/'Calc-Units'!$C$21)","v":1.8235069692691306E-3}]
[null,null,"Stores",{"$f":"'RRP 1.3'!Q$12","v":1.3630810727301883},0,0,0,0,1.3630810727301883,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K19,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K19,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K19,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K19,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K19,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K19,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K19,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K19,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,0.51372348010537749,0.17922807042369618,4.8174310248033286E-2,0.62195521195308134,null,null,0.51372348010537749,0.17922807042369618,4.8174310248033286E-2,0.62195521195308134,null,null,{"$f":"IF(ISERROR(X19*100000000/'Calc-Units'!$E$21),\" \",X19*100000000/'Calc-Units'!$E$21)","v":1.9419939402051934E-3},{"$f":"IF(ISERROR(Y19*100000000/'Calc-Units'!$D$21),\" \",Y19*100000000/'Calc-Units'!$D$21)","v":6.9293748366796323E-4},{"$f":"IF(ISERROR(Z19*100000000/'Calc-Units'!$C$21),\" \",Z19*100000000/'Calc-Units'!$C$21)","v":2.8198495813646268E-4},{"$f":"IF(ISERROR(AA19*100000000/'Calc-Units'!$C$21),\" \",AA19*100000000/'Calc-Units'!$C$21)","v":3.6405713647452665E-3},null,0.52569999999999995,0.71657171993425994,0.64650935279592836,null,null,0.24365904661398058,8.5007873801959108E-2,2.2849075350642189E-2,0.29499335702934654,null,null,{"$f":"IF(ISERROR(AN19*100000000/'Calc-Units'!$E$21),\" \",AN19*100000000/'Calc-Units'!$E$21)","v":9.2108772583932334E-4},{"$f":"IF(ISERROR(AO19*100000000/'Calc-Units'!$D$21),\" \",AO19*100000000/'Calc-Units'!$D$21)","v":3.2866024850371499E-4},{"$f":"IF(ISERROR(AP19*100000000/'Calc-Units'!$C$21),\" \",AP19*100000000/'Calc-Units'!$C$21)","v":1.3374546564412428E-4},{"$f":"IF(ISERROR(AQ19*100000000/'Calc-Units'!$C$21),\" \",AQ19*100000000/'Calc-Units'!$C$21)","v":1.7267229982986802E-3}]
[null,null,"Vehicles & Transport",{"$f":"'RRP 1.3'!R$12","v":5.4399459945200013},0,0,0,0,5.4399459945200013,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K20,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K20,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K20,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K20,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K20,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K20,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K20,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K20,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,2.0502287382603099,0.71528469092016134,0.19225976452570584,2.482172800813824,null,null,2.0502287382603099,0.71528469092016134,0.19225976452570584,2.482172800813824,null,null,{"$f":"IF(ISERROR(X20*100000000/'Calc-Units'!$E$21),\" \",X20*100000000/'Calc-Units'!$E$21)","v":7.7503402899150144E-3},{"$f":"IF(ISERROR(Y20*100000000/'Calc-Units'!$D$21),\" \",Y20*100000000/'Calc-Units'!$D$21)","v":2.765457289478817E-3},{"$f":"IF(ISERROR(Z20*100000000/'Calc-Units'!$C$21),\" \",Z20*100000000/'Calc-Units'!$C$21)","v":1.1253790946248294E-3},{"$f":"IF(ISERROR(AA20*100000000/'Calc-Units'!$C$21),\" \",AA20*100000000/'Calc-Units'!$C$21)","v":1.4529225010617092E-2},null,0.52569999999999995,2.8597796093191645,2.5801663852008367,null,null,0.97242349055686517,0.33925952890343258,9.1188806314542292E-2,1.1772945594259969,null,null,{"$f":"IF(ISERROR(AN20*100000000/'Calc-Units'!$E$21),\" \",AN20*100000000/'Calc-Units'!$E$21)","v":3.6759863995066921E-3},{"$f":"IF(ISERROR(AO20*100000000/'Calc-Units'!$D$21),\" \",AO20*100000000/'Calc-Units'!$D$21)","v":1.3116563923998032E-3},{"$f":"IF(ISERROR(AP20*100000000/'Calc-Units'!$C$21),\" \",AP20*100000000/'Calc-Units'!$C$21)","v":5.3376730458055662E-4},{"$f":"IF(ISERROR(AQ20*100000000/'Calc-Units'!$C$21),\" \",AQ20*100000000/'Calc-Units'!$C$21)","v":6.8912114225356882E-3}]
[null,null,"IT & Telecoms",{"$f":"'RRP 1.3'!S$12","v":11.413705956353251},0,0,0,0,11.413705956353251,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K21,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K21,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K21,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K21,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K21,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K21,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K21,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K21,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X21*100000000/'Calc-Units'!$E$21),\" \",X21*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y21*100000000/'Calc-Units'!$D$21),\" \",Y21*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z21*100000000/'Calc-Units'!$C$21),\" \",Z21*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA21*100000000/'Calc-Units'!$C$21),\" \",AA21*100000000/'Calc-Units'!$C$21)","v":" "},null,0.52569999999999995,6.0001852212549034,5.4135207350983476,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN21*100000000/'Calc-Units'!$E$21),\" \",AN21*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO21*100000000/'Calc-Units'!$D$21),\" \",AO21*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP21*100000000/'Calc-Units'!$C$21),\" \",AP21*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ21*100000000/'Calc-Units'!$C$21),\" \",AQ21*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Property Mgt",{"$f":"'RRP 1.3'!T$12","v":5.5343552999991585},0,0,0,0,5.5343552999991585,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K22,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K22,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K22,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K22,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K22,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K22,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K22,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K22,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X22*100000000/'Calc-Units'!$E$21),\" \",X22*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y22*100000000/'Calc-Units'!$D$21),\" \",Y22*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z22*100000000/'Calc-Units'!$C$21),\" \",Z22*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA22*100000000/'Calc-Units'!$C$21),\" \",AA22*100000000/'Calc-Units'!$C$21)","v":" "},null,0.52569999999999995,2.9094105812095572,2.6249447187896013,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN22*100000000/'Calc-Units'!$E$21),\" \",AN22*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO22*100000000/'Calc-Units'!$D$21),\" \",AO22*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP22*100000000/'Calc-Units'!$C$21),\" \",AP22*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ22*100000000/'Calc-Units'!$C$21),\" \",AQ22*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"HR & Non-operational Training",{"$f":"'RRP 1.3'!U$12","v":1.3726373768207174},0,0,0,0,1.3726373768207174,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K23,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K23,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K23,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K23,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K23,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K23,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K23,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K23,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,0.51732509844822394,0.18048460459234766,4.8512051243262279E-2,0.62631562253688344,null,null,0.51732509844822394,0.18048460459234766,4.8512051243262279E-2,0.62631562253688344,null,null,{"$f":"IF(ISERROR(X23*100000000/'Calc-Units'!$E$21),\" \",X23*100000000/'Calc-Units'!$E$21)","v":1.9556088931275417E-3},{"$f":"IF(ISERROR(Y23*100000000/'Calc-Units'!$D$21),\" \",Y23*100000000/'Calc-Units'!$D$21)","v":6.9779553755935334E-4},{"$f":"IF(ISERROR(Z23*100000000/'Calc-Units'!$C$21),\" \",Z23*100000000/'Calc-Units'!$C$21)","v":2.8396190144733247E-4},{"$f":"IF(ISERROR(AA23*100000000/'Calc-Units'!$C$21),\" \",AA23*100000000/'Calc-Units'!$C$21)","v":3.6660947233486505E-3},null,0.52569999999999995,0.7215954689946511,0.6510419078260663,null,null,0.24536729419399264,8.56038479581505E-2,2.3009265904679301E-2,0.29706149976924384,null,null,{"$f":"IF(ISERROR(AN23*100000000/'Calc-Units'!$E$21),\" \",AN23*100000000/'Calc-Units'!$E$21)","v":9.2754529801039316E-4},{"$f":"IF(ISERROR(AO23*100000000/'Calc-Units'!$D$21),\" \",AO23*100000000/'Calc-Units'!$D$21)","v":3.3096442346440129E-4},{"$f":"IF(ISERROR(AP23*100000000/'Calc-Units'!$C$21),\" \",AP23*100000000/'Calc-Units'!$C$21)","v":1.3468312985646981E-4},{"$f":"IF(ISERROR(AQ23*100000000/'Calc-Units'!$C$21),\" \",AQ23*100000000/'Calc-Units'!$C$21)","v":1.7388287272842651E-3}]
[null,null,"Health & Safety & Operational Training",{"$f":"'RRP 1.3'!V$12","v":1.9614634264481019},0,0,0,0,1.9614634264481019,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K24,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K24,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K24,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K24,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K24,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K24,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K24,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K24,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,0.73924422963049519,0.25790784727485638,6.9322470641176082E-2,0.89498887890157419,null,null,0.73924422963049519,0.25790784727485638,6.9322470641176082E-2,0.89498887890157419,null,null,{"$f":"IF(ISERROR(X24*100000000/'Calc-Units'!$E$21),\" \",X24*100000000/'Calc-Units'!$E$21)","v":2.794514694908629E-3},{"$f":"IF(ISERROR(Y24*100000000/'Calc-Units'!$D$21),\" \",Y24*100000000/'Calc-Units'!$D$21)","v":9.9713183479786067E-4},{"$f":"IF(ISERROR(Z24*100000000/'Calc-Units'!$C$21),\" \",Z24*100000000/'Calc-Units'!$C$21)","v":4.0577423695373498E-4},{"$f":"IF(ISERROR(AA24*100000000/'Calc-Units'!$C$21),\" \",AA24*100000000/'Calc-Units'!$C$21)","v":5.2387548519174324E-3},null,0.52569999999999995,1.031141323283767,0.93032210316433483,null,null,0.35062353811374392,0.1223256919624644,3.2879647825109819E-2,0.42449322526301669,null,null,{"$f":"IF(ISERROR(AN24*100000000/'Calc-Units'!$E$21),\" \",AN24*100000000/'Calc-Units'!$E$21)","v":1.3254383197951628E-3},{"$f":"IF(ISERROR(AO24*100000000/'Calc-Units'!$D$21),\" \",AO24*100000000/'Calc-Units'!$D$21)","v":4.7293962924462534E-4},{"$f":"IF(ISERROR(AP24*100000000/'Calc-Units'!$C$21),\" \",AP24*100000000/'Calc-Units'!$C$21)","v":1.9245872058715652E-4},{"$f":"IF(ISERROR(AQ24*100000000/'Calc-Units'!$C$21),\" \",AQ24*100000000/'Calc-Units'!$C$21)","v":2.4847414262644386E-3}]
[null,null,"Finance & Regulation",{"$f":"'RRP 1.3'!W$12","v":7.7816755968572568},0,0,0,0,7.7816755968572568,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K25,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K25,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K25,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K25,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K25,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K25,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K25,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K25,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,2.9327892145560601,1.0231927724551126,0.27502168576201425,3.5506719240840701,null,null,2.9327892145560601,1.0231927724551126,0.27502168576201425,3.5506719240840701,null,null,{"$f":"IF(ISERROR(X25*100000000/'Calc-Units'!$E$21),\" \",X25*100000000/'Calc-Units'!$E$21)","v":1.108662364702259E-2},{"$f":"IF(ISERROR(Y25*100000000/'Calc-Units'!$D$21),\" \",Y25*100000000/'Calc-Units'!$D$21)","v":3.9559016808929101E-3},{"$f":"IF(ISERROR(Z25*100000000/'Calc-Units'!$C$21),\" \",Z25*100000000/'Calc-Units'!$C$21)","v":1.6098202163545672E-3},{"$f":"IF(ISERROR(AA25*100000000/'Calc-Units'!$C$21),\" \",AA25*100000000/'Calc-Units'!$C$21)","v":2.0783609951323286E-2},null,0.52569999999999995,4.0908268612678595,3.6908487355893973,null,null,1.3910219244639395,0.48530033197545996,0.13044278555692337,1.6840836935930745,null,null,{"$f":"IF(ISERROR(AN25*100000000/'Calc-Units'!$E$21),\" \",AN25*100000000/'Calc-Units'!$E$21)","v":5.2583855957828154E-3},{"$f":"IF(ISERROR(AO25*100000000/'Calc-Units'!$D$21),\" \",AO25*100000000/'Calc-Units'!$D$21)","v":1.8762841672475075E-3},{"$f":"IF(ISERROR(AP25*100000000/'Calc-Units'!$C$21),\" \",AP25*100000000/'Calc-Units'!$C$21)","v":7.6353772861697123E-4},{"$f":"IF(ISERROR(AQ25*100000000/'Calc-Units'!$C$21),\" \",AQ25*100000000/'Calc-Units'!$C$21)","v":9.8576661999126344E-3}]
[null,null,"CEO etc",{"$f":"'RRP 1.3'!X$12","v":1.536754324034403},0,0,0,0,1.536754324034403,null,"MEAV",{"$f":"IF(ISERROR(VLOOKUP($K26,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K26,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":0.37688402427627665},{"$f":"IF(ISERROR(VLOOKUP($K26,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K26,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":0.13148746175802342},{"$f":"IF(ISERROR(VLOOKUP($K26,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K26,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":3.5342219338092909E-2},{"$f":"IF(ISERROR(VLOOKUP($K26,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K26,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":0.456286294627607},null,null,0.5791781539660551,0.20206392541295071,5.4312308388786576E-2,0.7011999362666107,null,null,0.5791781539660551,0.20206392541295071,5.4312308388786576E-2,0.7011999362666107,null,null,{"$f":"IF(ISERROR(X26*100000000/'Calc-Units'!$E$21),\" \",X26*100000000/'Calc-Units'!$E$21)","v":2.1894277930815872E-3},{"$f":"IF(ISERROR(Y26*100000000/'Calc-Units'!$D$21),\" \",Y26*100000000/'Calc-Units'!$D$21)","v":7.8122622022721384E-4},{"$f":"IF(ISERROR(Z26*100000000/'Calc-Units'!$C$21),\" \",Z26*100000000/'Calc-Units'!$C$21)","v":3.1791330126894508E-4},{"$f":"IF(ISERROR(AA26*100000000/'Calc-Units'!$C$21),\" \",AA26*100000000/'Calc-Units'!$C$21)","v":4.1044248201042542E-3},null,0.52569999999999995,0.8078717481448856,0.72888257588951744,null,null,0.27470419842609994,9.5838919823362526E-2,2.5760327868801475E-2,0.33257912977125348,null,null,{"$f":"IF(ISERROR(AN26*100000000/'Calc-Units'!$E$21),\" \",AN26*100000000/'Calc-Units'!$E$21)","v":1.038445602258597E-3},{"$f":"IF(ISERROR(AO26*100000000/'Calc-Units'!$D$21),\" \",AO26*100000000/'Calc-Units'!$D$21)","v":3.7053559625376757E-4},{"$f":"IF(ISERROR(AP26*100000000/'Calc-Units'!$C$21),\" \",AP26*100000000/'Calc-Units'!$C$21)","v":1.5078627879186067E-4},{"$f":"IF(ISERROR(AQ26*100000000/'Calc-Units'!$C$21),\" \",AQ26*100000000/'Calc-Units'!$C$21)","v":1.9467286921754476E-3}]
["Other Costs from full activitty cost allocation",null,"Atypical cash costs",{"$f":"'RRP 1.3'!Y$12","v":2.24185108},0,0,0,0,2.24185108,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K27,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K27,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K27,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K27,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K27,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K27,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K27,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K27,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X27*100000000/'Calc-Units'!$E$21),\" \",X27*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y27*100000000/'Calc-Units'!$D$21),\" \",Y27*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z27*100000000/'Calc-Units'!$C$21),\" \",Z27*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA27*100000000/'Calc-Units'!$C$21),\" \",AA27*100000000/'Calc-Units'!$C$21)","v":" "},null,0,0,2.24185108,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN27*100000000/'Calc-Units'!$E$21),\" \",AN27*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO27*100000000/'Calc-Units'!$D$21),\" \",AO27*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP27*100000000/'Calc-Units'!$C$21),\" \",AP27*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ27*100000000/'Calc-Units'!$C$21),\" \",AQ27*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Pension deficit payments",{"$f":"'RRP 1.3'!Z$12","v":7.62},0,0,0,0,7.62,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K28,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K28,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K28,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K28,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K28,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K28,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K28,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K28,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X28*100000000/'Calc-Units'!$E$21),\" \",X28*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y28*100000000/'Calc-Units'!$D$21),\" \",Y28*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z28*100000000/'Calc-Units'!$C$21),\" \",Z28*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA28*100000000/'Calc-Units'!$C$21),\" \",AA28*100000000/'Calc-Units'!$C$21)","v":" "},null,0.57699999999999996,4.3967399999999994,3.2232600000000002,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN28*100000000/'Calc-Units'!$E$21),\" \",AN28*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO28*100000000/'Calc-Units'!$D$21),\" \",AO28*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP28*100000000/'Calc-Units'!$C$21),\" \",AP28*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ28*100000000/'Calc-Units'!$C$21),\" \",AQ28*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Metering",{"$f":"'RRP 1.3'!AA$12","v":0.81564207},0,0,0,0,0.81564207,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K29,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K29,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K29,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K29,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K29,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K29,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K29,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K29,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X29*100000000/'Calc-Units'!$E$21),\" \",X29*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y29*100000000/'Calc-Units'!$D$21),\" \",Y29*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z29*100000000/'Calc-Units'!$C$21),\" \",Z29*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA29*100000000/'Calc-Units'!$C$21),\" \",AA29*100000000/'Calc-Units'!$C$21)","v":" "},null,0,0,0.81564207,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN29*100000000/'Calc-Units'!$E$21),\" \",AN29*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO29*100000000/'Calc-Units'!$D$21),\" \",AO29*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP29*100000000/'Calc-Units'!$C$21),\" \",AP29*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ29*100000000/'Calc-Units'!$C$21),\" \",AQ29*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Excluded services & de minimis",{"$f":"'RRP 1.3'!AB$12","v":12.183907341469606},0,0,0,0,12.183907341469606,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K30,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K30,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K30,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K30,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K30,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K30,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K30,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K30,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X30*100000000/'Calc-Units'!$E$21),\" \",X30*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y30*100000000/'Calc-Units'!$D$21),\" \",Y30*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z30*100000000/'Calc-Units'!$C$21),\" \",Z30*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA30*100000000/'Calc-Units'!$C$21),\" \",AA30*100000000/'Calc-Units'!$C$21)","v":" "},null,0,0,12.183907341469606,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN30*100000000/'Calc-Units'!$E$21),\" \",AN30*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO30*100000000/'Calc-Units'!$D$21),\" \",AO30*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP30*100000000/'Calc-Units'!$C$21),\" \",AP30*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ30*100000000/'Calc-Units'!$C$21),\" \",AQ30*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Relevant distributed generation (less contributions)",{"$f":"'RRP 1.3'!AC$12","v":1.3999999737279722E-7},0,0,0,0,1.3999999737279722E-7,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K31,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K31,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K31,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K31,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K31,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K31,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K31,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K31,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X31*100000000/'Calc-Units'!$E$21),\" \",X31*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y31*100000000/'Calc-Units'!$D$21),\" \",Y31*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z31*100000000/'Calc-Units'!$C$21),\" \",Z31*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA31*100000000/'Calc-Units'!$C$21),\" \",AA31*100000000/'Calc-Units'!$C$21)","v":" "},null,0,0,1.3999999737279722E-7,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN31*100000000/'Calc-Units'!$E$21),\" \",AN31*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO31*100000000/'Calc-Units'!$D$21),\" \",AO31*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP31*100000000/'Calc-Units'!$C$21),\" \",AP31*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ31*100000000/'Calc-Units'!$C$21),\" \",AQ31*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"IFI",{"$f":"'RRP 1.3'!AD$12","v":1.0147458008000003},0,0,0,0,1.0147458008000003,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K32,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K32,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K32,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K32,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K32,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K32,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K32,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K32,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X32*100000000/'Calc-Units'!$E$21),\" \",X32*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y32*100000000/'Calc-Units'!$D$21),\" \",Y32*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z32*100000000/'Calc-Units'!$C$21),\" \",Z32*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA32*100000000/'Calc-Units'!$C$21),\" \",AA32*100000000/'Calc-Units'!$C$21)","v":" "},null,0,0,1.0147458008000003,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN32*100000000/'Calc-Units'!$E$21),\" \",AN32*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO32*100000000/'Calc-Units'!$D$21),\" \",AO32*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP32*100000000/'Calc-Units'!$C$21),\" \",AP32*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ32*100000000/'Calc-Units'!$C$21),\" \",AQ32*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Disallowed Related Party Margins",{"$f":"'RRP 1.3'!AE$12","v":-5.1969463263321618},0,0,0,0,-5.1969463263321618,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K33,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K33,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K33,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K33,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K33,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K33,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K33,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K33,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X33*100000000/'Calc-Units'!$E$21),\" \",X33*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y33*100000000/'Calc-Units'!$D$21),\" \",Y33*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z33*100000000/'Calc-Units'!$C$21),\" \",Z33*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA33*100000000/'Calc-Units'!$C$21),\" \",AA33*100000000/'Calc-Units'!$C$21)","v":" "},null,0,0,-5.1969463263321618,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN33*100000000/'Calc-Units'!$E$21),\" \",AN33*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO33*100000000/'Calc-Units'!$D$21),\" \",AO33*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP33*100000000/'Calc-Units'!$C$21),\" \",AP33*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ33*100000000/'Calc-Units'!$C$21),\" \",AQ33*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Statutory Depreciation",{"$f":"'RRP 1.3'!AF$12","v":39.130465450300001},0,0,0,0,39.130465450300001,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K34,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K34,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K34,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K34,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K34,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K34,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K34,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K34,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X34*100000000/'Calc-Units'!$E$21),\" \",X34*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y34*100000000/'Calc-Units'!$D$21),\" \",Y34*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z34*100000000/'Calc-Units'!$C$21),\" \",Z34*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA34*100000000/'Calc-Units'!$C$21),\" \",AA34*100000000/'Calc-Units'!$C$21)","v":" "},null,0,0,39.130465450300001,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN34*100000000/'Calc-Units'!$E$21),\" \",AN34*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO34*100000000/'Calc-Units'!$D$21),\" \",AO34*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP34*100000000/'Calc-Units'!$C$21),\" \",AP34*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ34*100000000/'Calc-Units'!$C$21),\" \",AQ34*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Network Rates",{"$f":"'RRP 1.3'!AG$12","v":20.184226800000001},0,0,0,0,20.184226800000001,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K35,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K35,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K35,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K35,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K35,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K35,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K35,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K35,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X35*100000000/'Calc-Units'!$E$21),\" \",X35*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y35*100000000/'Calc-Units'!$D$21),\" \",Y35*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z35*100000000/'Calc-Units'!$C$21),\" \",Z35*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA35*100000000/'Calc-Units'!$C$21),\" \",AA35*100000000/'Calc-Units'!$C$21)","v":" "},null,0,0,20.184226800000001,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN35*100000000/'Calc-Units'!$E$21),\" \",AN35*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO35*100000000/'Calc-Units'!$D$21),\" \",AO35*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP35*100000000/'Calc-Units'!$C$21),\" \",AP35*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ35*100000000/'Calc-Units'!$C$21),\" \",AQ35*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Transmission Exit Charges",{"$f":"'RRP 1.3'!AH$12","v":8},0,0,0,0,8,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K36,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K36,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K36,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K36,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K36,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K36,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K36,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K36,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X36*100000000/'Calc-Units'!$E$21),\" \",X36*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y36*100000000/'Calc-Units'!$D$21),\" \",Y36*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z36*100000000/'Calc-Units'!$C$21),\" \",Z36*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA36*100000000/'Calc-Units'!$C$21),\" \",AA36*100000000/'Calc-Units'!$C$21)","v":" "},null,0,0,8,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN36*100000000/'Calc-Units'!$E$21),\" \",AN36*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO36*100000000/'Calc-Units'!$D$21),\" \",AO36*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP36*100000000/'Calc-Units'!$C$21),\" \",AP36*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ36*100000000/'Calc-Units'!$C$21),\" \",AQ36*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Pension deficit repair payments by related parties (note 2)",{"$f":"'RRP 1.3'!AI$12","v":-7.62},0,0,0,0,-7.62,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K37,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K37,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K37,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K37,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K37,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K37,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K37,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K37,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X37*100000000/'Calc-Units'!$E$21),\" \",X37*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y37*100000000/'Calc-Units'!$D$21),\" \",Y37*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z37*100000000/'Calc-Units'!$C$21),\" \",Z37*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA37*100000000/'Calc-Units'!$C$21),\" \",AA37*100000000/'Calc-Units'!$C$21)","v":" "},null,0,0,-7.62,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN37*100000000/'Calc-Units'!$E$21),\" \",AN37*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO37*100000000/'Calc-Units'!$D$21),\" \",AO37*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP37*100000000/'Calc-Units'!$C$21),\" \",AP37*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ37*100000000/'Calc-Units'!$C$21),\" \",AQ37*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Non activity costs and reconciling amounts (note 3)",{"$f":"'RRP 1.3'!AJ$12","v":2.4709437074936318},0,0,0,0,2.4709437074936318,null,"Do not allocate",{"$f":"IF(ISERROR(VLOOKUP($K38,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE)),\" \",VLOOKUP($K38,'Calc-Drivers'!$B$17:$F$27,L$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K38,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE)),\" \",VLOOKUP($K38,'Calc-Drivers'!$B$17:$F$27,M$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K38,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE)),\" \",VLOOKUP($K38,'Calc-Drivers'!$B$17:$F$27,N$42,FALSE))","v":" "},{"$f":"IF(ISERROR(VLOOKUP($K38,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE)),\" \",VLOOKUP($K38,'Calc-Drivers'!$B$17:$F$27,O$42,FALSE))","v":" "},null,null," "," "," "," ",null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(X38*100000000/'Calc-Units'!$E$21),\" \",X38*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(Y38*100000000/'Calc-Units'!$D$21),\" \",Y38*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(Z38*100000000/'Calc-Units'!$C$21),\" \",Z38*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AA38*100000000/'Calc-Units'!$C$21),\" \",AA38*100000000/'Calc-Units'!$C$21)","v":" "},null,0,0,2.4709437074936318,null,null," "," "," "," ",null,null,{"$f":"IF(ISERROR(AN38*100000000/'Calc-Units'!$E$21),\" \",AN38*100000000/'Calc-Units'!$E$21)","v":" "},{"$f":"IF(ISERROR(AO38*100000000/'Calc-Units'!$D$21),\" \",AO38*100000000/'Calc-Units'!$D$21)","v":" "},{"$f":"IF(ISERROR(AP38*100000000/'Calc-Units'!$C$21),\" \",AP38*100000000/'Calc-Units'!$C$21)","v":" "},{"$f":"IF(ISERROR(AQ38*100000000/'Calc-Units'!$C$21),\" \",AQ38*100000000/'Calc-Units'!$C$21)","v":" "}]
[null,null,"Total Annual Operating & Capital Expenditure per Regulatory Accounts",{"$f":"SUM(D6:D38)","v":299},{"$f":"SUM(E6:E38)","v":50.108008846344582},{"$f":"SUM(F6:F38)","v":48.765446533988381},{"$f":"SUM(G6:G38)","v":12.794773386254157},{"$f":"SUM(H6:H38)","v":19.401749813401153},167.93002142001174,null,null,null,null,null,null,null,"Total",{"$f":"SUM(R6:R38)","v":26.4335615819456},{"$f":"SUM(S6:S38)","v":9.2221524229070653},{"$f":"SUM(T6:T38)","v":2.4788016236827075},{"$f":"SUM(U6:U38)","v":32.002608471392918},null,"Total all network tiers",{"$f":"SUM(X40:AA40)","v":201.2071026799166},null,null,null,null,"Total all network tiers",{"$f":"SUM(AD40:AG40)","v":0.90383308625429115},null,null,null,null,"Total",{"$f":"SUM(AJ6:AJ38)","v":153.21038052366586},{"$f":"SUM(AK6:AK38)","v":145.78961947633414},null,"Total all network tiers",{"$f":"SUM(AN40:AQ40)","v":61.303057958715144},null,null,null,null,"Total all network tiers",{"$f":"SUM(AT40:AW40)","v":0.30283590829671092}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Total by network tiers",{"$f":"SUM(X6:X38)","v":76.5415704282902},{"$f":"SUM(Y6:Y38)","v":57.987598956895461},{"$f":"SUM(Z6:Z38)","v":15.273575009936868},{"$f":"SUM(AA6:AA38)","v":51.404358284794071},null,"Total by network tiers",{"$f":"SUM(AD6:AD38)","v":0.28934489409562913},{"$f":"SUM(AE6:AE38)","v":0.22419356973574614},{"$f":"SUM(AF6:AF38)","v":8.9402803851187471E-2},{"$f":"SUM(AG6:AG38)","v":0.30089181857172836},null,null,null,null,null,"Total by network tiers",{"$f":"SUM(AN6:AN38)","v":15.340742709529394},{"$f":"SUM(AO6:AO38)","v":12.174362749891531},{"$f":"SUM(AP6:AP38)","v":5.49878072963193},{"$f":"SUM(AQ6:AQ38)","v":28.289171769662286},null,"Total by network tiers",{"$f":"SUM(AT6:AT38)","v":5.7991566540898765E-2},{"$f":"SUM(AU6:AU38)","v":4.7068923239690634E-2},{"$f":"SUM(AV6:AV38)","v":3.2186728691359918E-2},{"$f":"SUM(AW6:AW38)","v":0.16558868982476163}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"% ",{"$f":"X40/$X$39","v":0.38041187119549019},{"$f":"Y40/$X$39","v":0.28819856846277958},{"$f":"Z40/$X$39","v":7.590972091196159E-2},{"$f":"AA40/$X$39","v":0.25547983942976865},null,"% ",{"$f":"AD40/$AD$39","v":0.32013089418395407},{"$f":"AE40/$AD$39","v":0.24804753570690799},{"$f":"AF40/$AD$39","v":9.8915170523016474E-2},{"$f":"AG40/$AD$39","v":0.33290639958612139},null,null,null,null,null,"% ",{"$f":"AN40/$AN$39","v":0.25024433071284463},{"$f":"AO40/$AN$39","v":0.19859307439590398},{"$f":"AP40/$AN$39","v":8.969831053672904E-2},{"$f":"AQ40/$AN$39","v":0.4614642843545223},null,"% ",{"$f":"AT40/$AT$39","v":0.19149501413841619},{"$f":"AU40/$AT$39","v":0.15542715361737652},{"$f":"AV40/$AT$39","v":0.10628438639391528},{"$f":"AW40/$AT$39","v":0.5467934458502921}]
[null,null,null,null,null,null,null,null,null,null,"Vlookup Values:",5,4,3,2,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"THESE % ARE USED TO ALLOCATE PRICE CONTROL OPEX"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Step 4.a. calculate proportion of cost classified as direct costs"]
[]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Total direct+other",{"$f":"SUMIF(X6:X11,\">0\",X6:X11)+SUMIF(X27:X38,\">0\",X27:X38)","v":54.630038216848384},{"$f":"SUMIF(Y6:Y11,\">0\",Y6:Y11)+SUMIF(Y27:Y38,\">0\",Y27:Y38)","v":50.003893900149059},{"$f":"SUMIF(Z6:Z11,\">0\",Z6:Z11)+SUMIF(Z27:Z38,\">0\",Z27:Z38)","v":13.269582398644378},{"$f":"SUMIF(AA6:AA11,\">0\",AA6:AA11)+SUMIF(AA27:AA38,\">0\",AA27:AA38)","v":37.616109438360894},"Max of zero or total from each catergory"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Total indirect",{"$f":"SUMIF(X12:X27,\">0\",X12:X27)","v":22.883785649150184},{"$f":"SUMIF(Y12:Y27,\">0\",Y12:Y27)","v":7.9837050567463947},{"$f":"SUMIF(Z12:Z27,\">0\",Z12:Z27)","v":2.145922139446538},{"$f":"SUMIF(AA12:AA27,\">0\",AA12:AA27)","v":27.704962503926446},"Max of zero or total from each catergory"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"% direct+other",{"$f":"X46/(X47+X46)","v":0.70477800593723305},{"$f":"Y46/(Y47+Y46)","v":0.86232047540576717},{"$f":"Z46/(Z47+Z46)","v":0.86079455692519979},{"$f":"AA46/(AA47+AA46)","v":0.57586485218117034}]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"% indirect",{"$f":"X47/(X46+X47)","v":0.29522199406276683},{"$f":"Y47/(Y46+Y47)","v":0.13767952459423277},{"$f":"Z47/(Z46+Z47)","v":0.13920544307480012},{"$f":"AA47/(AA46+AA47)","v":0.42413514781882961}]

{"sheet":"Calc-Units","index":6,"n_rows":21,"n_cols":6,"rows_kept":21,"cut":false,"hidden":false,"merged":[]}
["103. Units distributed (GWh) from RRP table 5.1",null,null,"Index"]
[null,"Units distributed (GWh) from RRP table 5.1"]
["Units distributed at LV",{"$f":"'RRP 5.1'!G36","v":17084}]
["Units distributed at HV",{"$f":"'RRP 5.1'!G35","v":9051}]
["Units distributed at EHV+",{"$f":"'RRP 5.1'!G34","v":616}]
["Losses",{"$f":"'RRP 5.1'!G40","v":1381}]
[]
["104. Estimated line loss adjustment factors relative to LV"]
[null,"LV services","LV","HV","EHV","132kV"]
["Units distributed at LV",1,1,1,1,1]
["Units distributed at HV",0,0,{"$f":"(1+$B$6/($B$3+$B$4/2+$B$5/4)/2)/(1+$B$6/($B$3+$B$4/2+$B$5/4))","v":0.97016569811402287},{"$f":"(1+$B$6/($B$3+$B$4/2+$B$5/4)/2)/(1+$B$6/($B$3+$B$4/2+$B$5/4))","v":0.97016569811402287},{"$f":"(1+$B$6/($B$3+$B$4/2+$B$5/4)/2)/(1+$B$6/($B$3+$B$4/2+$B$5/4))","v":0.97016569811402287}]
["Units distributed at EHV+",0,0,0,{"$f":"(1+$B$6/($B$3+$B$4/2+$B$5/4)/4)/(1+$B$6/($B$3+$B$4/2+$B$5/4))","v":0.95524854717103425},{"$f":"(1+$B$6/($B$3+$B$4/2+$B$5/4)/4)/(1+$B$6/($B$3+$B$4/2+$B$5/4))","v":0.95524854717103425}]
[]
[]
[]
[]
[]
[]
[null,"LV services","LV","HV","EHV","132kV"]
["Units (GWh) flowing through each level, loss-adjusted to LV",{"$f":"SUMPRODUCT(B$10:B$12,$B$3:$B$5)","v":17084},{"$f":"SUMPRODUCT(C$10:C$12,$B$3:$B$5)","v":17084},{"$f":"SUMPRODUCT(D$10:D$12,$B$3:$B$5)","v":25864.969733630023},{"$f":"SUMPRODUCT(E$10:E$12,$B$3:$B$5)","v":26453.40283868738},{"$f":"SUMPRODUCT(F$10:F$12,$B$3:$B$5)","v":26453.40283868738}]
["Units (kWh) flowing through each level, loss-adjusted to LV",{"$f":"B20*1000000","v":17084000000},{"$f":"C20*1000000","v":17084000000},{"$f":"D20*1000000","v":25864969733.630024},{"$f":"E20*1000000","v":26453402838.687378},{"$f":"F20*1000000","v":26453402838.687378}]

{"sheet":"Calc-Drivers","index":7,"n_rows":27,"n_cols":8,"rows_kept":27,"cut":false,"hidden":false,"merged":[]}
["Drivers - LV, HV, EHV split",null,null,null,null,null,null,"Index"]
[]
[null,"Category","LV","HV","EHV",null,"Source"]
[null,"Net Capex",{"$f":"'Calc-Net capex'!$D$6","v":0.17584193572888193},{"$f":"'Calc-Net capex'!$D$7","v":0.25925871853570936},{"$f":"'Calc-Net capex'!$D$8+'Calc-Net capex'!$D$9","v":0.56489934573540879},null,"FBPQ capex - see \"Calc Net capex\""]
[null,"Customers",1,0,0,null,"Assumption"]
[null,"Network Length",{"$f":"'RRP 5.1'!$G$64/'RRP 5.1'!$G$65","v":0.50771415660706221},{"$f":"'RRP 5.1'!$G$63/'RRP 5.1'!$G$65","v":0.42965270156865276},{"$f":"('RRP 5.1'!$G$61+'RRP 5.1'!$G$62)/'RRP 5.1'!$G$65","v":6.2633141824285074E-2},null,"RRP table 5.1"]
[null,"Substations",{"$f":"0/'RRP 5.1'!$G$73","v":0},{"$f":"('RRP 5.1'!$G$71+'RRP 5.1'!$G$72)/'RRP 5.1'!$G$73","v":0.99556999409332547},{"$f":"('RRP 5.1'!$G$68+'RRP 5.1'!$G$69+'RRP 5.1'!$G$70)/'RRP 5.1'!$G$73","v":4.4300059066745426E-3},null,"RRP table 5.1"]
[null,"Transmission Exit Charges",0,0,1,null,"Assumption"]
[null,"MEAV",{"$f":"'Calc-MEAV'!D6","v":0.456286294627607},{"$f":"'Calc-MEAV'!D7","v":0.16682968109611637},{"$f":"'Calc-MEAV'!D8+'Calc-MEAV'!D9","v":0.37688402427627665},null,"FBPQ capex - see \"Calc MEAV\""]
[null,"EHV only",0,0,1,null,"Assumption"]
[null,"LV only",1,0,0,null,"Assumption"]
[null,"HV only",0,1,0,null,"Assumption"]
[]
["Drivers - LV, LV/HV, HV, EHV split"]
[]
[null,"Category","LV","LV/HV","HV","EHV","Source"]
[null,"Net Capex",{"$f":"'Calc-Net capex'!H6","v":0.1758419357288819},{"$f":"'Calc-Net capex'!H7","v":5.3178230445720967E-2},{"$f":"'Calc-Net capex'!H8","v":0.20608048808998844},{"$f":"'Calc-Net capex'!$D$8+'Calc-Net capex'!$D$9","v":0.56489934573540879},"FBPQ capex - see \"Calc Net capex\""]
[null,"No. of Customers",1,0,0,0,"Assumption"]
[null,"Network Length",{"$f":"'RRP 5.1'!$G$64/'RRP 5.1'!$G$65","v":0.50771415660706221},0,{"$f":"'RRP 5.1'!$G$63/'RRP 5.1'!$G$65","v":0.42965270156865276},{"$f":"('RRP 5.1'!$G$61+'RRP 5.1'!$G$62)/'RRP 5.1'!$G$65","v":6.2633141824285074E-2},"RRP table 5.1"]
[null,"No. of Substations",{"$f":"0/'RRP 5.1'!$G$73","v":0},0,{"$f":"('RRP 5.1'!$G$71+'RRP 5.1'!$G$72)/'RRP 5.1'!$G$73","v":0.99556999409332547},{"$f":"('RRP 5.1'!$G$68+'RRP 5.1'!$G$69+'RRP 5.1'!$G$70)/'RRP 5.1'!$G$73","v":4.4300059066745426E-3},"RRP table 5.1"]
[null,"Transmission Exit Charges",0,0,0,1,"Assumption"]
[null,"MEAV",{"$f":"'Calc-MEAV'!H6","v":0.456286294627607},{"$f":"'Calc-MEAV'!H7","v":3.5342219338092909E-2},{"$f":"'Calc-MEAV'!H8","v":0.13148746175802342},{"$f":"'Calc-MEAV'!H9+'Calc-MEAV'!H10","v":0.37688402427627665},"FBPQ capex - see \"Calc MEAV\""]
[null,"MEAV excl services",{"$f":"'Calc-MEAV'!L6","v":0.29095507591047665},{"$f":"'Calc-MEAV'!L7","v":7.3362857886556845E-2},{"$f":"'Calc-MEAV'!L8","v":0.14419601068685498},{"$f":"'Calc-MEAV'!L9+'Calc-MEAV'!L10","v":0.49148605551611152},"FBPQ capex - see \"Calc MEAV\""]
[null,"MEAV excl services and 50% LV network",{"$f":"'Calc-MEAV'!Q3","v":0},{"$f":"'Calc-MEAV'!Q4","v":0},{"$f":"'Calc-MEAV'!Q5","v":"% of Total"},{"$f":"'Calc-MEAV'!Q6+'Calc-MEAV'!Q7","v":0.25609671548965307},"FBPQ capex - see \"Calc MEAV\""]
[null,"EHV only",0,0,0,1,"Assumption"]
[null,"LV only",1,0,0,0,"Assumption"]
[null,"HV only",0,0,1,0,"Assumption"]

{"sheet":"Calc-MEAV","index":8,"n_rows":164,"n_cols":18,"rows_kept":164,"cut":false,"hidden":false,"merged":[[2,14,2,16],[3,14,3,16],[2,1,2,3],[3,1,3,3],[2,5,2,7],[3,5,3,7],[2,9,2,11],[3,9,3,11]]}
["MEAV by Voltage Level",null,null,null,null,"Index"]
[]
[null,"MEAV  - LV, HV, EHV, 132kV split",null,null,null,"MEAV  - LV, LV/HV, HV, EHV, 132kV split",null,null,null,"MEAV  - LV (excl. services), LV/HV, HV, EHV, 132kV split",null,null,null,null,"MEAV  - LV (excl. services + 50%LV), LV/HV, HV, EHV, 132kV split"]
[null,"Sum of MEAV of asset classified in voltage tier (as calculated below)",null,null,null,"Sum of MEAV of asset classified in voltage tier",null,null,null,"Sum of MEAV of asset classified in voltage tier (as calculated below)",null,null,null,null,"Sum of MEAV of asset classified in voltage tier (as calculated below)"]
[null,null,"£m","% of Total",null,null,"£m","% of Total",null,null,"£m","% of Total",null,null,null,"£m","% of Total"]
[null,"LV",{"$f":"SUM(I20:I39)","v":7640546.6618143665},{"$f":"C6/$C$10","v":0.456286294627607},null,"LV",{"$f":"SUM(I20:I39)","v":7640546.6618143665},{"$f":"G6/$G$11","v":0.456286294627607},null,"LV",{"$f":"SUM(I20:I39)-I21-I30","v":3736022.4253502125},{"$f":"K6/$K$11","v":0.29095507591047665},null,null,"LV",{"$f":"(SUM(I20:I39)-I21-I30)*0.5","v":1868011.2126751062},{"$f":"P6/P$11","v":0.17024425268720195}]
[null,"HV",{"$f":"SUM(I42:I79)+SUM(I158:I163)+SUM(I153:I154)","v":2793574.9506366281},{"$f":"C7/$C$10","v":0.16682968109611637},null,"LV/HV",{"$f":"SUM(I62:I63)+SUM(I69:I70)+SUM(I75:I78)","v":591807.99240345811},{"$f":"G7/$G$11","v":3.5342219338092909E-2},null,"LV/HV",{"$f":"SUM(I59:I72)+SUM(I75:I78)","v":942019.24951565289},{"$f":"K7/$K$11","v":7.3362857886556845E-2},null,null,"LV/HV",{"$f":"SUM(I59:I72)+SUM(I75:I78)","v":942019.24951565289},{"$f":"P7/P$11","v":8.585246280245111E-2}]
[null,"EHV",{"$f":"SUM(I81:I120)+SUM(I149:I150)","v":1473541.3356383634},{"$f":"C8/$C$10","v":8.7998509240094391E-2},null,"HV",{"$f":"SUM(I42:I56)+SUM(I59:I61)+SUM(I64:I68)+SUM(I71:I72)+SUM(I158:I163)+SUM(I153:I154)","v":2201766.9582331693},{"$f":"G8/$G$11","v":0.13148746175802342},null,"HV",{"$f":"SUM(I42:I56)+SUM(I158:I163)+SUM(I153:I154)","v":1851555.7011209747},{"$f":"K8/$K$11","v":0.14419601068685498},null,null,"HV",{"$f":"SUM(I42:I56)+SUM(I158:I163)+SUM(I153:I154)","v":1851555.7011209747},{"$f":"P8/P$11","v":0.16874455276671438}]
[null,"132 kV",{"$f":"SUM(I121:I146)","v":4837408.6259979457},{"$f":"C9/$C$10","v":0.28888551503618226},"Check","EHV",{"$f":"SUM(I81:I120)+SUM(I149:I150)","v":1473541.3356383634},{"$f":"G9/$G$11","v":8.7998509240094391E-2},null,"EHV",{"$f":"SUM(I81:I120)+SUM(I149:I150)","v":1473541.3356383634},{"$f":"K9/$K$11","v":0.11475689446047581},null,null,"EHV",{"$f":"SUM(I81:I120)+SUM(I149:I150)","v":1473541.3356383634},{"$f":"P9/P$11","v":0.13429359619860362}]
[null,"Total",{"$f":"SUM(C6:C9)","v":16745071.574087303},{"$f":"SUM(D6:D9)","v":1},{"$f":"IF(C10=$I$164,\"OK\", \"error\")","v":"OK"},"132 kV",{"$f":"SUM(I121:I146)","v":4837408.6259979457},{"$f":"G10/$G$11","v":0.28888551503618226},"Check","132 kV",{"$f":"SUM(I121:I146)","v":4837408.6259979457},{"$f":"K10/$K$11","v":0.3767291610556357},"Check",null,"132 kV",{"$f":"SUM(I121:I146)","v":4837408.6259979457},{"$f":"P10/P$11","v":0.44086513554502893},"Check"]
[null,null,null,null,null,"Total",{"$f":"SUM(G6:G10)","v":16745071.574087303},{"$f":"SUM(H6:H10)","v":1},{"$f":"IF(G11=$I$164,\"OK\", \"error\")","v":"OK"},"Total",{"$f":"SUM(K6:K10)","v":12840547.337623149},{"$f":"SUM(L6:L10)","v":0.99999999999999989},{"$f":"IF(K11=($I$164-I21-I30),\"OK\", \"error\")","v":"OK"},null,"Total",{"$f":"SUM(P6:P10)","v":10972536.124948043},{"$f":"SUM(Q6:Q10)","v":1},{"$f":"IF(P11=($I$164-I21-I30-(SUM(I20:I39)-I21-I30)*0.5),\"OK\", \"error\")","v":"OK"}]
[]
[]
["MEAV Calculation = Replacement unit cost*FBPQ closing asset balance"]
[]
[null,null,"Asset categories","Units","DNO reported Unit Cost (£)",null,"Unit cost used in MEAV calculation (£)","Closing DCPR asset Balance (units)","MEAV (£)"]
[null,null,null,null,"Sum of direct and indriect replacement unit cost from FBPQ C2","PB power numbers, if available","Is DNO Unit cost if avaliable, otherwise PB power unit cost","Closing asset balannce from FBPQ V4","Unit cost used in MEAV calculation*Closing DCPR asset Balance (units)","Classification"]
["LV Network",null,null,null,null,null,null,null,null,null,null,"LV",{"$f":"SUMIF(J:J,L18,I:I)","v":7640546.6618143665},{"$f":"M18/M$25","v":0.456286294627607}]
[null,"Overhead lines",null,null,null,null,null,null,null,"LV",null,"HV/LV",{"$f":"SUMIF(J:J,L19,I:I)","v":782060.85740345821},{"$f":"M19/M$25","v":4.6703942347650712E-2}]
[null,null,"LV Main (OHL)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J12),'FBPQ C2'!J12,IF(ISNUMBER('FBPQ C2'!I12),'FBPQ C2'!I12,\"\"))","v":41.700246577433042},"DATA",{"$f":"IF(ISNUMBER(E20),E20,IF(H20>0,F20,\" \"))","v":41.700246577433042},{"$f":"IF(ISBLANK('FBPQ T4'!E12),\" \",'FBPQ T4'!AE12)","v":5998},{"$f":"IF(ISERROR(G20*H20),\" \",G20*H20)","v":250118.07897144338},"LV",null,"HV",1681558.985165759,0.10042112855271047]
[null,null,"LV Service (OHL)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J13),'FBPQ C2'!J13,IF(ISNUMBER('FBPQ C2'!I13),'FBPQ C2'!I13,\"\"))","v":0.50853959240772006},"DATA",0.50853959240772006,{"$f":"IF(ISBLANK('FBPQ T4'!E13),\" \",'FBPQ T4'!AE13)","v":236300},{"$f":"IF(ISERROR(G21*H21),\" \",G21*H21)","v":120167.90568594425},"LV",null,"EHV/HV",1318694.3352575633,7.8751191323554515E-2]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J14),'FBPQ C2'!J14,IF(ISNUMBER('FBPQ C2'!I14),'FBPQ C2'!I14,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E14),\" \",'FBPQ T4'!AE14)","v":" "}," ","LV",null,"EHV",358370.52060258045,2.1401552033802732E-2]
[null,"Overhead lines - Support",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J15),'FBPQ C2'!J15,IF(ISNUMBER('FBPQ C2'!I15),'FBPQ C2'!I15,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E15),\" \",'FBPQ T4'!AE15)","v":" "}," ","LV",null,"132kV/EHV",687177.21913543623,4.1037580287135389E-2]
[null,null,"LV Support","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J16),'FBPQ C2'!J16,IF(ISNUMBER('FBPQ C2'!I16),'FBPQ C2'!I16,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E16),\" \",'FBPQ T4'!AE16)","v":194497},0,"LV",null,"132kV",4276662.9947081394,0.25539831082753917]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J17),'FBPQ C2'!J17,IF(ISNUMBER('FBPQ C2'!I17),'FBPQ C2'!I17,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E17),\" \",'FBPQ T4'!AE17)","v":" "}," ","LV",null,"All",{"$f":"SUM(M18:M24)","v":16745071.574087303},1]
[null,"Underground cables",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J18),'FBPQ C2'!J18,IF(ISNUMBER('FBPQ C2'!I18),'FBPQ C2'!I18,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E18),\" \",'FBPQ T4'!AE18)","v":" "}," ","LV"]
[null,null,"LV Main (UG Consac)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J19),'FBPQ C2'!J19,IF(ISNUMBER('FBPQ C2'!I19),'FBPQ C2'!I19,\"\"))","v":127.13489810193002},"DATA",127.13489810193002,{"$f":"IF(ISBLANK('FBPQ T4'!E19),\" \",'FBPQ T4'!AE19)","v":3903},496207.50729183288,"LV"]
[null,null,"LV Main (UG Plastic)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J20),'FBPQ C2'!J20,IF(ISNUMBER('FBPQ C2'!I20),'FBPQ C2'!I20,\"\"))","v":127.13489810193002},"DATA",127.13489810193002,{"$f":"IF(ISBLANK('FBPQ T4'!E20),\" \",'FBPQ T4'!AE20)","v":5782.6999999999989},735182.97525403055,"LV",null,"EHV/HV",{"$f":"M21","v":1318694.3352575633},{"$f":"M28/M$32","v":0.19857147804650008}]
[null,null,"LV Main (UG Paper)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J21),'FBPQ C2'!J21,IF(ISNUMBER('FBPQ C2'!I21),'FBPQ C2'!I21,\"\"))","v":127.13489810193002},"DATA",127.13489810193002,{"$f":"IF(ISBLANK('FBPQ T4'!E21),\" \",'FBPQ T4'!AE21)","v":16215.5},2061555.9401718462,"LV",null,"EHV",{"$f":"M22","v":358370.52060258045},{"$f":"M29/M$32","v":5.3964108331783299E-2}]
[null,null,"LV Service (UG)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J22),'FBPQ C2'!J22,IF(ISNUMBER('FBPQ C2'!I22),'FBPQ C2'!I22,\"\"))","v":1.7000732843986286},"DATA",1.7000732843986286,{"$f":"IF(ISBLANK('FBPQ T4'!E22),\" \",'FBPQ T4'!AE22)","v":2225996},3784356.3307782095,"LV",null,"132kV/EHV",{"$f":"M23","v":687177.21913543623},{"$f":"M30/M$32","v":0.10347644062409317}]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J23),'FBPQ C2'!J23,IF(ISNUMBER('FBPQ C2'!I23),'FBPQ C2'!I23,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E23),\" \",'FBPQ T4'!AE23)","v":" "}," ","LV",null,"132kV",{"$f":"M24","v":4276662.9947081394},{"$f":"M31/M$32","v":0.64398797299762345}]
[null,"Switchgear ",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J24),'FBPQ C2'!J24,IF(ISNUMBER('FBPQ C2'!I24),'FBPQ C2'!I24,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E24),\" \",'FBPQ T4'!AE24)","v":" "}," ","LV",null,"All EHV",{"$f":"SUM(M28:M31)","v":6640905.0697037196},{"$f":"M32/M$32","v":1}]
[null,null,"LV Pillar (ID)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J25),'FBPQ C2'!J25,IF(ISNUMBER('FBPQ C2'!I25),'FBPQ C2'!I25,\"\"))","v":5.7210704145868512},"DATA",5.7210704145868512,{"$f":"IF(ISBLANK('FBPQ T4'!E25),\" \",'FBPQ T4'!AE25)","v":5238},29966.966831605925,"LV"]
[null,null,"LV Pillar (OD)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J26),'FBPQ C2'!J26,IF(ISNUMBER('FBPQ C2'!I26),'FBPQ C2'!I26,\"\"))","v":5.7210704145868512},"DATA",5.7210704145868512,{"$f":"IF(ISBLANK('FBPQ T4'!E26),\" \",'FBPQ T4'!AE26)","v":10420},59613.55371999499,"LV"]
[null,null,"LV Board (WM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J27),'FBPQ C2'!J27,IF(ISNUMBER('FBPQ C2'!I27),'FBPQ C2'!I27,\"\"))","v":5.7210704145868512},"DATA",5.7210704145868512,{"$f":"IF(ISBLANK('FBPQ T4'!E27),\" \",'FBPQ T4'!AE27)","v":0},0,"LV"]
[null,null,"LV UGB","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J28),'FBPQ C2'!J28,IF(ISNUMBER('FBPQ C2'!I28),'FBPQ C2'!I28,\"\"))","v":4.8311261278733406},"DATA",4.8311261278733406,{"$f":"IF(ISBLANK('FBPQ T4'!E28),\" \",'FBPQ T4'!AE28)","v":21398.2},103377.40310945932,"LV"]
[null,null,"LV Fuses (PM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J29),'FBPQ C2'!J29,IF(ISNUMBER('FBPQ C2'!I29),'FBPQ C2'!I29,\"\"))","v":""},"DATA","DATA",{"$f":"IF(ISBLANK('FBPQ T4'!E29),\" \",'FBPQ T4'!AE29)","v":34104}," ","LV"]
[null,null,"LV Fuses (TM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J30),'FBPQ C2'!J30,IF(ISNUMBER('FBPQ C2'!I30),'FBPQ C2'!I30,\"\"))","v":""},"DATA"," ",{"$f":"IF(ISBLANK('FBPQ T4'!E30),\" \",'FBPQ T4'!AE30)","v":0}," ","LV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J31),'FBPQ C2'!J31,IF(ISNUMBER('FBPQ C2'!I31),'FBPQ C2'!I31,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E31),\" \",'FBPQ T4'!AE31)","v":" "}," ","LV"]
["HV network",null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J32),'FBPQ C2'!J32,IF(ISNUMBER('FBPQ C2'!I32),'FBPQ C2'!I32,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E32),\" \",'FBPQ T4'!AE32)","v":" "}," "]
[null,"Overhead lines",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J33),'FBPQ C2'!J33,IF(ISNUMBER('FBPQ C2'!I33),'FBPQ C2'!I33,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E33),\" \",'FBPQ T4'!AE33)","v":" "}," ","HV"]
[null,null,"6.6/11 kV OHL (Open)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J34),'FBPQ C2'!J34,IF(ISNUMBER('FBPQ C2'!I34),'FBPQ C2'!I34,\"\"))","v":43.098730456554271},"DATA",43.098730456554271,{"$f":"IF(ISBLANK('FBPQ T4'!E34),\" \",'FBPQ T4'!AE34)","v":14429.7},621901.75086894119,"HV"]
[null,null,"6.6/11 kV OHL (Covered)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J35),'FBPQ C2'!J35,IF(ISNUMBER('FBPQ C2'!I35),'FBPQ C2'!I35,\"\"))","v":43.098730456554271},"DATA",43.098730456554271,{"$f":"IF(ISBLANK('FBPQ T4'!E35),\" \",'FBPQ T4'!AE35)","v":0},0,"HV"]
[null,null,"20 kV OHL (Open)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J36),'FBPQ C2'!J36,IF(ISNUMBER('FBPQ C2'!I36),'FBPQ C2'!I36,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E36),\" \",'FBPQ T4'!AE36)","v":0},0,"HV"]
[null,null,"20 kV OHL (Covered)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J37),'FBPQ C2'!J37,IF(ISNUMBER('FBPQ C2'!I37),'FBPQ C2'!I37,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E37),\" \",'FBPQ T4'!AE37)","v":0},0,"HV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J38),'FBPQ C2'!J38,IF(ISNUMBER('FBPQ C2'!I38),'FBPQ C2'!I38,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E38),\" \",'FBPQ T4'!AE38)","v":" "}," ","HV"]
[null,"Overhead lines - Support",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J39),'FBPQ C2'!J39,IF(ISNUMBER('FBPQ C2'!I39),'FBPQ C2'!I39,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E39),\" \",'FBPQ T4'!AE39)","v":" "}," ","HV"]
[null,null,"6.6/11 kV Support","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J40),'FBPQ C2'!J40,IF(ISNUMBER('FBPQ C2'!I40),'FBPQ C2'!I40,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E40),\" \",'FBPQ T4'!AE40)","v":207731},0,"HV"]
[null,null,"20 kV Support","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J41),'FBPQ C2'!J41,IF(ISNUMBER('FBPQ C2'!I41),'FBPQ C2'!I41,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E41),\" \",'FBPQ T4'!AE41)","v":0},0,"HV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J42),'FBPQ C2'!J42,IF(ISNUMBER('FBPQ C2'!I42),'FBPQ C2'!I42,\"\"))","v":""},"DATA","DATA",{"$f":"IF(ISBLANK('FBPQ T4'!E42),\" \",'FBPQ T4'!AE42)","v":" "}," ","HV"]
[null,"Underground cables (kms)",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J43),'FBPQ C2'!J43,IF(ISNUMBER('FBPQ C2'!I43),'FBPQ C2'!I43,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E43),\" \",'FBPQ T4'!AE43)","v":" "}," ","HV"]
[null,null,"6.6/11kV UG Cable","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J44),'FBPQ C2'!J44,IF(ISNUMBER('FBPQ C2'!I44),'FBPQ C2'!I44,\"\"))","v":84.544707237783456},"DATA",{"$f":"IF(ISNUMBER(E52),E52,IF(H52>0,F52,\" \"))","v":84.544707237783456},{"$f":"IF(ISBLANK('FBPQ T4'!E44),\" \",'FBPQ T4'!AE44)","v":12294.099999999999},1039401.0852520334,"HV"]
[null,null,"20kV UG Cable","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J45),'FBPQ C2'!J45,IF(ISNUMBER('FBPQ C2'!I45),'FBPQ C2'!I45,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E45),\" \",'FBPQ T4'!AE45)","v":0},0,"HV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J46),'FBPQ C2'!J46,IF(ISNUMBER('FBPQ C2'!I46),'FBPQ C2'!I46,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E46),\" \",'FBPQ T4'!AE46)","v":" "}," ","HV"]
[null,"Submarine cables (kms)",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J47),'FBPQ C2'!J47,IF(ISNUMBER('FBPQ C2'!I47),'FBPQ C2'!I47,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E47),\" \",'FBPQ T4'!AE47)","v":" "}," ","HV"]
[null,null,"HV Sub Cable","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J48),'FBPQ C2'!J48,IF(ISNUMBER('FBPQ C2'!I48),'FBPQ C2'!I48,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E48),\" \",'FBPQ T4'!AE48)","v":0},0,"HV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J49),'FBPQ C2'!J49,IF(ISNUMBER('FBPQ C2'!I49),'FBPQ C2'!I49,\"\"))","v":""},"DATA","DATA",{"$f":"IF(ISBLANK('FBPQ T4'!E49),\" \",'FBPQ T4'!AE49)","v":" "}," ","HV"]
[null,"Switchgear ",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J50),'FBPQ C2'!J50,IF(ISNUMBER('FBPQ C2'!I50),'FBPQ C2'!I50,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E50),\" \",'FBPQ T4'!AE50)","v":" "}," ","HV"]
[null,null,"6.6/11 kV CB (PM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J51),'FBPQ C2'!J51,IF(ISNUMBER('FBPQ C2'!I51),'FBPQ C2'!I51,\"\"))","v":13.984838791212301},"DATA",13.984838791212301,{"$f":"IF(ISBLANK('FBPQ T4'!E51),\" \",'FBPQ T4'!AE51)","v":1779},24879.028209566684,"EHV/HV"]
[null,null,"6.6/11 kV CB (GM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J52),'FBPQ C2'!J52,IF(ISNUMBER('FBPQ C2'!I52),'FBPQ C2'!I52,\"\"))","v":30.893780238768993},"DATA",30.893780238768993,{"$f":"IF(ISBLANK('FBPQ T4'!E52),\" \",'FBPQ T4'!AE52)","v":9875},305076.07985784381,"EHV/HV"]
[null,null,"6.6/11 kV Switch (PM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J53),'FBPQ C2'!J53,IF(ISNUMBER('FBPQ C2'!I53),'FBPQ C2'!I53,\"\"))","v":1.6527536753250902},"DATA",1.6527536753250902,{"$f":"IF(ISBLANK('FBPQ T4'!E53),\" \",'FBPQ T4'!AE53)","v":935},1545.3246864289592,"HV"]
[null,null,"6.6/11 kV Switch (GM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J54),'FBPQ C2'!J54,IF(ISNUMBER('FBPQ C2'!I54),'FBPQ C2'!I54,\"\"))","v":5.2125308221791302},"DATA",5.2125308221791302,{"$f":"IF(ISBLANK('FBPQ T4'!E54),\" \",'FBPQ T4'!AE54)","v":8754},45630.494817356106,"HV/LV"]
[null,null,"6.6/11 kV RMU","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J55),'FBPQ C2'!J55,IF(ISNUMBER('FBPQ C2'!I55),'FBPQ C2'!I55,\"\"))","v":16.400401855148971},"DATA",16.400401855148971,{"$f":"IF(ISBLANK('FBPQ T4'!E55),\" \",'FBPQ T4'!AE55)","v":13991},229458.02235538926,"HV/LV"]
[null,null,"6.6/11 kV Switchgear - Other (PM)","Each",{"$f":"E61","v":1.6527536753250902},"DATA",1.6527536753250902,{"$f":"IF(ISBLANK('FBPQ T4'!E56),\" \",'FBPQ T4'!AE56)","v":11321},18710.824358355345,"HV"]
[null,null,"6.6/11 kV Switchgear - Other (GM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J57),'FBPQ C2'!J57,IF(ISNUMBER('FBPQ C2'!I57),'FBPQ C2'!I57,\"\"))","v":""},"DATA"," ",{"$f":"IF(ISBLANK('FBPQ T4'!E57),\" \",'FBPQ T4'!AE57)","v":0}," ","HV"]
[null,null,"20 kV CB (PM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J58),'FBPQ C2'!J58,IF(ISNUMBER('FBPQ C2'!I58),'FBPQ C2'!I58,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E58),\" \",'FBPQ T4'!AE58)","v":0},0,"EHV/HV"]
[null,null,"20 kV CB (GM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J59),'FBPQ C2'!J59,IF(ISNUMBER('FBPQ C2'!I59),'FBPQ C2'!I59,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E59),\" \",'FBPQ T4'!AE59)","v":0},0,"EHV/HV"]
[null,null,"20 kV Switch (PM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J60),'FBPQ C2'!J60,IF(ISNUMBER('FBPQ C2'!I60),'FBPQ C2'!I60,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E60),\" \",'FBPQ T4'!AE60)","v":0},0,"HV"]
[null,null,"20 kV Switch (GM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J61),'FBPQ C2'!J61,IF(ISNUMBER('FBPQ C2'!I61),'FBPQ C2'!I61,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E61),\" \",'FBPQ T4'!AE61)","v":0},0,"HV/LV"]
[null,null,"20 kV RMU","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J62),'FBPQ C2'!J62,IF(ISNUMBER('FBPQ C2'!I62),'FBPQ C2'!I62,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E62),\" \",'FBPQ T4'!AE62)","v":0},0,"HV/LV"]
[null,null,"20 kV Switchgear - Other (PM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J63),'FBPQ C2'!J63,IF(ISNUMBER('FBPQ C2'!I63),'FBPQ C2'!I63,\"\"))","v":""},"DATA"," ",{"$f":"IF(ISBLANK('FBPQ T4'!E63),\" \",'FBPQ T4'!AE63)","v":0}," ","HV"]
[null,null,"20 kV Switchgear - Other (GM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J64),'FBPQ C2'!J64,IF(ISNUMBER('FBPQ C2'!I64),'FBPQ C2'!I64,\"\"))","v":""},"DATA"," ",{"$f":"IF(ISBLANK('FBPQ T4'!E64),\" \",'FBPQ T4'!AE64)","v":0}," ","HV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J65),'FBPQ C2'!J65,IF(ISNUMBER('FBPQ C2'!I65),'FBPQ C2'!I65,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E65),\" \",'FBPQ T4'!AE65)","v":" "}," "]
[null,"Transformers  ",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J66),'FBPQ C2'!J66,IF(ISNUMBER('FBPQ C2'!I66),'FBPQ C2'!I66,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E66),\" \",'FBPQ T4'!AE66)","v":" "}," "]
[null,null,"6.6/11 kV Transformer (PM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J67),'FBPQ C2'!J67,IF(ISNUMBER('FBPQ C2'!I67),'FBPQ C2'!I67,\"\"))","v":3.68691204495597},"DATA",3.68691204495597,{"$f":"IF(ISBLANK('FBPQ T4'!E67),\" \",'FBPQ T4'!AE67)","v":34852},128496.25859080546,"HV/LV"]
[null,null,"6.6/11 kV Transformer (GM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J68),'FBPQ C2'!J68,IF(ISNUMBER('FBPQ C2'!I68),'FBPQ C2'!I68,\"\"))","v":11.950680421581421},"DATA",11.950680421581421,{"$f":"IF(ISBLANK('FBPQ T4'!E68),\" \",'FBPQ T4'!AE68)","v":15750},188223.21663990736,"HV/LV"]
[null,null,"20 kV Transformer (PM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J69),'FBPQ C2'!J69,IF(ISNUMBER('FBPQ C2'!I69),'FBPQ C2'!I69,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E69),\" \",'FBPQ T4'!AE69)","v":0},0,"HV/LV"]
[null,null,"20 kV Transformer (GM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J70),'FBPQ C2'!J70,IF(ISNUMBER('FBPQ C2'!I70),'FBPQ C2'!I70,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E70),\" \",'FBPQ T4'!AE70)","v":0},0,"HV/LV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J71),'FBPQ C2'!J71,IF(ISNUMBER('FBPQ C2'!I71),'FBPQ C2'!I71,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E71),\" \",'FBPQ T4'!AE71)","v":" "}," "]
["EHV Network",null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J72),'FBPQ C2'!J72,IF(ISNUMBER('FBPQ C2'!I72),'FBPQ C2'!I72,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E72),\" \",'FBPQ T4'!AE72)","v":" "}," "]
[null,"Overhead lines",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J73),'FBPQ C2'!J73,IF(ISNUMBER('FBPQ C2'!I73),'FBPQ C2'!I73,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E73),\" \",'FBPQ T4'!AE73)","v":" "}," "]
[null,null,"33kV OHL (Pole Line)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J74),'FBPQ C2'!J74,IF(ISNUMBER('FBPQ C2'!I74),'FBPQ C2'!I74,\"\"))","v":98.402411130893839},"DATA",98.402411130893839,{"$f":"IF(ISBLANK('FBPQ T4'!E74),\" \",'FBPQ T4'!AE74)","v":1029.0000000000002},101256.08105368978,"EHV"]
[null,null,"33kV OHL (Tower Line)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J75),'FBPQ C2'!J75,IF(ISNUMBER('FBPQ C2'!I75),'FBPQ C2'!I75,\"\"))","v":156.75732935967969},"DATA",156.75732935967969,{"$f":"IF(ISBLANK('FBPQ T4'!E75),\" \",'FBPQ T4'!AE75)","v":0},0,"EHV"]
[null,null,"66kV OHL (Pole Line)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J76),'FBPQ C2'!J76,IF(ISNUMBER('FBPQ C2'!I76),'FBPQ C2'!I76,\"\"))","v":185.61695122881781},"DATA",{"$f":"IF(ISNUMBER(E84),E84,IF(H84>0,F84,\" \"))","v":185.61695122881781},{"$f":"IF(ISBLANK('FBPQ T4'!E76),\" \",'FBPQ T4'!AE76)","v":793},147194.24232445253,"EHV"]
[null,null,"66kV OHL (Tower Line)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J77),'FBPQ C2'!J77,IF(ISNUMBER('FBPQ C2'!I77),'FBPQ C2'!I77,\"\"))","v":185.61695122881781},"DATA",185.61695122881781,{"$f":"IF(ISBLANK('FBPQ T4'!E77),\" \",'FBPQ T4'!AE77)","v":0},{"$f":"IF(ISERROR(G85*H85),\" \",G85*H85)","v":0},"EHV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J78),'FBPQ C2'!J78,IF(ISNUMBER('FBPQ C2'!I78),'FBPQ C2'!I78,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E78),\" \",'FBPQ T4'!AE78)","v":" "}," "]
[null,"Overhead lines - Support",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J79),'FBPQ C2'!J79,IF(ISNUMBER('FBPQ C2'!I79),'FBPQ C2'!I79,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E79),\" \",'FBPQ T4'!AE79)","v":" "}," "]
[null,null,"33kV Pole","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J80),'FBPQ C2'!J80,IF(ISNUMBER('FBPQ C2'!I80),'FBPQ C2'!I80,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E80),\" \",'FBPQ T4'!AE80)","v":7311.4},0,"EHV"]
[null,null,"33kV Tower","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J81),'FBPQ C2'!J81,IF(ISNUMBER('FBPQ C2'!I81),'FBPQ C2'!I81,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E81),\" \",'FBPQ T4'!AE81)","v":725},0,"EHV"]
[null,null,"66kV Pole","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J82),'FBPQ C2'!J82,IF(ISNUMBER('FBPQ C2'!I82),'FBPQ C2'!I82,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E82),\" \",'FBPQ T4'!AE82)","v":8891},0,"EHV"]
[null,null,"66kV Tower","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J83),'FBPQ C2'!J83,IF(ISNUMBER('FBPQ C2'!I83),'FBPQ C2'!I83,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E83),\" \",'FBPQ T4'!AE83)","v":669},0,"EHV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J84),'FBPQ C2'!J84,IF(ISNUMBER('FBPQ C2'!I84),'FBPQ C2'!I84,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E84),\" \",'FBPQ T4'!AE84)","v":" "}," "]
[null,"Underground cables (kms)",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J85),'FBPQ C2'!J85,IF(ISNUMBER('FBPQ C2'!I85),'FBPQ C2'!I85,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E85),\" \",'FBPQ T4'!AE85)","v":" "}," "]
[null,null,"33kV UG Cable (Non Pressurised)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J86),'FBPQ C2'!J86,IF(ISNUMBER('FBPQ C2'!I86),'FBPQ C2'!I86,\"\"))","v":257.06676396210247},"DATA",257.06676396210247,{"$f":"IF(ISBLANK('FBPQ T4'!E86),\" \",'FBPQ T4'!AE86)","v":221.5},56940.288217605696,"EHV"]
[null,null,"33kV UG Cable (Oil)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J87),'FBPQ C2'!J87,IF(ISNUMBER('FBPQ C2'!I87),'FBPQ C2'!I87,\"\"))","v":257.06676396210247},"DATA",257.06676396210247,{"$f":"IF(ISBLANK('FBPQ T4'!E87),\" \",'FBPQ T4'!AE87)","v":122},31362.145203376502,"EHV"]
[null,null,"33kV UG Cable (Gas)","km",{"$f":"E95","v":257.06676396210247},"DATA",257.06676396210247,{"$f":"IF(ISBLANK('FBPQ T4'!E88),\" \",'FBPQ T4'!AE88)","v":9},2313.6008756589222,"EHV"]
[null,null,"66kV UG Cable (Non Pressurised)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J89),'FBPQ C2'!J89,IF(ISNUMBER('FBPQ C2'!I89),'FBPQ C2'!I89,\"\"))","v":1206.5101829873158},"DATA",1206.5101829873158,{"$f":"IF(ISBLANK('FBPQ T4'!E89),\" \",'FBPQ T4'!AE89)","v":8},9652.0814638985266,"EHV"]
[null,null,"66kV UG Cable (Oil)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J90),'FBPQ C2'!J90,IF(ISNUMBER('FBPQ C2'!I90),'FBPQ C2'!I90,\"\"))","v":1206.5101829873158},"DATA",1206.5101829873158,{"$f":"IF(ISBLANK('FBPQ T4'!E90),\" \",'FBPQ T4'!AE90)","v":8},9652.0814638985266,"EHV"]
[null,null,"66kV UG Cable (Gas)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J91),'FBPQ C2'!J91,IF(ISNUMBER('FBPQ C2'!I91),'FBPQ C2'!I91,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E91),\" \",'FBPQ T4'!AE91)","v":0},0,"EHV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J92),'FBPQ C2'!J92,IF(ISNUMBER('FBPQ C2'!I92),'FBPQ C2'!I92,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E92),\" \",'FBPQ T4'!AE92)","v":" "}," "]
[null,"Submarine cables (kms)",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J93),'FBPQ C2'!J93,IF(ISNUMBER('FBPQ C2'!I93),'FBPQ C2'!I93,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E93),\" \",'FBPQ T4'!AE93)","v":" "}," "]
[null,null,"EHV Sub Cable","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J94),'FBPQ C2'!J94,IF(ISNUMBER('FBPQ C2'!I94),'FBPQ C2'!I94,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E94),\" \",'FBPQ T4'!AE94)","v":0},0,"EHV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J95),'FBPQ C2'!J95,IF(ISNUMBER('FBPQ C2'!I95),'FBPQ C2'!I95,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E95),\" \",'FBPQ T4'!AE95)","v":" "}," "]
[null,"Switchgear ",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J96),'FBPQ C2'!J96,IF(ISNUMBER('FBPQ C2'!I96),'FBPQ C2'!I96,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E96),\" \",'FBPQ T4'!AE96)","v":" "}," "]
[null,null,"33 KV CB (ID)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J97),'FBPQ C2'!J97,IF(ISNUMBER('FBPQ C2'!I97),'FBPQ C2'!I97,\"\"))","v":184.98127673830817},"DATA",184.98127673830817,{"$f":"IF(ISBLANK('FBPQ T4'!E97),\" \",'FBPQ T4'!AE97)","v":88},16278.352352971118,"132kV/EHV"]
[null,null,"33 kV CB (OD)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J98),'FBPQ C2'!J98,IF(ISNUMBER('FBPQ C2'!I98),'FBPQ C2'!I98,\"\"))","v":184.98127673830817},"DATA",184.98127673830817,{"$f":"IF(ISBLANK('FBPQ T4'!E98),\" \",'FBPQ T4'!AE98)","v":305},56419.28940518399,"132kV/EHV"]
[null,null,"33 kV Switch (GM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J99),'FBPQ C2'!J99,IF(ISNUMBER('FBPQ C2'!I99),'FBPQ C2'!I99,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E99),\" \",'FBPQ T4'!AE99)","v":0},0,"132kV/EHV"]
[null,null,"33 kV Switch (PM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J100),'FBPQ C2'!J100,IF(ISNUMBER('FBPQ C2'!I100),'FBPQ C2'!I100,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E100),\" \",'FBPQ T4'!AE100)","v":0},0,"132kV/EHV"]
[null,null,"33 kV RMU","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J101),'FBPQ C2'!J101,IF(ISNUMBER('FBPQ C2'!I101),'FBPQ C2'!I101,\"\"))","v":588.50744331383407},"DATA",588.50744331383407,{"$f":"IF(ISBLANK('FBPQ T4'!E101),\" \",'FBPQ T4'!AE101)","v":0},0,"132kV/EHV"]
[null,null,"33 kV Switchgear - Other","Each",{"$f":"E106","v":184.98127673830817},"DATA",184.98127673830817,{"$f":"IF(ISBLANK('FBPQ T4'!E102),\" \",'FBPQ T4'!AE102)","v":1444},267112.96361011697,"EHV/HV"]
[null,null,"66 KV CB (ID & OD)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J103),'FBPQ C2'!J103,IF(ISNUMBER('FBPQ C2'!I103),'FBPQ C2'!I103,\"\"))","v":697.84345568149388},"DATA",697.84345568149388,{"$f":"IF(ISBLANK('FBPQ T4'!E103),\" \",'FBPQ T4'!AE103)","v":77},53733.946087475029,"132kV/EHV"]
[null,null,"66 KV Switchgear - Other","Each",{"$f":"E111","v":697.84345568149388},"DATA",697.84345568149388,{"$f":"IF(ISBLANK('FBPQ T4'!E104),\" \",'FBPQ T4'!AE104)","v":575},401259.987016859,"EHV/HV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J105),'FBPQ C2'!J105,IF(ISNUMBER('FBPQ C2'!I105),'FBPQ C2'!I105,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E105),\" \",'FBPQ T4'!AE105)","v":" "}," "]
[null,"Transformers  ",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J106),'FBPQ C2'!J106,IF(ISNUMBER('FBPQ C2'!I106),'FBPQ C2'!I106,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E106),\" \",'FBPQ T4'!AE106)","v":" "}," "]
[null,null,"33 kV Transformer (PM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J107),'FBPQ C2'!J107,IF(ISNUMBER('FBPQ C2'!I107),'FBPQ C2'!I107,\"\"))","v":532.56808814898477},"DATA",532.56808814898477,{"$f":"IF(ISBLANK('FBPQ T4'!E107),\" \",'FBPQ T4'!AE107)","v":3},1597.7042644469543,"EHV/HV"]
[null,null,"33 kV Transformer (GM)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J108),'FBPQ C2'!J108,IF(ISNUMBER('FBPQ C2'!I108),'FBPQ C2'!I108,\"\"))","v":571.97990656058312},"DATA",{"$f":"IF(ISNUMBER(E116),E116,IF(H116>0,F116,\" \"))","v":571.97990656058312},{"$f":"IF(ISBLANK('FBPQ T4'!E108),\" \",'FBPQ T4'!AE108)","v":203},116111.92103179837,"EHV/HV"]
[null,null,"33 kV AuxiliaryTransfomer","Each",{"$f":"E76","v":11.950680421581421},"DATA",11.950680421581421,{"$f":"IF(ISBLANK('FBPQ T4'!E109),\" \",'FBPQ T4'!AE109)","v":193},2306.4813213652142,"EHV/HV"]
[null,null,"66 kV Transformer","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J110),'FBPQ C2'!J110,IF(ISNUMBER('FBPQ C2'!I110),'FBPQ C2'!I110,\"\"))","v":2234.9043737338279},"DATA",2234.9043737338279,{"$f":"IF(ISBLANK('FBPQ T4'!E110),\" \",'FBPQ T4'!AE110)","v":82},183262.15864617389,"EHV/HV"]
[null,null,"66 kV AuxiliaryTransfomer","Each",{"$f":"E76","v":11.950680421581421},"DATA",11.950680421581421,{"$f":"IF(ISBLANK('FBPQ T4'!E111),\" \",'FBPQ T4'!AE111)","v":46},549.73129939274531,"EHV/HV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J112),'FBPQ C2'!J112,IF(ISNUMBER('FBPQ C2'!I112),'FBPQ C2'!I112,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E112),\" \",'FBPQ T4'!AE112)","v":" "}," "]
["132kV Network",null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J113),'FBPQ C2'!J113,IF(ISNUMBER('FBPQ C2'!I113),'FBPQ C2'!I113,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E113),\" \",'FBPQ T4'!AE113)","v":" "}," "]
[null,"Overhead lines",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J114),'FBPQ C2'!J114,IF(ISNUMBER('FBPQ C2'!I114),'FBPQ C2'!I114,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E114),\" \",'FBPQ T4'!AE114)","v":" "}," "]
[null,null,"132kV OHL Conductor (Pole Line)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J115),'FBPQ C2'!J115,IF(ISNUMBER('FBPQ C2'!I115),'FBPQ C2'!I115,\"\"))","v":714.87953202715244},"DATA",714.87953202715244,{"$f":"IF(ISBLANK('FBPQ T4'!E115),\" \",'FBPQ T4'!AE115)","v":0},0,"132kV"]
[null,null,"132kV OHL Conductor (Tower Line)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J116),'FBPQ C2'!J116,IF(ISNUMBER('FBPQ C2'!I116),'FBPQ C2'!I116,\"\"))","v":1228.5045203589498},"DATA",1228.5045203589498,{"$f":"IF(ISBLANK('FBPQ T4'!E116),\" \",'FBPQ T4'!AE116)","v":1368},1680594.1838510432,"132kV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J117),'FBPQ C2'!J117,IF(ISNUMBER('FBPQ C2'!I117),'FBPQ C2'!I117,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E117),\" \",'FBPQ T4'!AE117)","v":" "}," "]
[null,"Overhead lines - Support",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J118),'FBPQ C2'!J118,IF(ISNUMBER('FBPQ C2'!I118),'FBPQ C2'!I118,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E118),\" \",'FBPQ T4'!AE118)","v":" "}," "]
[null,null,"132kV Pole","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J119),'FBPQ C2'!J119,IF(ISNUMBER('FBPQ C2'!I119),'FBPQ C2'!I119,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E119),\" \",'FBPQ T4'!AE119)","v":843},0,"132kV"]
[null,null,"132kV Tower","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J120),'FBPQ C2'!J120,IF(ISNUMBER('FBPQ C2'!I120),'FBPQ C2'!I120,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E120),\" \",'FBPQ T4'!AE120)","v":2776},0,"132kV"]
[null,null,"132kV Fittings (Tower Line)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J121),'FBPQ C2'!J121,IF(ISNUMBER('FBPQ C2'!I121),'FBPQ C2'!I121,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E121),\" \",'FBPQ T4'!AE121)","v":4787},0,"132kV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J122),'FBPQ C2'!J122,IF(ISNUMBER('FBPQ C2'!I122),'FBPQ C2'!I122,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E122),\" \",'FBPQ T4'!AE122)","v":" "}," "]
[null,"Underground cables (kms)",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J123),'FBPQ C2'!J123,IF(ISNUMBER('FBPQ C2'!I123),'FBPQ C2'!I123,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E123),\" \",'FBPQ T4'!AE123)","v":" "}," "]
[null,null,"132kV UG Cable (Non Pressurised)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J124),'FBPQ C2'!J124,IF(ISNUMBER('FBPQ C2'!I124),'FBPQ C2'!I124,\"\"))","v":1239.5652564938177},"DATA",1239.5652564938177,{"$f":"IF(ISBLANK('FBPQ T4'!E124),\" \",'FBPQ T4'!AE124)","v":43},53301.306029234162,"132kV"]
[null,null,"132kV UG Cable (Oil)","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J125),'FBPQ C2'!J125,IF(ISNUMBER('FBPQ C2'!I125),'FBPQ C2'!I125,\"\"))","v":1239.5652564938177},"DATA",1239.5652564938177,{"$f":"IF(ISBLANK('FBPQ T4'!E125),\" \",'FBPQ T4'!AE125)","v":251},311130.87937994825,"132kV"]
[null,null,"132kV UG Cable (Gas)","km",{"$f":"E133","v":1239.5652564938177},"DATA",1239.5652564938177,{"$f":"IF(ISBLANK('FBPQ T4'!E126),\" \",'FBPQ T4'!AE126)","v":16},19833.044103901084,"132kV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J127),'FBPQ C2'!J127,IF(ISNUMBER('FBPQ C2'!I127),'FBPQ C2'!I127,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E127),\" \",'FBPQ T4'!AE127)","v":" "}," "]
[null,"Submarine cables (kms)",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J128),'FBPQ C2'!J128,IF(ISNUMBER('FBPQ C2'!I128),'FBPQ C2'!I128,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E128),\" \",'FBPQ T4'!AE128)","v":" "}," "]
[null,null,"132 kV Sub Cable","km",{"$f":"IF(ISNUMBER('FBPQ C2'!J129),'FBPQ C2'!J129,IF(ISNUMBER('FBPQ C2'!I129),'FBPQ C2'!I129,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E129),\" \",'FBPQ T4'!AE129)","v":0},0,"132kV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J130),'FBPQ C2'!J130,IF(ISNUMBER('FBPQ C2'!I130),'FBPQ C2'!I130,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E130),\" \",'FBPQ T4'!AE130)","v":" "}," "]
[null,"Switchgear ",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J131),'FBPQ C2'!J131,IF(ISNUMBER('FBPQ C2'!I131),'FBPQ C2'!I131,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E131),\" \",'FBPQ T4'!AE131)","v":" "}," "]
[null,null,"132 kV CB (ID & OD)","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J132),'FBPQ C2'!J132,IF(ISNUMBER('FBPQ C2'!I132),'FBPQ C2'!I132,\"\"))","v":1106.4550181810969},"DATA",1106.4550181810969,{"$f":"IF(ISBLANK('FBPQ T4'!E132),\" \",'FBPQ T4'!AE132)","v":295},326404.23036342359,"132kV"]
[null,null,"132 kV Switchgear (other)","Each",{"$f":"E140","v":1106.4550181810969},"DATA",1106.4550181810969,{"$f":"IF(ISBLANK('FBPQ T4'!E133),\" \",'FBPQ T4'!AE133)","v":1704},1885399.3509805892,"132kV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J134),'FBPQ C2'!J134,IF(ISNUMBER('FBPQ C2'!I134),'FBPQ C2'!I134,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E134),\" \",'FBPQ T4'!AE134)","v":" "}," "]
[null,"Transformers  ",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J135),'FBPQ C2'!J135,IF(ISNUMBER('FBPQ C2'!I135),'FBPQ C2'!I135,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E135),\" \",'FBPQ T4'!AE135)","v":" "}," "]
[null,null,"132 kV Transformer","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J136),'FBPQ C2'!J136,IF(ISNUMBER('FBPQ C2'!I136),'FBPQ C2'!I136,\"\"))","v":2234.9043737338279},"DATA",2234.9043737338279,{"$f":"IF(ISBLANK('FBPQ T4'!E136),\" \",'FBPQ T4'!AE136)","v":249},556491.18905972317,"132kV/EHV"]
[null,null,"132 kV AuxiliaryTransfomer","Each",{"$f":"E76","v":11.950680421581421},"DATA",11.950680421581421,{"$f":"IF(ISBLANK('FBPQ T4'!E137),\" \",'FBPQ T4'!AE137)","v":356},4254.4422300829856,"132kV/EHV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J138),'FBPQ C2'!J138,IF(ISNUMBER('FBPQ C2'!I138),'FBPQ C2'!I138,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E138),\" \",'FBPQ T4'!AE138)","v":" "}," "]
["Tele-control / SCADA",null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J139),'FBPQ C2'!J139,IF(ISNUMBER('FBPQ C2'!I139),'FBPQ C2'!I139,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E139),\" \",'FBPQ T4'!AE139)","v":" "}," "]
[null,"Primary substation",null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J140),'FBPQ C2'!J140,IF(ISNUMBER('FBPQ C2'!I140),'FBPQ C2'!I140,\"\"))","v":""},null,{"$f":"IF(ISNUMBER(E148),E148,IF(H148>0,F148,\" \"))","v":0},{"$f":"IF(ISBLANK('FBPQ T4'!E140),\" \",'FBPQ T4'!AE140)","v":" "}," "]
[null,null,"132 kV/EHV RTU (PM)","Each",62.645000000000003,"DATA",62.645000000000003,{"$f":"IF(ISBLANK('FBPQ T4'!E141),\" \",'FBPQ T4'!AE141)","v":2},{"$f":"IF(ISERROR(G149*H149),\" \",G149*H149)","v":125.29},"EHV/HV"]
[null,null,"132 kV/EHV RTU (GM)","Each",62.645000000000003,"DATA",62.645000000000003,{"$f":"IF(ISBLANK('FBPQ T4'!E142),\" \",'FBPQ T4'!AE142)","v":262},16412.990000000002,"EHV/HV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('[10]FBPQ C2'!K143),'[10]FBPQ C2'!K143,IF(ISNUMBER('[10]FBPQ C2'!I143),'[10]FBPQ C2'!I143,\"\"))","v":0},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E143),\" \",'FBPQ T4'!AE143)","v":" "}," "]
[null,"Secondary substation",null,null,{"$f":"IF(ISNUMBER('[10]FBPQ C2'!K144),'[10]FBPQ C2'!K144,IF(ISNUMBER('[10]FBPQ C2'!I144),'[10]FBPQ C2'!I144,\"\"))","v":0},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E144),\" \",'FBPQ T4'!AE144)","v":" "}," "]
[null,null,"HV RTU (PM)","Each",62.645000000000003,"DATA",62.645000000000003,{"$f":"IF(ISBLANK('FBPQ T4'!E145),\" \",'FBPQ T4'!AE145)","v":1773},{"$f":"IF(ISERROR(G153*H153),\" \",G153*H153)","v":111069.58500000001},"HV/LV"]
[null,null,"HV RTU (GM)","Each",62.645000000000003,"DATA",62.645000000000003,{"$f":"IF(ISBLANK('FBPQ T4'!E146),\" \",'FBPQ T4'!AE146)","v":1264},79183.28,"HV/LV"]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J147),'FBPQ C2'!J147,IF(ISNUMBER('FBPQ C2'!I147),'FBPQ C2'!I147,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E147),\" \",'FBPQ T4'!AE147)","v":" "}," "]
[null,null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J148),'FBPQ C2'!J148,IF(ISNUMBER('FBPQ C2'!I148),'FBPQ C2'!I148,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E148),\" \",'FBPQ T4'!AE148)","v":" "}," "]
["HV network switchgear",null,null,null,{"$f":"IF(ISNUMBER('FBPQ C2'!J149),'FBPQ C2'!J149,IF(ISNUMBER('FBPQ C2'!I149),'FBPQ C2'!I149,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E149),\" \",'FBPQ T4'!AE149)","v":" "}," "]
[null,null,"6.6/11 kV CB (GM)",null,{"$f":"IF(ISNUMBER('FBPQ C2'!J150),'FBPQ C2'!J150,IF(ISNUMBER('FBPQ C2'!I150),'FBPQ C2'!I150,\"\"))","v":""},null,0,{"$f":"IF(ISBLANK('FBPQ T4'!E150),\" \",'FBPQ T4'!AE150)","v":" "}," "]
[null,null,"Primary","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J151),'FBPQ C2'!J151,IF(ISNUMBER('FBPQ C2'!I151),'FBPQ C2'!I151,\"\"))","v":30.893780238768993},"DATA",30.893780238768993,{"$f":"IF(ISBLANK('FBPQ T4'!E151),\" \",'FBPQ T4'!AE151)","v":" "}," "]
[null,null,"Distribution","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J152),'FBPQ C2'!J152,IF(ISNUMBER('FBPQ C2'!I152),'FBPQ C2'!I152,\"\"))","v":7.882363682319661},"DATA",7.882363682319661,{"$f":"IF(ISBLANK('FBPQ T4'!E152),\" \",'FBPQ T4'!AE152)","v":" "}," "]
[null,null,"20 kV Switch (GM)",null,{"$f":"IF(ISNUMBER('FBPQ C2'!J153),'FBPQ C2'!J153,IF(ISNUMBER('FBPQ C2'!I153),'FBPQ C2'!I153,\"\"))","v":""},"DATA","DATA",{"$f":"IF(ISBLANK('FBPQ T4'!E153),\" \",'FBPQ T4'!AE153)","v":" "}," "]
[null,null,"Primary","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J154),'FBPQ C2'!J154,IF(ISNUMBER('FBPQ C2'!I154),'FBPQ C2'!I154,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E154),\" \",'FBPQ T4'!AE154)","v":" "}," "]
[null,null,"Distribution","Each",{"$f":"IF(ISNUMBER('FBPQ C2'!J155),'FBPQ C2'!J155,IF(ISNUMBER('FBPQ C2'!I155),'FBPQ C2'!I155,\"\"))","v":0},"DATA",0,{"$f":"IF(ISBLANK('FBPQ T4'!E155),\" \",'FBPQ T4'!AE155)","v":" "}," "]
[null,null,null,null,null,null,null,"Total MEAV",{"$f":"SUM(I18:I163)","v":16745071.574087301}]

{"sheet":"Calc-Net capex","index":9,"n_rows":55,"n_cols":15,"rows_kept":55,"cut":false,"hidden":false,"merged":[[46,7,46,8],[36,7,36,8],[2,9,2,11],[2,13,2,15],[3,9,3,11],[3,13,3,15],[45,7,45,8],[2,5,2,7],[3,5,3,7],[16,7,16,8],[15,7,15,8],[24,4,24,5],[35,7,35,8],[3,1,3,3],[2,1,2,3],[15,4,15,5],[15,1,15,2],[16,1,16,2],[24,1,24,2],[16,4,16,5],[45,1,45,2],[46,1,46,2],[25,1,25,2],[36,4,36,5],[46,4,46,5],[35,1,35,2],[35,4,35,5],[36,1,36,2],[25,4,25,5],[45,4,45,5]]}
["Total Net Capex",null,null,null,null,"Index"]
[]
[null,"Total Net Capex 2005/06 -2014/15 LV, HV, EHV, 132kV split",null,null,null,"Total Net Capex 2005/06 -2014/15 LV, LV/HV, HV, EHV, 132kV split",null,null,null,"IP Appendix 6 Table 5 Reductions to EHV",null,null,null,"IP Appendix 7 Reductions to EHV"]
[null,"Sum connecions/reinforcement/replacement capex -see below",null,null,null,"Sum connecions/reinforcement/replacement capex -see below",null,null,null,"Appendix 6 Table 5 EHV & 132",null,null,null,"Appendix 7 Table 18"]
[null,null,"£m","% of Total",null,null,"£m","% of Total",null,"EHV",null,{"$f":"K5*(F21/(F21+F22))","v":0},null,null,"£m"]
[null,"LV",{"$f":"C19+F19+I19+C28+F28-O6","v":166.8798952627794},{"$f":"C6/SUM($C$6:$C$9)","v":0.17584193572888193},null,"LV",{"$f":"+C39+F39+I39+C49+F49-O6","v":166.8798952627794},{"$f":"G6/SUM($G$6:$G$10)","v":0.1758419357288819},null,"132kV",null,{"$f":"K5*(F22/(F21+F22))","v":0},null,"LV"]
[null,"HV",{"$f":"C20+F20+I20+C29+F29-O7-O8","v":246.04522019087011},{"$f":"C7/SUM($C$6:$C$9)","v":0.25925871853570936},null,"LV/HV",{"$f":"+C40+F40+I40+C50+F50-O7","v":50.467924447354974},{"$f":"G7/SUM($G$6:$G$10)","v":5.3178230445720967E-2},null,null,null,null,null,"LV/HV"]
[null,"EHV",{"$f":"C21+F21+I21+C30+F30-L5-O9","v":187.02448249234808},{"$f":"C8/SUM($C$6:$C$9)","v":0.19706835852432295},null,"HV",{"$f":"+C41+F41+I41+C51+F51-O8","v":195.57729574351521},{"$f":"G8/SUM($G$6:$G$10)","v":0.20608048808998844},null,null,null,null,null,"HV"]
[null,"132 kV",{"$f":"C22+F22+I22+C31+F31-L6-O10","v":349.08394499724864},{"$f":"C9/SUM($C$6:$C$9)","v":0.36783098721108581},null,"EHV",{"$f":"+C42+F42+I42+C52+F52-L5-O9","v":187.02448249234808},{"$f":"G9/SUM($G$6:$G$10)","v":0.19706835852432295},null,null,null,null,null,"EHV"]
[null,null,null,null,null,"132 kV",{"$f":"+C43+F43+I43+C53+F53-L6-O10","v":349.08394499724864},{"$f":"G10/SUM($G$6:$G$10)","v":0.36783098721108576},null,null,null,null,null,"132 kV"]
[]
[]
["Connection/Reinforcement/Replacement Capex LV, HV, EHV, 132kV split"]
[]
[]
[null,"Connections Capex 2005/06 -2014/15 (£m)",null,null,"General reinforcement Capex 2005/06 -2014/15 (£m)",null,null,"Fault reinforcement Capex 2005/06 -2014/15 (£m)"]
[null,"Connections spend minus customer contributions (from FBPQ LR1)",null,null,"(from FBPQ LR4)",null,null,"(from FBPQ LR6)"]
[]
["c32","LV",29.935989292598578,null,"LV",{"$f":"SUM('FBPQ LR4'!D11:M11)","v":10.756772462044905},null,"LV",{"$f":"SUM('FBPQ LR6'!C28:L28)","v":0}]
["c33","HV",9.6943771821511007,null,"HV",{"$f":"SUM('FBPQ LR4'!D12:M12)","v":30.575324895711095},null,"HV",{"$f":"SUM('FBPQ LR6'!C29:L29)","v":0}]
["c34","EHV",0,null,"EHV",{"$f":"SUM('FBPQ LR4'!D13:M13)","v":108.75996228110381},null,"EHV",{"$f":"SUM('FBPQ LR6'!C30:L30)","v":4.2186510156450376}]
["c35","132 kV",0,null,"132 kV",{"$f":"SUM('FBPQ LR4'!D14:M14)","v":99.474026522812494},null,"132 kV",{"$f":"SUM('FBPQ LR6'!C31:L31)","v":15.055225002265182}]
[]
[]
[null,"Replacement Capex 2005/06 -2014/15 (£m)",null,null,"ESQCR 2005/06 -2014/15 (£m)"]
[null," (from FBPQ NL1)",null,null,"(from FBPQ NL9)"]
[]
[null,"LV",{"$f":"SUM('FBPQ NL1 0309'!D10:M16)","v":126.18713350813591},null,"LV",{"$f":"SUM('NL9 - Legal & Safety'!D33:M33,'NL9 - Legal & Safety'!D42:M42)","v":0}]
[null,"HV",{"$f":"SUM('FBPQ NL1 0309'!D17:M22)","v":205.77551811300791},null,"HV",{"$f":"SUM('NL9 - Legal & Safety'!D34:M34,'NL9 - Legal & Safety'!D43:M43)","v":0}]
[null,"EHV",{"$f":"SUM('FBPQ NL1 0309'!D23:M28)","v":74.045869195599238},null,"EHV",{"$f":"SUM('NL9 - Legal & Safety'!D35:M35,'NL9 - Legal & Safety'!D44:M44)","v":0}]
[null,"132 kV",{"$f":"SUM('FBPQ NL1 0309'!D29:M34)","v":234.55469347217092},null,"132 kV",{"$f":"SUM('NL9 - Legal & Safety'!D36:M36,'NL9 - Legal & Safety'!D45:M45)","v":0}]
[]
["Connection/Reinforcement/Replacement Capex LV, LV/HV, HV, EHV, 132kV split"]
[]
[]
[null,"Connections Capex 2005/06 -2014/15 (£m)",null,null,"General reinforcement Capex 2005/06 -2014/15 (£m)",null,null,"Fault reinforcement Capex 2005/06 -2014/15 (£m)"]
[null,"Connections spend minus customer contributions (from FBPQ LR1)",null,null,"(from FBPQ LR4)",null,null,"(from FBPQ LR6)"]
[]
["c20","LV",29.935989292598578,null,"LV",{"$f":"SUM('FBPQ LR4'!D11:M11)","v":10.756772462044905},null,"LV",{"$f":"SUM('FBPQ LR6'!C28:L28)","v":0}]
["c21","LV/HV",2.3811685205236506,"allocated in proportion to repex","LV/HV",{"$f":"SUM('FBPQ LR4'!D12:M12)*(C55)","v":7.5100235712404491},"allocated in proportion to repex","LV/HV",{"$f":"SUM('FBPQ LR6'!C29:L29)*(C55)","v":0},"allocated in proportion to repex"]
["c22","HV",7.3132086616274492,null,"HV",{"$f":"SUM('FBPQ LR4'!D12:M12)*(1-C55)","v":23.065301324470646},null,"HV",{"$f":"SUM('FBPQ LR6'!C29:L29)*(1-C55)","v":0}]
["c23","EHV",0,null,"EHV",{"$f":"SUM('FBPQ LR4'!D13:M13)","v":108.75996228110381},null,"EHV",{"$f":"SUM('FBPQ LR6'!C30:L30)","v":4.2186510156450376}]
["c24","132 kV",0,null,"132 kV",{"$f":"SUM('FBPQ LR4'!D14:M14)","v":99.474026522812494},null,"132 kV",{"$f":"SUM('FBPQ LR6'!C31:L31)","v":15.055225002265182}]
[]
[]
[null,"Replacement Capex 2005/06 -2014/15 (£m)",null,null,"ESQCR 2005/06 -2014/15 (£m)",null,null,"ESQCR 2005/06 -2014/15 (£m)"]
[null," (from FBPQ NL1)",null,null,"(from FBPQ NL9)",null,null,"NL1 + NL9"]
[]
[null,"LV",{"$f":"SUM('FBPQ NL1 0309'!D10:M16)","v":126.18713350813591},null,"LV",{"$f":"SUM('NL9 - Legal & Safety'!D33:M33,'NL9 - Legal & Safety'!D42:M42)","v":0},null,"LV",{"$f":"F49+C49","v":126.18713350813591}]
[null,"LV/HV",{"$f":"SUM('FBPQ NL1 0309'!D21:M22)","v":40.57673235559087},"HV/LV sub/trans costs","LV/HV",{"$f":"SUM('NL9 - Legal & Safety'!D34:M34,'NL9 - Legal & Safety'!D43:M43)*C55","v":0},null,"LV/HV",{"$f":"F50+C50","v":40.57673235559087}]
[null,"HV",{"$f":"SUM('FBPQ NL1 0309'!D17:M20)","v":165.19878575741711},null,"HV",{"$f":"SUM('NL9 - Legal & Safety'!D34:M34,'NL9 - Legal & Safety'!D43:M43)*(1-C55)","v":0},null,"HV",{"$f":"F51+C51","v":165.19878575741711}]
[null,"EHV",{"$f":"SUM('FBPQ NL1 0309'!D23:M28)","v":74.045869195599238},null,"EHV",{"$f":"SUM('NL9 - Legal & Safety'!D35:M35,'NL9 - Legal & Safety'!D44:M44)","v":0},null,"EHV",{"$f":"F52+C52","v":74.045869195599238}]
[null,"132 kV",{"$f":"SUM('FBPQ NL1 0309'!D29:M34)","v":234.55469347217092},null,"132 kV",{"$f":"SUM('NL9 - Legal & Safety'!D36:M36,'NL9 - Legal & Safety'!D45:M45)","v":0},null,"132 kV",{"$f":"F53+C53","v":234.55469347217092}]
[]
[null,"LV/HV/(LV/HV+HV) %",{"$f":"C50/C51","v":0.24562367192683227}]

{"sheet":"Summary of revenue","index":10,"n_rows":49,"n_cols":12,"rows_kept":49,"cut":false,"hidden":false,"merged":[[29,1,29,4],[10,1,10,4],[11,1,11,4],[12,1,12,4],[13,1,13,4],[15,1,15,4],[17,1,17,4],[18,1,18,4],[20,1,20,4],[25,1,25,4],[26,1,26,4],[27,1,27,4],[46,1,46,4],[31,1,31,4],[33,1,33,4],[37,1,37,4],[38,1,38,4],[44,1,44,4],[45,1,45,4]]}
[null,null,"Summary of Revenue",null,null,null,null,null,null,"Index"]
[]
[]
[]
[]
[]
[]
["Allowed Demand Revenue (ADt)",null,null,null,null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10"]
[null,null,null,null,null,null,null,16,17,18,19,20]
[]
[null,"Base Demand Revenue  (BRt)",null,null,null,"£m",null,255.06868,262.01640500000002,274.19156400000003]
[null,"Pass through Items (PTt)",null,null,null,"£m",null,-1.912898,-3.5919140000000001,-3.6379950000000001]
[null,"Incentive Revenue (Ipt)",null,null,null,"£m",null,4.5676199999999998,8.8523080000000007,7.1725950000000003]
[null,"Correction Factor (KDt)",null,null,null,"£m",null,-8.2132999999999998E-2,-11.672268000000001,-1.294306]
[]
[null,"Allowed Demand Revenue (Adt)",null,null,null,"£m",null,257.80553500000002,278.94906700000001,279.02046999999999]
[]
[null,"Regulated Demand Revenue (RDt)",null,null,null,"£m",null,246.67,277.74,278.05]
[null,"Net Movement on Revenue Provisions",null,null,null,"£m",null,2.5299999999999998,-2.64,-4.83]
[]
[null,"Over/Under Recovery",null,null,null,"£m",null,-11.135535000000001,-1.2090669999999999,-0.97047000000000005]
[]
[]
["Allowed Network Generation Revenue (AGt)"]
[]
[null,"Incentivised Generation (IGt)",null,null,null,"£m",null,0,2.5645000000000001E-2,6.1178000000000003E-2]
[null,"Registered Power Zones (RPZt)",null,null,null,"£m",null,0,0,0]
[null,"Correction Factor (KGt)",null,null,null,"£m",null,0,0,4.6620000000000003E-3]
[]
[null,"Allowed Network Generation Revenue (AGt)",null,null,null,"£m",null,0,2.5645000000000001E-2,5.6515999999999997E-2]
[]
[null,"Network Generation Revenue (RGt)",null,null,null,"£m",null,0,0.03,7.0000000000000007E-2]
[]
[null,"Over/Under Recovery",null,null,null,"£m",null,0,4.3550000000000004E-3,1.3483999999999999E-2]
[]
[]
["Metering Revenue"]
[null,"Legacy Basic Meter Asset Provision Revenue",null,null,null,"£m",null,6.5,8.2200000000000006,7.78]
[null,"Basic Meter Operation Revenue",null,null,null,"£m",null,4.735894,3.994996,0]
[]
[null,null,null,null,null,null,null,11.235894,12.214995999999999,7.78]
[]
[]
["Excluded Services and Revenue Outside of Price Control"]
[null,"Excluded Services",null,null,null,"£m",null,20.66,51.69,74.23]
[null,"Revenue Outside of Price Control",null,null,null,"£m",null,6.63,7.24,7.96]
[null,"De-Minimis Revenue",null,null,null,"£m",null,0,0.4,0.65]
[]
[null,null,null,null,null,null,null,27.29,59.33,82.84]

{"sheet":"Allowed revenue -DPCR4","index":11,"n_rows":33,"n_cols":10,"rows_kept":33,"cut":false,"hidden":false,"merged":[]}
[null,null,"2004/05","2005/6","2006/7","2007/8","2008/9","2009/10",null,"Index"]
[null,null,"(£M)","(£M)","(£M)","(£M)","(£M)","(£M)"]
[1,"Opening asset value",null,964.7,1013.2,1057.4000000000001,1095.0999999999999,1126.5," "]
[2,"Total capex",null,120.8,120.4,120,119.5,119.3," "]
[3,"Depreciation",null,-72.3,-76.2,-82.2,-88.2,-94.2," "]
[4,"Closing asset value",null,1013.2,1057.4000000000001,1095.0999999999999,1126.5,1151.5999999999999," "]
[5,"Present value of opening / closing RAV",null,964.7,null,null,null,879.3]
[6,"5 Year movement in closing RAV",null,null,null,null,null,85.4]
["ALLOWED ITEMS"]
[7,"Operating costs (excluding pensions)",null,72.5,70,68,66.599999999999994,66," "]
[8,"Capital expenditure (excluding pensions)",null,111.5,111.1,110.7,110.2,110," "]
[9,"Pensions allowance",null,16.2,16.2,16.2,16.2,16.2," "]
[10,"Tax allowance",null,25.9,26.7,26.9,27,26.7," "]
[11,"Capex incentive scheme",null,1.2,0.9,1,0.5,0.6," "]
[12,"Sliding scale additional income",null,1.4,1.5,1.5,1.6,1.6," "]
[13,"Opex incentive / Other adjustments",null,"-","-","-","-","-"," "]
[14,"Quality award",null,"-","-","-","-","-"," "]
[15,"DPCR3 costs",null,0.9,"-","-","-","-"," "]
[16,"Total allowed items",null,229.6,226.4,224.3,222.1,221.1," "]
[17,"Present value of allowed items",null,223.5,208.8,196,183.9,173.5," "]
[18,"5 year movement in closing RAV",null,null,null,null,null,85.4]
[19,"TOTAL PRESENT VALUE OVER 5 YEARS",null,null,null,null,null,1071.0999999999999]
["REVENUE"]
[20,"Revenue index",null,1,1.0069999999999999,1.0149999999999999,1.022,1.0289999999999999," "]
[21,"Discounted revenue index",null,0.97299999999999998,0.92900000000000005,0.88700000000000001,0.84599999999999997,0.80700000000000005," "]
[22,"Price control revenue",246.1,238.7,240.5,242.3,244,245.7," "]
[23,"Excluded service revenue",null,2.4,2.4,2.4,2.4,2.4," "]
[24,"Total revenue",null,241.1,242.9,244.7,246.4,248.1," "]
[25,"Present value of total revenue",null,234.7,224,213.8,204,194.6," "]
[26,"TOTAL PRESENT VALUE OVER 5 YEARS",null,null,null,null,null,1071.0999999999999]
[]
["Take these data from the February 2005 Ofgem document (link below), not the November 2004 final proposals."]
["http://www.ofgem.gov.uk/Markets/RetMkts/Metrng/Metering/Documents1/9745-5405.pdf"]

{"sheet":"FBPQ T4","index":12,"n_rows":146,"n_cols":31,"rows_kept":146,"cut":false,"hidden":false,"merged":[[6,16,6,20],[6,21,6,25],[6,1,8,4],[6,5,8,5],[7,28,7,29],[6,26,6,30],[7,6,7,7],[7,8,7,9],[7,11,7,12],[7,13,7,14],[7,16,7,17],[7,18,7,19],[7,21,7,22],[7,23,7,24],[7,26,7,27],[6,6,6,10],[6,11,6,15]]}
["Main Forecast Business Plan DPCR5",null,null,null,null," ","Index",null," ",null," "," ",null," ",null," "," ",null," ",null," "," ",null," ",null," "," ",null," ",null," "]
[]
["T4 - Volume Summary"]
[]
[null,"Total Asset Register Movement"]
[]
[null,"Asset categories",null,null,null,"Opening Balance DCPR4","2005/06",null,null,null,null,"2006/07",null,null,null,null,"2007/08",null,null,null,null,"2008/09",null,null,null,null,"2009/10"]
[null,null,null,null,null,null,"Assets removed ",null,"Assets Installed",null,"Closing Balance","Assets removed ",null,"Assets Installed",null,"Closing Balance","Assets removed ",null,"Assets Installed",null,"Closing Balance","Assets removed ",null,"Assets Installed",null,"Closing Balance","Assets removed ",null,"Assets Installed",null,"Closing Balance DPCR4"]
[null,null,null,null,null,null,"LRE","NLRE","LRE","NLRE","2005/06","LRE","NLRE","LRE","NLRE","2006/07","LRE","NLRE","LRE","NLRE","2007/08","LRE","NLRE","LRE","NLRE","2008/09","LRE","NLRE","LRE","NLRE","2009/10"]
[null,null,"LV Network"]
[null,null,null,"Overhead lines - Conductor"]
[null,null,null,null,"LV Main (OHL)",5988,14,4,215,2,6187,30,6,10,3,6164,51,4,9,2,6120,47.7,36.300000000000004,8.4,14.4,6058.8,39.6,72.099999999999994,7.2,43.7,5998]
[null,null,null,null,"LV Service (OHL)",236522,0,677,56,95,235996,0,704,23,460,235775,0,827,1017,1434,237399,0,2681,945,820,236483,0,2454,814,1457,236300]
[]
[null,null,null,"Overhead lines - Support"]
[null,null,null,null,"LV Support",199126,134,0,61,0,199053,781,0,54,0,198326,1955,1092,914,1092,197285,1828,616,852,176,195869,1517,1167,719,593,194497]
[]
[null,null,null,"Underground cables"]
[null,null,null,null,"LV Main (UG Consac)",4061,0,6,0,0,4055,0,24,0,0,4031,0,37,0,0,3994,0,43,0,0,3951,0,48,0,0,3903]
[null,null,null,null,"LV Main (UG Plastic)",3759.5,0,0,648,24,4431.5,0,0,50,286,4767.5,0,0,301.39999999999998,56,5124.8999999999996,0,1.3,281.89999999999998,73,5478.4999999999991,0,0.6,233.7,71.099999999999994,5782.6999999999989]
[null,null,null,null,"LV Main (UG Paper)",16295,0,0,0,0,16295,0,30,0,0,16265,0,44,0,0,16221,0,3.9,0,0,16217.1,0,1.5999999999999999,0,0,16215.5]
[null,null,null,null,"LV Service (UG)",2131108,55,680,27797,680,2158850,0,1068,23048,1486,2182316,0,10699,18463,1653,2191733,0,107,17278,1811,2210715,0,40,14289,1032,2225996]
[]
[null,null,null,"Switchgear "]
[null,null,null,null,"LV Pillar (ID)",4508,43,13,230,13,4695,0,73,417,81,5120,0,65,134,87,5276,0,253,125,138,5286,0,278,105,125,5238]
[null,null,null,null,"LV Pillar (OD)",10805,0,0,0,0,10805,111,0,0,0,10694,201,54,100,54,10593,188,0,94,0,10499,156,0,77,0,10420]
[null,null,null,null,"LV Board (WM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"LV UGB",20522,0,275,341,281,20869,0,576,124,465,20882,0,713,155,582,20906,0,295,145,398.7,21154.7,0,296,121,418.5,21398.2]
[null,null,null,null,"LV Fuses (PM)",34104,0,0,31,0,34135,0,63,429,0,34501,590,117,444,117,34355,552,0,415,0,34218,458,0,344,0,34104]
[null,null,null,null,"LV Fuses (TM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,"HV network"]
[null,null,null,"Overhead lines - Conductor"]
[null,null,null,null,"6.6/11 kV OHL (Open)",14594,2,14,13,14,14605,68,7,43,7,14580,46,252,4,252,14538,17.3,250.6,1.2,220.1,14491.4,30.9,270,1.2,238,14429.7]
[null,null,null,null,"6.6/11 kV OHL (Covered)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"20 kV OHL (Open)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"20 kV OHL (Covered)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,null,"Overhead lines - Support"]
[null,null,null,null,"6.6/11 kV Support",209466,23,137,148,137,209591,808,94,573,94,209356,1577,660,991,660,208770,592,1779.2,402,1474.8,208275.59999999998,1060,2050.3000000000002,835,1730.7,207731]
[null,null,null,null,"20 kV Support",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,null,"Underground cables (kms)"]
[null,null,null,null,"6.6/11kV UG Cable",11712,0,1,91,19,11821,0,73,134,76,11958,0,5,89,43,12085,0,10.7,32.799999999999997,77.099999999999994,12184.199999999999,0,6.1,64.8,51.2,12294.099999999999]
[null,null,null,null,"20kV UG Cable",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,null,"Submarine cables (kms)"]
[null,null,null,null,"HV Sub Cable",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,null,"Switchgear "]
[null,null,null,null,"6.6/11 kV CB (PM)",1660,0,28,0,34,1666,0,4,1,44,1707,0,39,0,60,1728,0,0,0,26,1754,0,0,0,25,1779]
[null,null,null,null,"6.6/11 kV CB (GM)",10293,0,1,37,0,10329,0,228,3,11,10115,0,463,0,177,9829,0,8,0,36,9857,0,12,0,30,9875]
[null,null,null,null,"6.6/11 kV Switch (PM)",773,0,0,0,2,775,0,13,0,21,783,0,0,0,103,886,0,382,0,412,916,0,235,0,254,935]
[null,null,null,null,"6.6/11 kV Switch (GM)",10115,0,137,1,169,10148,0,353,1,0,9796,0,629,0,1,9168,0,232,0,1,8937,0,184,0,1,8754]
[null,null,null,null,"6.6/11 kV RMU",11364,16,6,355,6,11703,0,113,357,343,12290,0,236,590,140,12784,0,63,254,268,13243,0,60,576,232,13991]
[null,null,null,null,"6.6/11 kV Switchgear - Other (PM)",11757,0,209,0,249,11797,58,264,0,264,11739,230,360,33,360,11542,86,0,10,0,11466,155,0,10,0,11321]
[null,null,null,null,"6.6/11 kV Switchgear - Other (GM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"20 kV CB (PM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"20 kV CB (GM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"20 kV Switch (PM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"20 kV Switch (GM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"20 kV RMU",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"20 kV Switchgear - Other (PM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"20 kV Switchgear - Other (GM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,null,"Transformers  "]
[null,null,null,null,"6.6/11 kV Transformer (PM)",33900,254,38,411,58,34077,0,109,404,129,34501,519,188,592,188,34574,195,133,253,136,34635,349,133,572,127,34852]
[null,null,null,null,"6.6/11 kV Transformer (GM)",15050,34,20,325,10,15331,63,47,290,47,15558,280,140,305,140,15583,105,73,130,89,15624,188,59,294,79,15750]
[null,null,null,null,"20 kV Transformer (PM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"20 kV Transformer (GM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,"EHV Network"]
[null,null,null,"Overhead lines - Conductor"]
[null,null,null,null,"33kV OHL (Pole Line)",1032,0,6,5,6,1037,8,8,6,8,1035,3,8,5,8,1037,5,3.1,4.3,1.9000000000000001,1035.1000000000001,0.6,9.6999999999999993,0.7,3.5,1029.0000000000002]
[null,null,null,null,"33kV OHL (Tower Line)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"66kV OHL (Pole Line)",801,0,0,0,0,801,8,0,0,0,793,0,0,0,0,793,0,0,0,0,793,0,0,0,0,793]
[null,null,null,null,"66kV OHL (Tower Line)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,null,"Overhead lines - Support"]
[null,null,null,null,"33kV Pole",7723,0,58,45,43,7753,0,0,0,0,7753,168,448,97,158,7392,50,35,43,22.7,7372.7,6,98.8,7,36.5,7311.4]
[null,null,null,null,"33kV Tower",730,5,0,0,0,725,0,0,0,0,725,0,0,0,0,725,0,0,0,0,725,0,0,0,0,725]
[null,null,null,null,"66kV Pole",8891,0,0,0,0,8891,0,0,0,0,8891,0,0,0,0,8891,0,0,0,0,8891,0,0,0,0,8891]
[null,null,null,null,"66kV Tower",672,0,0,0,0,672,3,0,0,0,669,0,0,0,0,669,0,0,0,0,669,0,0,0,0,669]
[]
[null,null,null,"Underground cables (kms)"]
[null,null,null,null,"33kV UG Cable (Non Pressurised)",219,0,0,1,2,222,1,3,3,3,224,0,7,6,10,233,1.9,19.2,11.9,4.5,228.3,1.1000000000000001,12.3,4.4000000000000004,2.2000000000000002,221.5]
[null,null,null,null,"33kV UG Cable (Oil)",130,0,0,0,0,130,2,0,0,0,128,6,0,0,0,122,0,0,0,0,122,0,0,0,0,122]
[null,null,null,null,"33kV UG Cable (Gas)",9,0,0,0,0,9,0,0,0,0,9,0,0,0,0,9,0,0,0,0,9,0,0,0,0,9]
[null,null,null,null,"66kV UG Cable (Non Pressurised)",8,0,0,0,0,8,0,0,0,0,8,0,0,0,0,8,0,0,0,0,8,0,0,0,0,8]
[null,null,null,null,"66kV UG Cable (Oil)",8,0,0,0,0,8,0,0,0,0,8,0,0,0,0,8,0,0,0,0,8,0,0,0,0,8]
[null,null,null,null,"66kV UG Cable (Gas)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[]
[null,null,null,"Submarine cables (kms)"]
[null,null,null,null,"EHV Sub Cable",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,"",0,"",0,0,"",0,"",0,0]
[]
[null,null,null,"Switchgear "]
[null,null,null,null,"33 KV CB (ID)",85,0,0,0,0,85,0,0,0,0,85,0,0,0,0,85,0,10,0,10,85,0,4,3,4,88]
[null,null,null,null,"33 kV CB (OD)",307,0,0,1,0,308,4,3,1,3,305,0,0,0,0,305,0,18,0,18,305,0,9,0,9,305]
[null,null,null,null,"33 kV Switch (GM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"33 kV Switch (PM)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"33 kV RMU",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"33 kV Switchgear - Other",1438,0,0,0,0,1438,0,0,0,0,1438,0,0,0,6,1444,0,0,0,0,1444,0,0,0,0,1444]
[null,null,null,null,"66 KV CB (ID & OD)",71,0,0,0,0,71,0,0,0,1,72,0,0,0,5,77,0,0,0,0,77,0,0,0,0,77]
[null,null,null,null,"66 KV Switchgear - Other",561,0,0,0,0,561,0,0,0,0,561,0,0,0,14,575,0,0,0,0,575,0,0,0,0,575]
[]
[null,null,null,"Transformers  "]
[null,null,null,null,"33 kV Transformer (PM)",3,0,0,0,0,3,0,0,0,0,3,0,0,0,0,3,0,0,0,0,3,0,0,0,0,3]
[null,null,null,null,"33 kV Transformer (GM)",208,4,0,0,0,204,0,0,0,0,204,2,1,1,1,203,0,16,0,16,203,2,0,2,0,203]
[null,null,null,null,"33 kV AuxiliaryTransfomer",190,0,0,0,0,190,0,0,0,0,190,0,0,0,3,193,0,0,0,0,193,0,0,0,0,193]
[null,null,null,null,"66 kV Transformer",78,0,0,0,1,79,0,0,0,1,80,0,4,1,5,82,0,3,0,3,82,0,0,0,0,82]
[null,null,null,null,"66 kV AuxiliaryTransfomer",42,0,0,0,0,42,0,0,0,0,42,0,0,0,4,46,0,0,0,0,46,0,0,0,0,46]
[]
[null,null,"132kV Network"]
[null,null,null,"Overhead lines - Conductor"]
[null,null,null,null,"132kV OHL Conductor (Pole Line)",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0]
[null,null,null,null,"132kV OHL Conductor (Tower Line)",1403,11,0,0,0,1392,0,2,0,2,1392,24,0,0,0,1368,0,200,0,200,1368,0,46,0,46,1368]
[]
[null,null,null,"Overhead lines - Support"]
[null,null,null,null,"132kV Pole",843,0,0,0,0,843,0,0,0,0,843,0,0,0,0,843,0,0,0,0,843,0,0,0,0,843]
[null,null,null,null,"132kV Tower",2799,23,0,0,0,2776,0,0,0,0,2776,0,0,0,0,2776,0,50,0,50,2776,0,9,0,9,2776]
[null,null,null,null,"132kV Fittings (Tower Line)",4787,0,0,0,0,4787,0,0,0,0,4787,0,0,0,0,4787,0,70,0,70,4787,0,19,0,19,4787]
[]
[null,null,null,"Underground cables (kms)"]
[null,null,null,null,"132kV UG Cable (Non Pressurised)",35,0,0,0,0,35,0,0,1,0,36,0,0,0,0,36,0,0,7,0,43,0,0,0,0,43]
[null,null,null,null,"132kV UG Cable (Oil)",256,0,0,0,0,256,0,0,0,0,256,5,0,0,0,251,0,0,0,0,251,0,0,0,0,251]
[null,null,null,null,"132kV UG Cable (Gas)",16,0,0,0,0,16,0,0,0,0,16,0,0,0,0,16,0,0,0,0,16,0,0,0,0,16]
[]
[null,null,null,"Submarine cables (kms)"]
[null,null,null,null,"132 kV Sub Cable",0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,0,"",0,"",0,0,"",0,"",0,0]
[]
[null,null,null,"Switchgear "]
[null,null,null,null,"132 kV CB (ID & OD)",319,10,0,3,0,312,19,0,2,0,295,0,0,0,0,295,0,0,0,0,295,0,0,0,0,295]
[null,null,null,null,"132 kV Switchgear (other)",1690,0,0,0,0,1690,0,0,0,0,1690,0,0,0,14,1704,0,25,0,25,1704,0,2,0,2,1704]
[]
[null,null,null,"Transformers  "]
[null,null,null,null,"132 kV Transformer",230,0,0,4,0,234,0,2,3,3,238,0,2,1,3,240,4,6,7,6,243,0,0,0,6,249]
[null,null,null,null,"132 kV AuxiliaryTransfomer",354,0,0,0,0,354,0,0,0,0,354,0,0,0,2,356,2,0,2,0,356,0,0,0,0,356]
[]
[null,null,"Tele-control / SCADA"]
[null,null,null,"Primary substation"]
[null,null,null,null,"132 kV/EHV RTU (PM)",2,0,0,0,0,2,0,0,0,0,2,0,0,0,0,2,"",0,"",0,2,"",0,"",0,2]
[null,null,null,null,"132 kV/EHV RTU (GM)",262,0,0,0,0,262,0,0,0,0,262,0,0,0,0,262,"",0,"",0,262,"",0,"",0,262]
[]
[null,null,null,"Secondary substation"]
[null,null,null,null,"HV RTU (PM)",1773,0,0,0,0,1773,0,0,0,0,1773,0,0,0,0,1773,"",0,"",0,1773,"",0,"",0,1773]
[null,null,null,null,"HV RTU (GM)",1264,0,0,0,0,1264,0,0,0,0,1264,0,0,0,0,1264,"",0,"",0,1264,"",0,"",0,1264]

{"sheet":"FBPQ LR1","index":13,"n_rows":136,"n_cols":20,"rows_kept":136,"cut":false,"hidden":false,"merged":[[104,1,105,1],[104,2,105,2],[130,1,131,1],[130,2,131,2],[7,1,8,1],[7,2,8,2],[17,2,18,2],[50,2,51,2],[75,1,76,1],[75,2,76,2],[50,1,51,1],[17,1,18,1]]}
["Main Forecast Business Plan DPCR5",null,null,null,null,"Index"]
[]
["LR1 - Demand"]
[]
[]
[null,"Demand Totals"]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,"Gross direct costs","£m",13.245009222625885,30.467388090526448,43.706197044293013,35.337268920415227,31.512553421511626,30.60763079497908,32.371574795483063,35.073910669642856,37.404456108870967,39.504377406401552,null,87.418594357445357,66.849822341926853,154.26841669937221,null,174.96194977537752,0.13413979036507168]
[null,"Customer contributions directs","£m",11.2,25.7,36.1,30.999999999999996,29.1,27.2,28.9,31.400000000000002,33.5,35.5,null,73,60.099999999999994,133.1,null,156.5,0.17580766341096923]
[null,"Net (gross directs - customer contributions directs)","£m",2.045009222625886,4.767388090526449,7.6061970442930118,4.3372689204152302,2.4125534215116247,3.4076307949790809,3.4715747954830647,3.6739106696428543,3.9044561088709671,4.0043774064015523,null,14.418594357445347,6.7498223419268548,21.168416699372202,null,18.461949775377519,-0.12785400828182625]
[null,"Customer contributions indirects","£m",-5.6,16.399999999999999,18.100000000000001,7.3,10.199999999999999,9.8000000000000007,10.5,11.4,12.1,12.9,null,28.9,17.5,46.399999999999991,null,56.7,0.22198275862068995]
[null,"Net (gross directs - customer contributions directs and indirects)","£m",7.6450092226258857,-11.63261190947355,-10.49380295570699,-2.9627310795847697,-7.7874465784883746,-6.3923692050209198,-7.0284252045169353,-7.7260893303571461,-8.1955438911290326,-8.8956225935984481,null,-14.481405642554654,-10.750177658073145,-25.231583300627797,null,-38.238050224622484,0.5154835813918609]
[]
[null,"Demand trends"]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15"]
[]
[null,"Estimated system maximum demand","MW",4796,4658.9513070661806,4826.0106287524131,4881.0087798210307,4891.0150350325257,4901.0151388216536,4911.0200827760555,4921.9636723530948,4931.9598640408049,4941.9963579009709]
[null,"Increase/Reduction in max demand","MW",18.411043619575576,-137.04869293381986,167.05932168623241,54.998151068617197,10.006255211495427,10.00010378912784,10.004943954401883,10.94358957703963,9.996191687710148,10.036493860165717]
[null,"Incremental increase in max demand due to new connections","MW",29.788408241052473,55.943213503808835,45.741403388645409,34.568844545640133,31.480483362369512,32.59562053245822,35.600909023399225,39.339554646036973,43.69215675670749,48.732458929163059]
[null,"Incremental reduction in max demand due to disconnections","MW",-11.377364621476897,-23.891906437628698,-30.782081702412999,-30.070693477022935,-31.574228150874085,-29.995516743330381,-26.995965068997343,-26.995965068997343,-26.995965068997343,-26.995965068997343]
[null,"Net change in max demand (not due to connections/disconnections)","MW",0,-169.1,152.1,50.5,10.1,7.4,1.4,-1.4,-6.7,-11.7]
[]
[null,"Estimated units distributed","GWh",27442.5,26786.445197405887,26750.635090851607,25371.579153800722,24285.927659013949,24194.592671263927,24710.969172083929,24690.032871184278,24748.532077601347,24685.941626647957]
[null,"Increase/Reduction in units distributed","GWh",0,-656.05480259411513,-35.810106554279912,-1379.0559370508863,-1085.6514947867727,-91.334987750022265,516.37650082000255,-20.936300899651542,58.499206417069217,-62.59045095339026]
[null,"Increase in units distributed due to generic background demand growth","GWh",0,-457.1,7.3,-130,21.790992851614646,-26.763058476932116,599.76576011759266,89.485711399578562,205.87934611450001,122.90668715687468]
[null,"Reduction in units distributed due to energy efficiency ","GWh",0,-54.885017293623179,-53.572786189936423,-53.501224357635863,-50.743232262663689,-48.571929273090142,-48.389259297590101,-49.422012299230104,-49.380139697430799,-49.497138110264942]
[null,"Units distributed offset by DG","GWh",0,0,0,0,-1,-16,-35,-61,-98,-136]
[null,"Units distributed offset by DSM","GWh",0,0,0,0,0,0,0,0,0,0]
[null,"Price impact on units distributed ","GWh",0,-144.06978530049193,10.462679635656512,-165.09025644655472,0,0,0,0,0,0]
[null,"Economic downturn effect on units distributed ","GWh",0,0,0,-1030.4644562466956,-1055.6992553757236,0,0,0,0,0]
[]
[null,"Estimated units distributed"]
[null,"LV","GWh",17231.534288632341,16986.07185731611,17083.980089974037,16260.70716609991,15739.435991959641,15703.638888327863,16138.156491596999,16185.009469663044,16226.018192180643,16227.415795658475]
[null,"HV","GWh",9571.7151826030058,9219.5604920406713,9050.8322700025674,8539.2830338536824,8008.0371776174552,7953.8623516927528,8023.7787345524584,7954.8623478699565,7972.3528317694263,7909.1404156413928]
[null,"EHV (inc. 132kV)","GWh",639.25917557624075,580.76074561142593,615.79981884132508,571.62593137825104,538.49146696797357,537.12840877443,549.0709234655933,550.19803118240134,550.19803118240134,549.42239287921188]
[null,"Total units distributed","GWh",27442.508646811588,26786.393094968211,26750.61217881793,25371.616131331844,24285.964636545072,24194.629648795049,24711.006149615052,24690.0698487154,24748.56905513247,24685.978604179079]
[]
[null,"Incremental increase in units distributed attributable to new connections"]
[null,"LV","MWh",150986.26417066815,203584.55404342199,192253.5893249269,132484.41094598046,122176.02190486882,125837.56714792983,137088.3975282902,151224.35070925605,167392.03205629866,185894.69171820194]
[null,"HV","MWh",83864.249071945393,323226.79329812288,212281.3804633618,186685.31277786181,166269.60964441008,173692.03248024115,190606.7963286067,211244.83275900036,235871.04812542369,264843.88721184368]
[null,"EHV (inc. 132kV)","MWh",0,0,0,0,0,0,0,0,0,0]
[null,"Total increase in units distributed due to new connections","MWh",234850.51324261352,526811.34734154493,404534.9697882887,319169.7237238423,288445.63154927891,299529.59962817095,327695.19385689689,362469.18346825638,403263.08018172235,450738.57893004559]
[]
[]
[null,"Connections/disconnections volume"]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15"]
[null,"Connections/Disconnections"]
[null,"Estimated number demand connections/disconnections at LV"]
[null,"IDNO connections","#",1,0,4,4,3,3,4,4,5,5]
[null,"Connections (excluding IDNOs)","#",34709,32183,29520,20064,21471,21340,22365,24164,26142,28314]
[null,"Disconnections","#",6042,12688,16347,15969,16768,15929,14336,14336,14336,14336]
[null,"Estimated number demand connections/disconnections at HV"]
[null,"IDNO connections","#",2,5,6,5,5,5,6,6,7,8]
[null,"Connections (excluding IDNOs)","#",54,615,376,336,302,317,348,386,432,488]
[null,"Disconnections","#",61,128,165,161,169,161,145,145,145,145]
[null,"Estimated number demand connections/disconnections at EHV"]
[null,"IDNO connections","#",0,0,0,0,0,0,0,0,0,0]
[null,"Connections (excluding IDNOs)","#",0,0,0,0,0,0,0,0,0,0]
[null,"Disconnections","#",0,0,0,0,0,0,0,0,0,0]
[null,"Estimated number demand connections/disconnections at 132kV"]
[null,"IDNO connections","#",0,0,0,0,0,0,0,0,0,0]
[null,"Connections (excluding IDNOs)","#",0,0,0,0,0,0,0,0,0,0]
[null,"Disconnections","#",0,0,0,0,0,0,0,0,0,0]
[null,"Total number of demand connections","#",34766,32803,29906,20409,21781,21665,22723,24560,26586,28815]
[null,"Total number of demand disconnections","#",6103,12816,16512,16130,16937,16090,14481,14481,14481,14481]
[]
[]
[null,"Customer specific demand investment"]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,"New connections & customer specific reinforcement:"]
[null,"Connections provided at LV"]
[null,"Sole use","£m",0,0,0,20.745756192041522,17.044525749999998,16.488626912133892,17.567500956085322,19.3103553125,20.670883639112905,22.012389400581959,null,0,37.790281942041517,37.790281942041517,null,96.049756220414082,1.5416522789569125]
[null,"Shared","£m",11.861202288918703,27.291634283044864,36.554273891590519,12.109962944636678,8.6213589549418597,8.39241489539749,8.9811381292346297,9.8522220982142859,10.630740157258066,11.301003486905916,null,75.707110463554088,20.731321899578539,96.43843236313262,null,49.157518767010387,-0.49027044962830835]
[null,"LV total","£m",11.861202288918703,27.291634283044864,36.554273891590519,32.855719136678204,25.66588470494186,24.881041807531382,26.548639085319952,29.162577410714285,31.301623796370968,33.313392887487879,null,75.707110463554088,58.521603841620063,134.22871430517415,null,145.20727498742446,8.1789956337435549E-2]
[null,"Connections provided at HV"]
[null,"Sole use","£m",0,0,0,1.4889298702422145,3.3692667180232556,2.6658259079497908,2.7634271166875783,2.7586221874999999,2.8545505977822581,2.9480878661493697,null,0,4.8581965882654696,4.8581965882654696,null,13.990513676068998,1.8797751226991939]
[null,"Shared","£m",1.3838069337071819,3.1757538074815841,7.1519231527024933,0.99261991349480971,2.4774019985465117,3.0607630794979079,3.0595085934755333,3.1527110714285715,3.2482817147177419,3.2428966527643062,null,11.711483893891259,3.4700219120413216,15.181505805932581,null,15.764161111884061,3.8379282885350668E-2]
[null,"HV total","£m",1.3838069337071819,3.1757538074815841,7.1519231527024933,2.481549783737024,5.8466687165697673,5.7265889874476983,5.8229357101631116,5.9113332589285719,6.1028323125000004,6.1909845189136758,null,11.711483893891259,8.3282185003067912,20.039702394198049,null,29.754674787953061,0.48478626092609634]
[null,"Connections provided at EHV"]
[null,"Sole use","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Shared","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"EHV total","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Connections provided at 132kV"]
[null,"Sole use","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Shared","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"132kV total","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[]
[null,"Expenditure on DSM to avoid customer spec investment","£m",null,null,null,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Total inc. expenditure on DSM to avoid customer spec investment","£m",13.245009222625885,30.467388090526448,43.706197044293013,35.337268920415227,31.512553421511626,30.60763079497908,32.371574795483063,35.073910669642856,37.404456108870967,39.504377406401552,null,87.418594357445357,66.849822341926853,154.26841669937221,null,174.96194977537752,0.13413979036507168]
[]
[null,"Expenditure avoided due to DG","£m",null,null,null,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Expenditure avoided due to DSM","£m",null,null,null,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[]
[]
[null,"Customer contributions - customer specific demand investment"]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,"Customer contributions (directs) for connections at LV"]
[null,"Sole use","£m",0,0,0,20.9,17.2,16.7,17.8,19.600000000000001,21,22.4,null,0,38.099999999999994,38.099999999999994,null,97.5,1.5590551181102366]
[null,"Shared ","£m",10,23,30.6,7.7,6.4,6.2,6.6,7.3,7.8,8.3000000000000007,null,63.6,14.100000000000001,77.7,null,36.200000000000003,-0.53410553410553407]
[null,"LV total","£m",10,23,30.6,28.599999999999998,23.6,22.9,24.4,26.900000000000002,28.8,30.7,null,63.6,52.2,115.80000000000001,null,133.69999999999999,0.1545768566493953]
[null,"Customer contributions (directs) for connections at HV"]
[null,"Sole use","£m",0,0,0,1.5,3.4,2.7,2.8,2.8,2.9,3,null,0,4.9000000000000004,4.9000000000000004,null,14.200000000000001,1.8979591836734695]
[null,"Shared ","£m",1.2,2.7,5.5,0.9,2.1,1.6,1.7,1.7,1.8,1.8,null,9.4,3,12.4,null,8.6,-0.30645161290322587]
[null,"HV total","£m",1.2,2.7,5.5,2.4,5.5,4.3000000000000007,4.5,4.5,4.7,4.8,null,9.4,7.9,17.3,null,22.8,0.31791907514450868]
[null,"Customer contributions (directs) for connections at EHV"]
[null,"Sole use","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Shared ","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"EHV total","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Customer contributions (directs) for connections at 132kV"]
[null,"Sole use","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Shared ","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"132kV total","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[]
[null,"Customer contributions (directs) total","£m",11.2,25.7,36.1,30.999999999999996,29.1,27.2,28.9,31.400000000000002,33.5,35.5,null,73,60.099999999999994,133.1,null,156.5,0.17580766341096923]
[null,"Customer contributions (indirects)","£m",-5.6,16.399999999999999,18.100000000000001,7.3,10.199999999999999,9.8000000000000007,10.5,11.4,12.1,12.9,null,28.9,17.5,46.399999999999991,null,56.7,0.22198275862068995]
[null,"Customer contributions total","£m",5.6,42.099999999999994,54.2,38.299999999999997,39.299999999999997,37,39.4,42.800000000000004,45.6,48.4,null,101.9,77.599999999999994,179.5,null,213.20000000000002,0.18774373259052934]
[]
[null,"Total inc. exp on DSM to avoid customer spec investment (net of cust cont)","£m",7.6450092226258857,-11.632611909473546,-10.49380295570699,-2.9627310795847706,-7.7874465784883711,-6.3923692050209198,-7.0284252045169353,-7.7260893303571478,-8.1955438911290344,-8.8956225935984463,null,-14.48140564255465,-10.750177658073142,-25.23158330062779,null,-38.238050224622484,0.51548358139186135]
[]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,"Unapportioned part of shared LV","£m",1.8612022889187028,4.2916342830448642,5.9542738915905176,4.4099629446366775,2.2213589549418593,2.1924148953974898,2.3811381292346301,2.552222098214286,2.8307401572580657,3.0010034869059155,null,12.107110463554084,6.6313218995785368,18.73843236313262,null,12.957518767010388,-0.3085057215082746]
[null,"Unapportioned part of shared HV","£m",0.18380693370718193,0.47575380748158391,1.6519231527024933,9.2619913494809691E-2,0.37740199854651157,1.4607630794979078,1.3595085934755333,1.4527110714285716,1.4482817147177418,1.4428966527643061,null,2.3114838938912592,0.47002191204132127,2.7815058059325803,null,7.1641611118840602,1.575641257553323]
[null,"Unapportioned part of shared EHV","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Unapportioned part of shared 132kV","£m",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]

{"sheet":"FBPQ LR1 - V5 opt3","index":14,"n_rows":266,"n_cols":20,"rows_kept":266,"cut":false,"hidden":false,"merged":[[78,1,79,1],[78,2,79,2],[109,1,110,1],[109,2,110,2],[142,1,143,1],[142,2,143,2],[7,1,8,1],[7,2,8,2],[25,2,26,2],[25,1,26,1],[47,1,48,1],[47,2,48,2]]}
["Main Forecast Business Plan DPCR5"]
[]
["LR1a - Demand - metered connections"]
[]
[]
[null,"Demand Totals - Table 1"]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,"Gross all connections costs","£m",{"$f":"SUM(D178,D217,D240)","v":0},0,0,0,0,0,0,0,0,0,null,{"$f":"SUM(D10:G10)","v":0},{"$f":"SUM(H10)","v":0},{"$f":"SUM(D10:H10)","v":0},null,{"$f":"SUM(I10:M10)","v":0},{"$f":"IF(Q10<>0,(S10-Q10)/Q10,\"0\")","v":"0"}]
[null,"Gross direct connections costs subject to apportionment rule","£m",{"$f":"D240","v":0},0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Customer contributions excluding margins","£m",{"$f":"D263","v":0},0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Net (gross directs subject to apportionment rule - customer contributions directs)","£m",{"$f":"D11-D12","v":0},0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"DUOS funded related party margin","£m",null,null,null,null,null,null,null,null,null,0.3,null,0,0,0,null,0.3,"0"]
[null,"Net (gross directs subject to apportionment rule - customer contributions directs + DUOS funded related party margin)","£m",{"$f":"D13+D14","v":0},0,0,0,0,0,0,0,0,0.3,null,0,0,0,null,0.3,"0"]
[null,"Check",null,{"$f":"IF(D13-SUM(D31,D35,D39,D43)=0,\"OK\",\"ERROR\")","v":"OK"},"OK","OK","OK","OK","OK","OK","OK","OK","OK"]
[]
[null,null,null,"DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,"Units","2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,"Pensions with total gross direct connections costs","£m",null,null,null,null,null,null,null,null,null,null,null,{"$f":"SUM(D20:G20)","v":0},{"$f":"SUM(H20)","v":0},{"$f":"SUM(D20:H20)","v":0},null,{"$f":"SUM(I20:M20)","v":0},{"$f":"IF(Q20<>0,(S20-Q20)/Q20,\"0\")","v":"0"}]
[null,"Pensions with direct connections costs subject to apportionment rule","£m",null,null,null,null,null,null,null,null,null,null,null,{"$f":"SUM(D21:G21)","v":0},{"$f":"SUM(H21)","v":0},{"$f":"SUM(D21:H21)","v":0},null,{"$f":"SUM(I21:M21)","v":0},{"$f":"IF(Q21<>0,(S21-Q21)/Q21,\"0\")","v":"0"}]
[null,"Total","£m",{"$f":"D20+D21","v":0},0,0,0,0,0,0,0,0,0,null,{"$f":"SUM(D22:G22)","v":0},{"$f":"SUM(H22)","v":0},{"$f":"SUM(D22:H22)","v":0},null,{"$f":"SUM(I22:M22)","v":0},{"$f":"IF(Q22<>0,(S22-Q22)/Q22,\"0\")","v":"0"}]
[]
[null,"Connections expenditure recovered via DUoS - Table 2"]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,"Customer contributions (directs) for connections at LV"]
[null,"Small scale LV domestic and one-off commercial","£m",null,null,null,null,null,{"$f":"I225-I248","v":0},0,0,0,0]
[null,"All other LV (with only LV work)","£m",null,null,null,null,null,0,0,0,0,0]
[null,"LV total","£m",{"$f":"D227-D250","v":0},{"$f":"E227-E250","v":0},{"$f":"F227-F250","v":0},{"$f":"G227-G250","v":0},{"$f":"H227-H250","v":0},{"$f":"SUM(I29:I30)","v":0},{"$f":"SUM(J29:J30)","v":0},{"$f":"SUM(K29:K30)","v":0},{"$f":"SUM(L29:L30)","v":0},{"$f":"SUM(M29:M30)","v":0},null,{"$f":"SUM(D31:G31)","v":0},{"$f":"SUM(H31)","v":0},{"$f":"SUM(D31:H31)","v":0},null,{"$f":"SUM(I31:M31)","v":0},{"$f":"IF(Q31<>0,(S31-Q31)/Q31,\"0\")","v":"0"}]
[null,"Customer contributions (directs) for connections at HV"]
[null,"LV end connections involving HV work","£m",null,null,null,null,null,{"$f":"I229-I252","v":0},0,0,0,0]
[null,"HV end connections involving only HV work","£m",null,null,null,null,null,0,0,0,0,0]
[null,"HV total","£m",{"$f":"D231-D254","v":0},{"$f":"E231-E254","v":0},{"$f":"F231-F254","v":0},{"$f":"G231-G254","v":0},{"$f":"H231-H254","v":0},{"$f":"SUM(I33:I34)","v":0},{"$f":"SUM(J33:J34)","v":0},{"$f":"SUM(K33:K34)","v":0},{"$f":"SUM(L33:L34)","v":0},{"$f":"SUM(M33:M34)","v":0},null,{"$f":"SUM(D35:G35)","v":0},{"$f":"SUM(H35)","v":0},{"$f":"SUM(D35:H35)","v":0},null,{"$f":"SUM(I35:M35)","v":0},{"$f":"IF(Q35<>0,(S35-Q35)/Q35,\"0\")","v":"0"}]
[null,"Customer contributions (directs) for connections at EHV"]
[null,"HV end connections involving EHV work","£m",null,null,null,null,null,{"$f":"I233-I256","v":0},0,0,0,0]
[null,"EHV end connections involving only EHV work","£m",null,null,null,null,null,0,0,0,0,0]
[null,"EHV total","£m",{"$f":"D235-D258","v":0},{"$f":"E235-E258","v":0},{"$f":"F235-F258","v":0},{"$f":"G235-G258","v":0},{"$f":"H235-H258","v":0},{"$f":"SUM(I37:I38)","v":0},{"$f":"SUM(J37:J38)","v":0},{"$f":"SUM(K37:K38)","v":0},{"$f":"SUM(L37:L38)","v":0},{"$f":"SUM(M37:M38)","v":0},null,{"$f":"SUM(D39:G39)","v":0},{"$f":"SUM(H39)","v":0},{"$f":"SUM(D39:H39)","v":0},null,{"$f":"SUM(I39:M39)","v":0},{"$f":"IF(Q39<>0,(S39-Q39)/Q39,\"0\")","v":"0"}]
[null,"Customer contributions (directs) for connections at 132kV"]
[null," HV or EHV connections involving 132kV work","£m",null,null,null,null,null,{"$f":"I237-I260","v":0},0,0,0,0]
[null,"132kV end connections involving only 132kV work","£m",null,null,null,null,null,0,0,0,0,0]
[null,"132kV total","£m",{"$f":"D239-D262","v":0},{"$f":"E239-E262","v":0},{"$f":"F239-F262","v":0},{"$f":"G239-G262","v":0},{"$f":"H239-H262","v":0},{"$f":"SUM(I41:I42)","v":0},{"$f":"SUM(J41:J42)","v":0},{"$f":"SUM(K41:K42)","v":0},{"$f":"SUM(L41:L42)","v":0},{"$f":"SUM(M41:M42)","v":0},null,{"$f":"SUM(D43:G43)","v":0},{"$f":"SUM(H43)","v":0},{"$f":"SUM(D43:H43)","v":0},null,{"$f":"SUM(I43:M43)","v":0},{"$f":"IF(Q43<>0,(S43-Q43)/Q43,\"0\")","v":"0"}]
[]
[]
[null,"Metered connections volume - Table 3"]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15"]
[null,"Metered connections"]
[null,"Estimated number demand connections at LV"]
[null,"IDNO connections","#",{"$f":"D83+D114","v":0},0,0,0,0,0,0,0,0,0]
[null,"Adopted connections",null,{"$f":"D84+D115","v":0},0,0,0,0,0,0,0,0,0]
[null,"Small scale LV domestic and one-off commercial connections",null,null,null,null,null,null,{"$f":"I85+I116","v":0},0,0,0,0]
[null,"All other LV connections (with only LV work)","#",null,null,null,null,null,0,0,0,0,0]
[null,"DNO total LV",null,{"$f":"D87+D118","v":0},{"$f":"E87+E118","v":0},{"$f":"F87+F118","v":0},{"$f":"G87+G118","v":0},{"$f":"H87+H118","v":0},0,0,0,0,0]
[null,"Estimated number demand connections at HV"]
[null,"IDNO connections","#",{"$f":"D89+D120","v":0},0,0,0,0,0,0,0,0,0]
[null,"Adopted connections",null,{"$f":"D90+D121","v":0},0,0,0,0,0,0,0,0,0]
[null,"LV end connections involving HV work",null,null,null,null,null,null,{"$f":"I91+I122","v":0},0,0,0,0]
[null,"HV end connections involving only HV work","#",null,null,null,null,null,0,0,0,0,0]
[null,"DNO total HV",null,{"$f":"D93+D124","v":0},{"$f":"E93+E124","v":0},{"$f":"F93+F124","v":0},{"$f":"G93+G124","v":0},{"$f":"H93+H124","v":0},0,0,0,0,0]
[null,"Estimated number demand connections at EHV"]
[null,"IDNO connections","#",{"$f":"D95+D126","v":0},0,0,0,0,0,0,0,0,0]
[null,"Adopted connections",null,{"$f":"D96+D127","v":0},0,0,0,0,0,0,0,0,0]
[null,"HV end connections involving EHV work",null,null,null,null,null,null,{"$f":"I97+I128","v":0},0,0,0,0]
[null,"EHV end connections involving only EHV work","#",null,null,null,null,null,0,0,0,0,0]
[null,"DNO total EHV",null,{"$f":"D99+D130","v":0},{"$f":"E99+E130","v":0},{"$f":"F99+F130","v":0},{"$f":"G99+G130","v":0},{"$f":"H99+H130","v":0},0,0,0,0,0]
[null,"Estimated number demand connections at 132kV"]
[null,"IDNO connections","#",{"$f":"D101+D132","v":0},0,0,0,0,0,0,0,0,0]
[null,"Adopted connections",null,{"$f":"D102+D133","v":0},0,0,0,0,0,0,0,0,0]
[null," HV or EHV connections involving 132kV work",null,null,null,null,null,null,{"$f":"I103+I134","v":0},0,0,0,0]
[null,"132kV end connections involving only 132kV work","#",null,null,null,null,null,0,0,0,0,0]
[null,"DNO total 132kV",null,{"$f":"D105+D136","v":0},{"$f":"E105+E136","v":0},{"$f":"F105+F136","v":0},{"$f":"G105+G136","v":0},{"$f":"H105+H136","v":0},0,0,0,0,0]
[null,"Total number of demand connections","#",{"$f":"SUM(D52:D55,D58:D61,D64:D67,D70:D73)","v":0},0,0,0,0,0,0,0,0,0]
[]
[null,"Metered connections volume - Sole use connections where there is no associated expenditure subject to the apportionment rule - Table 4"]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15"]
[null,"Metered connections"]
[null,"Estimated number demand connections at LV"]
[null,"IDNO connections","#"]
[null,"Adopted connections"]
[null,"Small scale LV domestic and one-off commercial connections"]
[null,"All other LV connections (with only LV work)","#"]
[null,"DNO total LV",null,null,null,null,null,null,{"$f":"SUM(I85:I86)","v":0},{"$f":"SUM(J85:J86)","v":0},{"$f":"SUM(K85:K86)","v":0},{"$f":"SUM(L85:L86)","v":0},{"$f":"SUM(M85:M86)","v":0}]
[null,"Estimated number demand connections with HV work"]
[null,"IDNO connections","#"]
[null,"Adopted connections"]
[null,"LV end connections involving HV work"]
[null,"HV end connections involving only HV work","#"]
[null,"DNO total HV",null,null,null,null,null,null,{"$f":"SUM(I91:I92)","v":0},{"$f":"SUM(J91:J92)","v":0},{"$f":"SUM(K91:K92)","v":0},{"$f":"SUM(L91:L92)","v":0},{"$f":"SUM(M91:M92)","v":0}]
[null,"Estimated number demand connections with EHV work"]
[null,"IDNO connections","#"]
[null,"Adopted connections"]
[null,"HV end connections involving EHV work"]
[null,"EHV end connections involving only EHV work","#"]
[null,"DNO total EHV",null,null,null,null,null,null,{"$f":"SUM(I97:I98)","v":0},{"$f":"SUM(J97:J98)","v":0},{"$f":"SUM(K97:K98)","v":0},{"$f":"SUM(L97:L98)","v":0},{"$f":"SUM(M97:M98)","v":0}]
[null,"Estimated number demand connections with 132kV work"]
[null,"IDNO connections","#"]
[null,"Adopted connections"]
[null," HV or EHV connections involving 132kV work"]
[null,"132kV end connections involving only 132kV work","#"]
[null,"DNO total 132kV",null,null,null,null,null,null,{"$f":"SUM(I103:I104)","v":0},{"$f":"SUM(J103:J104)","v":0},{"$f":"SUM(K103:K104)","v":0},{"$f":"SUM(L103:L104)","v":0},{"$f":"SUM(M103:M104)","v":0}]
[null,"Total number of demand connections","#",{"$f":"SUM(D83:D84,D87,D89:D90,D93,D95:D96,D99,D101:D102,D105)","v":0},0,0,0,0,0,0,0,0,0]
[]
[null,"Metered connections volume - Connections where there is associated expenditure subject to the apportionment rule - Table 5"]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15"]
[null,"Metered connections"]
[null,"Estimated number demand connections at LV"]
[null,"IDNO connections","#"]
[null,"Adopted connections"]
[null,"Small scale LV domestic and one-off commercial connections"]
[null,"All other LV connections (with only LV work)","#"]
[null,"DNO total LV",null,null,null,null,null,null,{"$f":"SUM(I116:I117)","v":0},{"$f":"SUM(J116:J117)","v":0},{"$f":"SUM(K116:K117)","v":0},{"$f":"SUM(L116:L117)","v":0},{"$f":"SUM(M116:M117)","v":0}]
[null,"Estimated number demand connections with HV work"]
[null,"IDNO connections","#"]
[null,"Adopted connections"]
[null,"LV end connections involving HV work"]
[null,"HV end connections involving only HV work","#"]
[null,"DNO total HV",null,null,null,null,null,null,{"$f":"SUM(I122:I123)","v":0},{"$f":"SUM(J122:J123)","v":0},{"$f":"SUM(K122:K123)","v":0},{"$f":"SUM(L122:L123)","v":0},{"$f":"SUM(M122:M123)","v":0}]
[null,"Estimated number demand connections with EHV work"]
[null,"IDNO connections","#"]
[null,"Adopted connections"]
[null,"HV end connections involving EHV work"]
[null,"EHV end connections involving only EHV work","#"]
[null,"DNO total EHV",null,null,null,null,null,null,{"$f":"SUM(I128:I129)","v":0},{"$f":"SUM(J128:J129)","v":0},{"$f":"SUM(K128:K129)","v":0},{"$f":"SUM(L128:L129)","v":0},{"$f":"SUM(M128:M129)","v":0}]
[null,"Estimated number demand connections with 132kV work"]
[null,"IDNO connections","#"]
[null,"Adopted connections"]
[null," HV or EHV connections involving 132kV work"]
[null,"132kV end connections involving only 132kV work","#"]
[null,"DNO total 132kV",null,null,null,null,null,null,{"$f":"SUM(I134:I135)","v":0},{"$f":"SUM(J134:J135)","v":0},{"$f":"SUM(K134:K135)","v":0},{"$f":"SUM(L134:L135)","v":0},{"$f":"SUM(M134:M135)","v":0}]
[null,"Total number of demand connections","#",{"$f":"SUM(D114:D115,D118,D120:D121,D124,D126:D127,D130,D132:D133,D136)","v":0},0,0,0,0,0,0,0,0,0]
[]
[]
[]
[null,"Customer specific demand investment - Sole use expenditure where there is no associated expenditure subject to the apportionment rule - Table 6"]
[]
[null,null,"Units","DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,"New connections & customer specific reinforcement:"]
[null,"Connections provided at LV"]
[null,"Small scale LV domestic and one-off commercial","£m"]
[null,"Ratio - small scale LV domestic and one-off commercial - non-contestable","%"]
[null,"Ratio - small scale LV domestic and one-off commercial - contestable","%",null,null,null,null,null,{"$f":"1-I148","v":1},{"$f":"1-J148","v":1},{"$f":"1-K148","v":1},{"$f":"1-L148","v":1},{"$f":"1-M148","v":1}]
[null,"All other LV (with only LV work)","£m"]
[null,"Ratio - all other LV (with only LV work) - non-contestable","%"]
[null,"Ratio - all other LV (with only LV work) - contestable","%",null,null,null,null,null,{"$f":"1-I151","v":1},{"$f":"1-J151","v":1},{"$f":"1-K151","v":1},{"$f":"1-L151","v":1},{"$f":"1-M151","v":1}]
[null,"LV total","£m",null,null,null,null,null,{"$f":"SUM(I147,I150)","v":0},{"$f":"SUM(J147,J150)","v":0},{"$f":"SUM(K147,K150)","v":0},{"$f":"SUM(L147,L150)","v":0},{"$f":"SUM(M147,M150)","v":0},null,{"$f":"SUM(D153:G153)","v":0},{"$f":"SUM(H153)","v":0},{"$f":"SUM(D153:H153)","v":0},null,{"$f":"SUM(I153:M153)","v":0},{"$f":"IF(Q153<>0,(S153-Q153)/Q153,\"0\")","v":"0"}]
[null,"Connections with HV work"]
[null,"LV end connections involving HV work","£m"]
[null,"Ratio - LV end connections involving HV work - non-contestable","%"]
[null,"Ratio - LV end connections involving HV work - contestable","%",null,null,null,null,null,{"$f":"1-I156","v":1},{"$f":"1-J156","v":1},{"$f":"1-K156","v":1},{"$f":"1-L156","v":1},{"$f":"1-M156","v":1}]
[null,"HV end connections involving only HV work","£m"]
[null,"Ratio - HV end connections involving only HV work - non-contestable","%"]
[null,"Ratio - HV end connections involving only HV work - contestable","%",null,null,null,null,null,{"$f":"1-I159","v":1},{"$f":"1-J159","v":1},{"$f":"1-K159","v":1},{"$f":"1-L159","v":1},{"$f":"1-M159","v":1}]
[null,"HV total","£m",null,null,null,null,null,{"$f":"SUM(I155,I158)","v":0},{"$f":"SUM(J155,J158)","v":0},{"$f":"SUM(K155,K158)","v":0},{"$f":"SUM(L155,L158)","v":0},{"$f":"SUM(M155,M158)","v":0},null,{"$f":"SUM(D161:G161)","v":0},{"$f":"SUM(H161)","v":0},{"$f":"SUM(D161:H161)","v":0},null,{"$f":"SUM(I161:M161)","v":0},{"$f":"IF(Q161<>0,(S161-Q161)/Q161,\"0\")","v":"0"}]
[null,"Connections with EHV work"]
[null,"HV end connections involving EHV work","£m"]
[null,"Ratio - HV end connections involving EHV work - non-contestable","%"]
[null,"Ratio - HV end connections involving EHV work - contestable","%",null,null,null,null,null,{"$f":"1-I164","v":1},{"$f":"1-J164","v":1},{"$f":"1-K164","v":1},{"$f":"1-L164","v":1},{"$f":"1-M164","v":1}]
[null,"EHV end connections involving only EHV work","£m"]
[null,"Ratio - EHV end connections involving only EHV work - non-contestable","%"]
[null,"Ratio - EHV end connections involving only EHV work - contestable","%",null,null,null,null,null,{"$f":"1-I167","v":1},{"$f":"1-J167","v":1},{"$f":"1-K167","v":1},{"$f":"1-L167","v":1},{"$f":"1-M167","v":1}]
[null,"EHV total","£m",null,null,null,null,null,{"$f":"SUM(I163,I166)","v":0},{"$f":"SUM(J163,J166)","v":0},{"$f":"SUM(K163,K166)","v":0},{"$f":"SUM(L163,L166)","v":0},{"$f":"SUM(M163,M166)","v":0},null,{"$f":"SUM(D169:G169)","v":0},{"$f":"SUM(H169)","v":0},{"$f":"SUM(D169:H169)","v":0},null,{"$f":"SUM(I169:M169)","v":0},{"$f":"IF(Q169<>0,(S169-Q169)/Q169,\"0\")","v":"0"}]
[null,"Connections with 132kV work"]
[null," HV or EHV connections involving 132kV work","£m"]
[null,"Ratio - HV or EHV connections involving 132kV work - non-contestable","%"]
[null,"Ratio - HV or EHV connections involving 132kV work - contestable","%",null,null,null,null,null,{"$f":"1-I172","v":1},{"$f":"1-J172","v":1},{"$f":"1-K172","v":1},{"$f":"1-L172","v":1},{"$f":"1-M172","v":1}]
[null,"132kV end connections involving only 132kV work","£m"]
[null,"Ratio - 132kV end connections involving only 132kV work - non-contestable","%"]
[null,"Ratio - 132kV end connections involving only 132kV work - contestable","%",null,null,null,null,null,{"$f":"1-I175","v":1},{"$f":"1-J175","v":1},{"$f":"1-K175","v":1},{"$f":"1-L175","v":1},{"$f":"1-M175","v":1}]
[null,"132kV total","£m",null,null,null,null,null,{"$f":"SUM(I171,I174)","v":0},{"$f":"SUM(J171,J174)","v":0},{"$f":"SUM(K171,K174)","v":0},{"$f":"SUM(L171,L174)","v":0},{"$f":"SUM(M171,M174)","v":0},null,{"$f":"SUM(D177:G177)","v":0},{"$f":"SUM(H177)","v":0},{"$f":"SUM(D177:H177)","v":0},null,{"$f":"SUM(I177:M177)","v":0},{"$f":"IF(Q177<>0,(S177-Q177)/Q177,\"0\")","v":"0"}]
[null,"Total sole use expenditure where there is no expenditure subject to the apportionment rule",null,{"$f":"SUM(D153,D161,D169,D177)","v":0},0,0,0,0,0,0,0,0,0,null,{"$f":"SUM(O153,O161,O169,O177)","v":0},{"$f":"SUM(P153,P161,P169,P177)","v":0},{"$f":"SUM(Q153,Q161,Q169,Q177)","v":0},null,{"$f":"SUM(S153,S161,S169,S177)","v":0},{"$f":"IF(Q178<>0,(S178-Q178)/Q178,\"0\")","v":"0"}]
[]
[null,"Customer specific demand investment - sole use expenditure where there is also associated expenditure subject to the apportionment rule - Table 7"]
[]
[null,null,null,"DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,"Customer specific demand investment","Units","2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,"New connections & customer specific reinforcement:"]
[null,"Connections provided at LV"]
[null,"Small scale LV domestic and one-off commercial","£m"]
[null,"Ratio - small scale LV domestic and one-off commercial - non-contestable","%"]
[null,"Ratio - small scale LV domestic and one-off commercial - contestable","%",null,null,null,null,null,{"$f":"1-I187","v":1},{"$f":"1-J187","v":1},{"$f":"1-K187","v":1},{"$f":"1-L187","v":1},{"$f":"1-M187","v":1}]
[null,"All other LV (with only LV work)","£m"]
[null,"Ratio - all other LV (with only LV work) - non-contestable","%"]
[null,"Ratio - all other LV (with only LV work) - contestable","%",null,null,null,null,null,{"$f":"1-I190","v":1},{"$f":"1-J190","v":1},{"$f":"1-K190","v":1},{"$f":"1-L190","v":1},{"$f":"1-M190","v":1}]
[null,"LV total","£m",null,null,null,null,null,{"$f":"SUM(I186,I189)","v":0},{"$f":"SUM(J186,J189)","v":0},{"$f":"SUM(K186,K189)","v":0},{"$f":"SUM(L186,L189)","v":0},{"$f":"SUM(M186,M189)","v":0},null,{"$f":"SUM(D192:G192)","v":0},{"$f":"SUM(H192)","v":0},{"$f":"SUM(D192:H192)","v":0},null,{"$f":"SUM(I192:M192)","v":0},{"$f":"IF(Q192<>0,(S192-Q192)/Q192,\"0\")","v":"0"}]
[null,"Connections with HV work"]
[null,"LV end connections involving HV work","£m"]
[null,"Ratio - LV end connections involving HV work - non-contestable","%"]
[null,"Ratio - LV end connections involving HV work - contestable","%",null,null,null,null,null,{"$f":"1-I195","v":1},{"$f":"1-J195","v":1},{"$f":"1-K195","v":1},{"$f":"1-L195","v":1},{"$f":"1-M195","v":1}]
[null,"HV end connections involving only HV work","£m"]
[null,"Ratio - HV end connections involving only HV work - non-contestable","%"]
[null,"Ratio - HV end connections involving only HV work - contestable","%",null,null,null,null,null,{"$f":"1-I198","v":1},{"$f":"1-J198","v":1},{"$f":"1-K198","v":1},{"$f":"1-L198","v":1},{"$f":"1-M198","v":1}]
[null,"HV total","£m",null,null,null,null,null,{"$f":"SUM(I194,I197)","v":0},{"$f":"SUM(J194,J197)","v":0},{"$f":"SUM(K194,K197)","v":0},{"$f":"SUM(L194,L197)","v":0},{"$f":"SUM(M194,M197)","v":0},null,{"$f":"SUM(D200:G200)","v":0},{"$f":"SUM(H200)","v":0},{"$f":"SUM(D200:H200)","v":0},null,{"$f":"SUM(I200:M200)","v":0},{"$f":"IF(Q200<>0,(S200-Q200)/Q200,\"0\")","v":"0"}]
[null,"Connections with EHV work"]
[null,"HV end connections involving EHV work","£m"]
[null,"Ratio - HV end connections involving EHV work - non-contestable","%"]
[null,"Ratio - HV end connections involving EHV work - contestable","%",null,null,null,null,null,{"$f":"1-I203","v":1},{"$f":"1-J203","v":1},{"$f":"1-K203","v":1},{"$f":"1-L203","v":1},{"$f":"1-M203","v":1}]
[null,"EHV end connections involving only EHV work","£m"]
[null,"Ratio - EHV end connections involving only EHV work - non-contestable","%"]
[null,"Ratio - EHV end connections involving only EHV work - contestable","%",null,null,null,null,null,{"$f":"1-I206","v":1},{"$f":"1-J206","v":1},{"$f":"1-K206","v":1},{"$f":"1-L206","v":1},{"$f":"1-M206","v":1}]
[null,"EHV total","£m",null,null,null,null,null,{"$f":"SUM(I202,I205)","v":0},{"$f":"SUM(J202,J205)","v":0},{"$f":"SUM(K202,K205)","v":0},{"$f":"SUM(L202,L205)","v":0},{"$f":"SUM(M202,M205)","v":0},null,{"$f":"SUM(D208:G208)","v":0},{"$f":"SUM(H208)","v":0},{"$f":"SUM(D208:H208)","v":0},null,{"$f":"SUM(I208:M208)","v":0},{"$f":"IF(Q208<>0,(S208-Q208)/Q208,\"0\")","v":"0"}]
[null,"Connections with 132kV work"]
[null," HV or EHV connections involving 132kV work","£m"]
[null,"Ratio - HV or EHV connections involving 132kV work - non-contestable","%"]
[null,"Ratio - HV or EHV connections involving 132kV work - contestable","%",null,null,null,null,null,{"$f":"1-I211","v":1},{"$f":"1-J211","v":1},{"$f":"1-K211","v":1},{"$f":"1-L211","v":1},{"$f":"1-M211","v":1}]
[null,"132kV end connections involving only 132kV work","£m"]
[null,"Ratio - 132kV end connections involving only 132kV work - non-contestable","%"]
[null,"Ratio - 132kV end connections involving only 132kV work - contestable","%",null,null,null,null,null,{"$f":"1-I214","v":1},{"$f":"1-J214","v":1},{"$f":"1-K214","v":1},{"$f":"1-L214","v":1},{"$f":"1-M214","v":1}]
[null,"132kV total","£m",null,null,null,null,null,{"$f":"SUM(I210,I213)","v":0},{"$f":"SUM(J210,J213)","v":0},{"$f":"SUM(K210,K213)","v":0},{"$f":"SUM(L210,L213)","v":0},{"$f":"SUM(M210,M213)","v":0},null,{"$f":"SUM(D216:G216)","v":0},{"$f":"SUM(H216)","v":0},{"$f":"SUM(D216:H216)","v":0},null,{"$f":"SUM(I216:M216)","v":0},{"$f":"IF(Q216<>0,(S216-Q216)/Q216,\"0\")","v":"0"}]
[null,"Total sole use expenditure where there is also expenditure subject to the apportionment rule",null,{"$f":"SUM(D192,D200,D208,D216)","v":0},0,0,0,0,0,0,0,0,0,null,{"$f":"SUM(O192,O200,O208,O216)","v":0},{"$f":"SUM(P192,P200,P208,P216)","v":0},{"$f":"SUM(Q192,Q200,Q208,Q216)","v":0},null,{"$f":"SUM(S192,S200,S208,S216)","v":0},{"$f":"IF(Q217<>0,(S217-Q217)/Q217,\"0\")","v":"0"}]
[]
[null,"Customer specific demand investment - all expenditure subject to the apportionment rule - Table 8"]
[]
[null,null,null,"DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,"Customer specific demand investment","Units","2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,"New connections & customer specific reinforcement:"]
[null,"Connections provided at LV"]
[null,"Small scale LV domestic and one-off commercial","£m"]
[null,"All other LV (with only LV work)","£m"]
[null,"LV total","£m",null,null,null,null,null,{"$f":"SUM(I225,I226)","v":0},{"$f":"SUM(J225,J226)","v":0},{"$f":"SUM(K225,K226)","v":0},{"$f":"SUM(L225,L226)","v":0},{"$f":"SUM(M225,M226)","v":0},null,{"$f":"SUM(D227:G227)","v":0},{"$f":"SUM(H227)","v":0},{"$f":"SUM(D227:H227)","v":0},null,{"$f":"SUM(I227:M227)","v":0},{"$f":"IF(Q227<>0,(S227-Q227)/Q227,\"0\")","v":"0"}]
[null,"Connections with HV work"]
[null,"LV end connections involving HV work","£m"]
[null,"HV end connections involving only HV work","£m"]
[null,"HV total","£m",null,null,null,null,null,{"$f":"SUM(I229,I230)","v":0},{"$f":"SUM(J229,J230)","v":0},{"$f":"SUM(K229,K230)","v":0},{"$f":"SUM(L229,L230)","v":0},{"$f":"SUM(M229,M230)","v":0},null,{"$f":"SUM(D231:G231)","v":0},{"$f":"SUM(H231)","v":0},{"$f":"SUM(D231:H231)","v":0},null,{"$f":"SUM(I231:M231)","v":0},{"$f":"IF(Q231<>0,(S231-Q231)/Q231,\"0\")","v":"0"}]
[null,"Connections with EHV work"]
[null,"HV end connections involving EHV work","£m"]
[null,"EHV end connections involving only EHV work","£m"]
[null,"EHV total","£m",null,null,null,null,null,{"$f":"SUM(I233,I234)","v":0},{"$f":"SUM(J233,J234)","v":0},{"$f":"SUM(K233,K234)","v":0},{"$f":"SUM(L233,L234)","v":0},{"$f":"SUM(M233,M234)","v":0},null,{"$f":"SUM(D235:G235)","v":0},{"$f":"SUM(H235)","v":0},{"$f":"SUM(D235:H235)","v":0},null,{"$f":"SUM(I235:M235)","v":0},{"$f":"IF(Q235<>0,(S235-Q235)/Q235,\"0\")","v":"0"}]
[null,"Connections with 132kV work"]
[null," HV or EHV connections involving 132kV work","£m"]
[null,"132kV end connections involving only 132kV work","£m"]
[null,"132kV total","£m",null,null,null,null,null,{"$f":"SUM(I237,I238)","v":0},{"$f":"SUM(J237,J238)","v":0},{"$f":"SUM(K237,K238)","v":0},{"$f":"SUM(L237,L238)","v":0},{"$f":"SUM(M237,M238)","v":0},null,{"$f":"SUM(D239:G239)","v":0},{"$f":"SUM(H239)","v":0},{"$f":"SUM(D239:H239)","v":0},null,{"$f":"SUM(I239:M239)","v":0},{"$f":"IF(Q239<>0,(S239-Q239)/Q239,\"0\")","v":"0"}]
[null,"Total connections expenditure subject to the apportionment rule",null,{"$f":"SUM(D227,D231,D235,D239)","v":0},0,0,0,0,0,0,0,0,0,null,{"$f":"SUM(O227,O231,O235,O239)","v":0},{"$f":"SUM(P227,P231,P235,P239)","v":0},{"$f":"SUM(Q227,Q231,Q235,Q239)","v":0},null,{"$f":"SUM(S227,S231,S235,S239)","v":0},{"$f":"IF(Q240<>0,(S240-Q240)/Q240,\"0\")","v":"0"}]
[]
[]
[null,"Customer contributions - customer specific demand investment - contributions associated with apportionment rule - Table 9"]
[]
[null,null,null,"DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,"Customer contributions - customer specific demand investment","Units","2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,"Customer contributions (directs) for connections at LV"]
[null,"Small scale LV domestic and one-off commercial","£m"]
[null,"All other LV (with only LV work)"]
[null,"LV total","£m",null,null,null,null,null,{"$f":"SUM(I248:I249)","v":0},{"$f":"SUM(J248:J249)","v":0},{"$f":"SUM(K248:K249)","v":0},{"$f":"SUM(L248:L249)","v":0},{"$f":"SUM(M248:M249)","v":0},null,{"$f":"SUM(D250:G250)","v":0},{"$f":"SUM(H250)","v":0},{"$f":"SUM(D250:H250)","v":0},null,{"$f":"SUM(I250:M250)","v":0},{"$f":"IF(Q250<>0,(S250-Q250)/Q250,\"0\")","v":"0"}]
[null,"Customer contributions (directs) for connections with HV work"]
[null,"LV end connections involving HV work","£m"]
[null,"HV end connections involving only HV work","£m"]
[null,"HV total","£m",null,null,null,null,null,{"$f":"SUM(I252:I253)","v":0},{"$f":"SUM(J252:J253)","v":0},{"$f":"SUM(K252:K253)","v":0},{"$f":"SUM(L252:L253)","v":0},{"$f":"SUM(M252:M253)","v":0},null,{"$f":"SUM(D254:G254)","v":0},{"$f":"SUM(H254)","v":0},{"$f":"SUM(D254:H254)","v":0},null,{"$f":"SUM(I254:M254)","v":0},{"$f":"IF(Q254<>0,(S254-Q254)/Q254,\"0\")","v":"0"}]
[null,"Customer contributions (directs) for connections with EHV work"]
[null,"HV end connections involving EHV work","£m"]
[null,"EHV end connections involving only EHV work","£m"]
[null,"EHV total","£m",null,null,null,null,null,{"$f":"SUM(I256:I257)","v":0},{"$f":"SUM(J256:J257)","v":0},{"$f":"SUM(K256:K257)","v":0},{"$f":"SUM(L256:L257)","v":0},{"$f":"SUM(M256:M257)","v":0},null,{"$f":"SUM(D258:G258)","v":0},{"$f":"SUM(H258)","v":0},{"$f":"SUM(D258:H258)","v":0},null,{"$f":"SUM(I258:M258)","v":0},{"$f":"IF(Q258<>0,(S258-Q258)/Q258,\"0\")","v":"0"}]
[null,"Customer contributions (directs) for connections with 132kV work"]
[null," HV or EHV connections involving 132kV work","£m"]
[null,"132kV end connections involving only 132kV work","£m"]
[null,"132kV total","£m",null,null,null,null,null,{"$f":"SUM(I260:I261)","v":0},{"$f":"SUM(J260:J261)","v":0},{"$f":"SUM(K260:K261)","v":0},{"$f":"SUM(L260:L261)","v":0},{"$f":"SUM(M260:M261)","v":0},null,{"$f":"SUM(D262:G262)","v":0},{"$f":"SUM(H262)","v":0},{"$f":"SUM(D262:H262)","v":0},null,{"$f":"SUM(I262:M262)","v":0},{"$f":"IF(Q262<>0,(S262-Q262)/Q262,\"0\")","v":"0"}]
[null,"Total customer contributions associated with apportionment rule",null,{"$f":"SUM(D250,D254,D258,D262)","v":0},0,0,0,0,0,0,0,0,0,null,{"$f":"SUM(O250,O254,O258,O262)","v":0},{"$f":"SUM(P250,P254,P258,P262)","v":0},{"$f":"SUM(Q250,Q254,Q258,Q262)","v":0},null,{"$f":"SUM(S250,S254,S258,S262)","v":0},{"$f":"IF(Q263<>0,(S263-Q263)/Q263,\"0\")","v":"0"}]
[]
[]
[null,null,null,{"$f":"SUM(D240:M240) - SUM(D263:M263)","v":0}]

{"sheet":"FBPQ LR4","index":15,"n_rows":121,"n_cols":41,"rows_kept":121,"cut":false,"hidden":false,"merged":[[42,35,43,35],[43,21,43,30],[6,18,6,19],[42,2,42,10],[42,11,42,15],[42,16,42,20],[42,21,42,34],[31,2,32,2],[23,2,24,2]]}
["June Forecast Business Plan DPCR5"]
["EDFE SPN"]
["LR4 - General reinforcement"]
[]
[null,"General reinforcement expenditure"]
[]
[null,null,null,"DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,null,null,"(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)",null,"(£m)","(£m)","(£m)",null,"(£m)","(£m)"]
[null,null,"General reinforcement:"]
[null,null,"LV System",1.1284494913874921,1.3414500463147323,0.79348913117546849,1.0013579221453288,1.1085926989968014,1.0537833919966832,1.0312306586243754,1.0289736351869729,1.129259125021439,1.1401863611956096,null,{"$f":"SUM(D11:G11)","v":4.2647465910230213},{"$f":"H11","v":1.1085926989968014},{"$f":"SUM(D11:H11)","v":5.3733392900198229},null,{"$f":"SUM(I11:M11)","v":5.3834331720250796},{"$f":"IF(Q11<>0,(S11-Q11)/Q11,\"0\")","v":1.8785119383778017E-3}]
[null,null,"HV System",2.5732252698082219,4.2307270691464636,4.5625625042589437,1.8914538529411764,1.9954668581942427,2.9505934975907131,2.9905689100106878,2.984023542042221,3.0797976136948333,3.3169057780235915,null,13.257968696154805,1.9954668581942427,15.253435554349048,null,15.321889341362045,4.4877619057746877E-3]
[null,null,"EHV System",2.7728870482237062,8.771019533596327,8.2324497359454867,12.57260502249135,11.751082609366092,16.649777593547597,20.830859304212382,11.01001789650061,10.779291647931917,5.3899718892883355,null,32.348961340256871,11.751082609366092,44.100043949622965,null,64.659918331480839,0.46620983882338402]
[null,null,"132kV System",9.3578625829313111,5.8817425107645951,1.7853505451448042,3.2265977491349478,17.51576464414946,6.2173220127804321,5.0530302272594394,14.302733529098925,14.988348386648187,21.145274334900392,null,20.251553387975662,17.51576464414946,37.767318032125118,null,61.706708490687376,0.6338652492665553,null,null," "]
[null,null,"Expenditure on DSM to avoid general reinforcement",null,null,null,0,0,0,0,0,0,0,null,0,0,{"$f":"SUM(D15:H15)","v":0},null,0,"0"]
[null,null,"Total",15.832424392350731,20.224939159822117,15.373851916524703,18.692014546712805,32.3709068107066,26.871476495915427,29.905689100106883,29.325748602828728,29.976696773296375,30.992338363407928,null,70.123230015410343,32.3709068107066,102.49413682611694,null,147.07194933555533,0.43493036665175699]
[]
[null,null,"Expenditure avoided due to DG",null,null,null,0,0,0,0,0,0,0,null,{"$f":"SUM(D18:G18)","v":0},{"$f":"H18","v":0},0,null,{"$f":"SUM(I18:M18)","v":0},{"$f":"IF(Q18<>0,(S18-Q18)/Q18,\"0\")","v":"0"}]
[null,null,"Expenditure avoided due to DSM",null,null,null,0,0,0,0,0,0,0,null,{"$f":"SUM(D19:G19)","v":0},{"$f":"H19","v":0},0,null,{"$f":"SUM(I19:M19)","v":0},{"$f":"IF(Q19<>0,(S19-Q19)/Q19,\"0\")","v":"0"}]
[]
[]
[null,"General reinforcement outputs"]
[]
[null,null,"Changes in general utilisation due to projected expenditure levels","At 31st March 2010",null,null,null,"At 31st March 2015",null,null,null,"At 31st March 2010","At 31st March 2015"]
[null,null,null,"132kV-EHV","132kV - HV","EHV - EHV","EHV - HV","132kV-EHV","132kV - HV","EHV - EHV","EHV - HV","Total","Total"]
[null,null,"Total number substations (operated by DNO)",null,null,null,null,null,null,null,null,{"$f":"SUM(D26:G26)","v":0},{"$f":"SUM(H26:K26)","v":0}]
[null,null,"Σ substation maximum demands",null,null,null,null,null,null,null,null,{"$f":"SUM(D27:G27)","v":0},{"$f":"SUM(H27:K27)","v":0}]
[null,null,"Σ substation firm capacities ",null,null,null,null,null,null,null,null,{"$f":"SUM(D28:G28)","v":0},{"$f":"SUM(H28:K28)","v":0}]
[null,null,"Σ substation maximum demands / Σ substation firm capacities ",{"$f":"IF(D27,D27/D28,\"-\")","v":"-"},{"$f":"IF(E27,E27/E28,\"-\")","v":"-"},"-","-","-","-","-","-","-","-"]
[]
[]
[null,null,"Changes in utilisation of highly loaded substations due to projected expenditure levels","At 31st March 2010",null,null,null,"At 31st March 2015",null,null,null,"At 31st March 2010","At 31st March 2015"]
[null,null,null,"132kV-EHV","132kV - HV","EHV - EHV","EHV - HV","132kV-EHV","132kV - HV","EHV - EHV","EHV - HV","Total","Total"]
[null,null,"Number of substations loaded >=80% of firm capacity",null,null,null,null,null,null,null,null,{"$f":"SUM(D34:G34)","v":0},{"$f":"SUM(H34:K34)","v":0}]
[null,null,"Σ substation maximum demands for substations loaded >=80% of firm capacity",null,null,null,null,null,null,null,null,0,0]
[null,null,"Σ substation firm capacities for substations loaded >=80% of firm capacity",null,null,null,null,null,null,null,null,0,0]
[null,null,"% Loading of substations which are operating at >=80% of firm capacity  = Σ demand /Σ firm capacity ",{"$f":"IF(D35,D35/D36,\"-\")","v":"-"},{"$f":"IF(E35,E35/E36,\"-\")","v":"-"},"-","-","-","-","-","-","-","-"]
[null,null,"Number of substations loaded above 100% of firm capacity",null,null,null,null,null,null,null,null,0,0]
[null,null,"Number of DNO substations requiring reinforcement within 5 yrs",null,null,null,null,null,null,null,null,0,0]
[]
[null,"General reinforcement projects"]
[]
[null,null,"Scheme details",null,null,null,null,null,null,null,null,"DPCR4 Expenditure",null,null,null,null,"DPCR5 Expenditure",null,null,null,null,"Utilisation",null,null,null,null,null,null,null,null,null,null,null,null,null,"(N-2) scheme?","Scheme description"]
[null,null,"Named scheme","Primary Voltage","Secondary Voltage","Limiting \nFactor","Forecast year in which substation demand will reach substation/group firm capacity","Planned reinforce-ment Year","MVA of additional firm capacity to be installed","Total cost of project","Total cost of project in DPCR5 period","2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15","Historic and forecast max demand (MVA)",null,null,null,null,null,null,null,null,null,"Substation/Group Total\nCapability","Substation/group firm capacity under single circuit outage conditions","Substation/Group Maximum Demand","Season of critical loading condition",null,"Brief description of work involved, substations affected, assets installed/replaced etc."]
[null,null,"(Unique name)","(kV)","(kV)","(a-j)","(Year)","(Year)","(MVA)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15","(MVA)","(MVA)","(MVA)","Season","(Y/N)","(Description)"]
[null,1,"Banbury group, Brackley SCO","132kV","132kV","c",2013,null,189,0.41111456795038348,0.41111456795038348,0,0,0,0,0,0,0,0.2057947270373946,0.20531984091298891,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of a third 132kV circuit. Costs split across East and West. Wayleaves only in DPCR5, construction in DPCR6."]
[null,2,"Bishops Castle 33/11kV Transformer reinforcement, switchgear automation","33kV","33kV","a",2007,null,6.5,0.73313782772321678,0.73313782772321678,0,0,0,0,0,0.52689169599834162,0.2062461317248751,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of an additional 6/12MVA transformer at Bishops Castle. Replacement of 11kV switchgear"]
[null,3,"Bishops Castle-Priestweston Interconnection","33kV","33kV","c",2012,null,15,0.6159595227389667,0.6159595227389667,0,0,0,0,0,0,0,0,0.6159595227389667,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Construction of 33kV interconnector between Bishops Castle and Priestweston (10km)"]
[null,4,"Bishops Cleeve 66/11kV reinforcement","11kV","11kV","c",2009,null,19.75,1.085,1.085,0,0,0,0,0,1.085,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of second 66/11kV transformer and 66kV section switch"]
[null,5,"Bixhead 33/11kV reinforcement","33kV","33kV","a",2008,null,24,0.72186146103706272,0.72186146103706272,0,0,0,0,0,0,0.72186146103706272,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Upgrading two transformers and installation of a crossbay CB between T1 & T2."]
[null,6,"Bloxham 66/11kV reinforcement","66kV","66kV","a & c",2013,null,24,0.5182665278161861,0.5182665278161861,0,0,0,0,0,0,0,0,0,0.5182665278161861,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of a second 12/24MVA transformer"]
[null,7,"Bodenham Second 66/11kV Transformer & install 66kV bus section","66kV","66kV","c",2014,null,13,0.5182665278161861,0.5182665278161861,0,0,0,0,0,0,0,0,0,0.5182665278161861,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Commissioning of the transformer currently in position at Bodenham and installation of a 66kV bus-section circuit breaker.",null,null,null," "]
[null,8,"Bromyard 66kV Breaker ","66kV","66kV","g",2008,null,13,0.21075667839933671,0.21075667839933671,0,0,0,0,0,0.21075667839933671,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of a 66kV mesh circuit breaker"]
[null,9,"Cheadle 33/11kV reinforcement","33kV","33kV","a",2011,null,14,1.3352912951210363,1.3352912951210363,0,0,0,0,0,0,0,0.30869209055609192,1.0265992045649444,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Replacement of transformers with 12/24MVA units."]
[null,10,"Chipping Sod - P2/5, Hammerley Down circuit","33kV","33kV","j",2007,null,20,0.31613501759900503,0.31613501759900503,0,0,0,0,0,0.31613501759900503,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rebuilding overhead line - 7km"]
[null,11,"Chipping Sodbury 33kV Reinforcement","33kV","33kV","j",2010,null,56,2.2935154556831643,2.2935154556831643,0,0,0,0,0,1.1591617311963516,1.1343537244868129,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of 1 transformer BSP at Iron Acton. Includes 33kV connection and rebuild of Iron Acton - Alveston circuit"]
[null,12,"Comet Bridge 33/11kV Reinforcement (aka Monkmoor or Spring Gardens)","33kV","33kV","a",2006,null,14,6.3127833919966836,1.0537833919966832,0,0,0,1.4,3.859,1.0537833919966832,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of a new 33/11kV substation at Spring Gardens near existing primary site and dismantlement of Comet Bridge. "]
[null,13,"Cotes Heath 33/11kV S/S reinforcement","33kV","33kV","a",2010,null,7.5,0.41474753678698095,0.41474753678698095,0,0,0,0,0,0.10537833919966835,0.30936919758731257,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of an additional transformer, 33kV crossbay and extension of 11kV board"]
[null,14,"Cowhorn 33/11kV reinforcement","33kV","33kV","a",2007,null,24,2.0602042938113483,2.0602042938113483,0,0,0,0,0,0,1.0312306586243754,1.0289736351869729,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of third 12/24MVA transformer, 33kV crossbay and additional 11kV switchboard."]
[null,15,"Craven Arms reinforcement","33kV","33kV","a",2008,null,3.25,1.7643684863475919,1.7643684863475919,0,0,0,0,0,0.52689169599834162,1.2374767903492503,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Upgrading T2 from 5MVA to 15MVA. Establishing a new 33kV bay at Ludlow and a new 33kV circuit (15km) to Craven Arms."]
[null,16,"Dudbridge 33/11kV reinforcement","33kV","33kV","a",2008,null,5.25,1.235421987818663,1.235421987818663,0,0,0,0,0,0,0.51561532931218768,0.51448681759348647,0.20531984091298891,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Upgrading at least 2 transformers to 12/24MVA and installation of a 33kV cross-bay."]
[null,17,"Dymock 66/11","66kV","66kV","c",2008,null,4.75,0.51561532931218768,0.51561532931218768,0,0,0,0,0,0,0.51561532931218768,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Option of installation of second transformer or strengthening 11kV interconnection"]
[null,18,"Elmdon 132kV crossbay re-configuration","132kV","132kV","g",2013,null,39,0.20531984091298891,0.20531984091298891,0,0,0,0,0,0,0,0,0.20531984091298891,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reinstallation of CB120 on cross-bay and associated protection modifications"]
[null,19,"Endon reinforcement","33kV","33kV","a",2007,null,14.25,0.94389450612255343,0.94389450612255343,0,0,0,0,0,0.73764837439767827,0.2062461317248751,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Upgrading transformers with 12/24 MVA units & rationalisation of substation layout"]
[null,20,"Evesham 66/11kV reinforcement","66kV","66kV","a",2009,null,39,1.6860534271946936,1.6860534271946936,0,0,0,0,0,1.6860534271946936,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of an additional 66/11kV transformer and 11kV switch board "]
[null,21,"Feckenham - Bevington dual circuit steel tower line uprating ","66kV","66kV","j",2008,null,28,1.4421430056679436,1.4421430056679436,0,0,0,0,0,0,0.72186146103706272,0.72028154463088101,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uprating the Feckenham – Bevington - Evesham circuits using 200AAAC POPLAR conductor"]
[null,22,"Forest Ring-Bixhead to Stowfield tee","33kV","33kV","j",2007,null,22,0.52689169599834162,0.52689169599834162,0,0,0,0,0,0.52689169599834162,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rebuilding the Bixhead-Stowfield tee 33kV OHL"]
[null,23,"Forsbrook/Meaford 33kV interconnection","132kV","132kV","c",2011,null,58,2.0555728397519175,2.0555728397519175,0,0,0,0,0,0,0,1.0289736351869729,1.0265992045649444,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reinforcement of 33kV interconnection between Meaford and Forsbrook BSP. Allows indefinite deferral of Meaford reinforcement."]
[null,24,"Gloucester / Iron Acton Z Route","132kV","132kV","a",2013,null,170,12.901953590954676,12.901953590954676,0,0,0,0,0,0,2.4749535806985006,2.4695367244487354,2.4638380909558668,5.4936251948515729,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rebuilding Z route and interconnection from Iron Acton to Cambridge Arms switching site "]
[null,25,"Gnosall 11kV reinforcement","33kV","33kV","c",2011,null,5,0.2057947270373946,0.2057947270373946,0,0,0,0,0,0,0,0.2057947270373946,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reinforcement of 11kV circuits to enable at least 5MVA transfers from High Offley"]
[null,26,"Hereford - Ledbury 66kV OHL reinforcement","66kV","66kV","j",2009,null,43,0.92810759276193777,0.92810759276193777,0,0,0,0,0,0,0.92810759276193777,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uprating line by rebuilding / refurbishment (19km)"]
[null,27,"Hereford BSP GT3 replacement","132kV","132kV","a",2009,null,56.75,0.84302671359734682,0.84302671359734682,0,0,0,0,0,0.84302671359734682,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Complete reinstallation of GT3 (new transformer delivered to Upton Warren in 2008)"]
[null,28,"Hereford South Additional Capacity","66kV","66kV","a",2010,null,39,5.9634182587179625,5.9634182587179625,0,0,0,0,0,0,1.0312306586243754,1.9550499068552485,2.9771376932383387,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Establishing new substation on reserved site (Wide Marsh Street)"]
[null,29,"High Offley reinforcement","33kV","33kV","g",2008,null,10,0.2062461317248751,0.2062461317248751,0,0,0,0,0,0,0.2062461317248751,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of additional transformer (10/15MVA)"]
[null,30,"Hill Chorlton 33/11kV S/S reinforcement","33kV","33kV","a",2007,null,12,0.31613501759900503,0.31613501759900503,0,0,0,0,0,0.31613501759900503,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uprating transformer to 7.5/15MVA and possible 11kV reinforcement / interconnection to Coates Heath."]
[null,31,"Hinksford 132kV reinforcement and 132kV siwtchgear replacement (new 2 switch crossbay)","132kV","132kV","g",2010,null,13,2.0602042938113483,2.0602042938113483,0,0,0,0,0,0,1.0312306586243754,1.0289736351869729,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Replacement of 132kV switchgear, upgrading single switch crossbay to 2 switches. Removal of redundant plant. Re routing cables"]
[null,32,"Hinstock 33/11kV S/S reinforcement","33kV","33kV","a",2010,null,6.5,0.52012587598664928,0.52012587598664928,0,0,0,0,0,0.21075667839933671,0.30936919758731257,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of additional 7.5/15MVA transformer or uprating existing units"]
[null,33,"Hookgate 33/11kV S/S reinforcement","33kV","33kV","a",2008,null,5,0.30797976136948335,0.30797976136948335,0,0,0,0,0,0,0,0,0.30797976136948335,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of an additional transformer or 11kV reinforcement"]
[null,34,"Ironbridge - Halesfield & Madeley 33kV Reinforcement","33kV","33kV","c",2009,null,28,2.9883118865732858,2.9883118865732858,0,0,0,0,0,0,1.9593382513863129,1.0289736351869729,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of new 33kV circuits from Ironbridge to Madeley and from Madeley to Halesfield. Installation of a 33kV crossbay at Madeley."]
[null,35,"Ketley BSP reinforcement","132kV","132kV","c",2010,null,51,1.9550499068552485,1.9550499068552485,0,0,0,0,0,0,0,1.9550499068552485,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reinforcement of 33kV interconnection or 132/33kV reinforcement"]
[null,36,"Knypersley-Goldenhill-Talke Cct reinforcement","33kV","33kV","j",2008,null,20,0.30936919758731257,0.30936919758731257,0,0,0,0,0,0,0.30936919758731257,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uprating Knypersley-Goldenhill-Talke 33kV circuit (10km). Rebuilding 1.3km of OH and overlay 1.4km of UG cable."]
[null,37,"Ladywood / Winson Green SCO security","132kV","132kV","c",2012,null,100,6.1056111771635688,6.1056111771635688,0,0,0,0,0,0,0,0,1.0265992045649444,5.0790119725986242,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of third 132kV circuit from Bustleholm to Winson Green or Ladywood or 132kV interconnector from Ladywood to Summer Lane."]
[null,38,"Lichfield/Rugeley T group reinforcement (Lichfield - Burntwoodinterconnector)","132kV","132kV","c",2011,null,100,2.9960120102664511,2.9960120102664511,0,0,0,0,0,0,0,0,1.0265992045649444,1.969412805701507,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Unpicking Rugeley T circuit. 132kV Burntwood -Lichfield interconnection following route of redundant 33kV OHLs."]
[null,39,"Lower Chadnor","33kV","33kV","c",2008,null,5,0.2057947270373946,0.2057947270373946,0,0,0,0,0,0,0,0.2057947270373946,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"11kV reinforcement"]
[null,40,"Malehurst 33/11kV reinforcement","33kV","33kV","a",2007,null,14.25,0.93148962771769828,0.93148962771769828,0,0,0,0,0,0.21075667839933671,0.2062461317248751,0.51448681759348647,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uprating two 7.5MVA transformers with two 12/24MVA units and replacement of 11kV switchboard"]
[null,41,"Market Drayton 33/11kV reinforcement","33kV","33kV","a",2007,null,24,0.73764837439767827,0.73764837439767827,0,0,0,0,0,0.73764837439767827,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of additional third transformer (12/24 MVA)"]
[null,42,"Meaford West 33kV network Reinforcement (PHASE 2:Meaford - Hookgate (tee Market Drayton) 4th 33kV circuit)","33kV","33kV","j",2007,null,21,2.0850140506210586,2.0850140506210586,0,0,0,0,0,1.0537833919966832,1.0312306586243754,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Establishment of 4th Meaford - Hookgate (tee Market Drayton) 33kV circuit"]
[null,43,"Moreton 66/11kV reinforcement","66kV","66kV","a",2008,null,14.25,3.0334191034180735,3.0334191034180735,0,0,0,0,0,2.0021884447936982,1.0312306586243754,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uprating transformers at Moreton to 12/24MVA units and improving 11kV alternative supplies to Stow."]
[null,44,"New Birmingham City Centre primary Substation (site acquisition + preps only)","132kV","132kV","a",2013,null,78,1.0365330556323722,1.0365330556323722,0,0,0,0,0,0,0,0,0,1.0365330556323722,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"New 132/11kV s/s in the eastside of the city centre to support new load and heavily loaded primaries. Acquire site in DPCR5"]
[null,45,"New Whitfield-Knypersley 33kV cct","33kV","33kV","j",2010,null,41,0.41262645203946335,0.41262645203946335,0,0,0,0,0,0,0,0,0.20531984091298891,0.20730661112647447,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of additional (3rd) Whitfield-Knypersley 33kV circuit (at least 41MVA)"]
[null,46,"Newcastle - Scot Hay 33kC cct  reinforcement","33kV","33kV","j",2010,null,11,0.30936919758731257,0.30936919758731257,0,0,0,0,0,0,0.30936919758731257,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uprating Newcastle - Scot Hay 33kV circuit.  Approx 4km 200mm2 AAAC gives 41MVA capacity"]
[null,47,"Newcastle 132/11kV Reinforcement","132kV","132kV","a",2007,null,39,2.5290801407920402,2.5290801407920402,0,0,0,0,0,2.5290801407920402,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of 3rd 132/11kV transformer and 11kV s/board. Replacement of 132/33kV transformer and decommissioning redundant 33kV s/gear"]
[null,48,"Newent reinforcement","66kV","66kV","c",2008,null,12,0.92810759276193777,0.92810759276193777,0,0,0,0,0,0,0.92810759276193777,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Upgrading double circuit 11kV line from Newent to Dymock to 66kV.  Installation of second 6/12MVA transformer at Newent and new 11kV switchboard"]
[null,49,"Oldbury 132/11kV reinforcement","132kV","132kV","c",2010,null,19,0.51561532931218768,0.51561532931218768,0,0,0,0,0,0,0.51561532931218768,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of additional transformer and possible upgrade of 11Kv interconnections"]
[null,50,"Oldbury Group reinforcement","132kV","132kV","c",2010,null,100,5.9611612352805601,5.9611612352805601,0,0,0,0,0,0,0,2.984023542042221,2.9771376932383387,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of a 132kV interconnection from Ocker Hill to Tividale. Installation of additional 132kV GIS switchgear required at Tividale. "]
[null,51,"Pattingham 33kV crossbay re-configuration","33kV","33kV","g",2012,null,6,0.1028973635186973,0.1028973635186973,0,0,0,0,0,0,0,0.1028973635186973,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of 33kV CB on crossbay and associated protection modifications"]
[null,52,"Pontrilas voltage regulator","66kV","66kV","c",2007,null,3,0.31613501759900503,0.31613501759900503,0,0,0,0,0,0.31613501759900503,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of pole mounted voltage regulators to support the 11kV network."]
[null,53,"Presteigne - Knighton 66kV new line","66kV","66kV","c",2008,null,10,1.2645400703960201,1.2645400703960201,0,0,0,0,0,1.2645400703960201,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of second 66kV line between Presteigne and Kington"]
[null,54,"Priestweston 33/11kV S/S reinforcement","33kV","33kV","c",2013,null,6.5,0.51329960228247218,0.51329960228247218,0,0,0,0,0,0,0,0,0.51329960228247218,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of second 33/11kV transformer or 11kV interconnection."]
[null,55,"Quatt-Wribbenhall-Kinver 33kV ccts reinforcement","33kV","33kV","j",2012,null,10,1.5547995834485584,1.5547995834485584,0,0,0,0,0,0,0,0,0,1.5547995834485584,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Rebuilding Quatt-Wribbenhall - Kinver 33kV circuits"]
[null,56,"Quedgeley Primary","33kV","33kV","a",2008,null,39,7.9216279983855742,7.9216279983855742,0,0,0,0,0,0,2.4749535806985006,2.4695367244487354,2.9771376932383387,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of new Quedgeley 132/11kV substation"]
[null,57,"Rugeley GSP reinforcement","132kV","132kV","c",2012,null,240,3.0059458613338794,3.0059458613338794,0,0,0,0,0,0,0,0,0,3.0059458613338794,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of new GSP near Burntwood. Discussions with NG still ongoing on options (3rd SGT and circuit or new GSP)"]
[null,58,"Selly Oak reinforcement","132kV","132kV","a",2011,null,39,2.0555728397519175,2.0555728397519175,0,0,0,0,0,0,0,1.0289736351869729,1.0265992045649444,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of additional transformer and 11kV switchgear section"]
[null,59,"Shifnal primary reinforcement","33kV","33kV","a",2014,null,8.5,1.0365330556323722,1.0365330556323722,0,0,0,0,0,0,0,0,0,1.0365330556323722,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uprating 2 x 5MVA transformers with 7.5/15MVA units"]
[null,60,"Shrewsbury - Harlescott 33kV reinforcement","33kV","33kV","f",2008,null,31,0.84302671359734682,0.84302671359734682,0,0,0,0,0,0.84302671359734682,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Construction of new 33kV OHL between Shrewsbury and Harlescott.  "]
[null,61,"Shrewsbury 132/33kV Grid Transformer Reinforcement","132kV","132kV","a",2013,null,117,3.1354746714435837,3.1354746714435837,0,0,0,0,0,1.5806750879950251,0,0,0,1.5547995834485584,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of a third 132/33kV transformer (90MVA).  Transfer of assets from NG in 2010"]
[null,62,"Snedshill 33/11kV reinforcement","33kV","33kV","a",2007,null,18,1.5806750879950251,1.5806750879950251,0,0,0,0,0,1.5806750879950251,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uprating 20MVA TX at Snedshill to 20/40MVA unit.  Installation of 33kV s/gear at Ketley BSP.  Rectify Snedshill 11kV s/gear restrictions."]
[null,63,"St. Weonards reinforcement","11kV","11kV","c",2008,null,4,0.86050000000000004,0.86050000000000004,0,0,0,0,0,0.32550000000000001,0.53500000000000003,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"11kV reinforcement"]
[null,64,"Stafford Grid","132kV","132kV","a",2008,null,54,1.5693987213088709,1.5693987213088709,0,0,0,0,0,1.0537833919966832,0.51561532931218768,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uprating 30MVA transformer for 60MVA, commission second winding of 60MVA Transformer and extend switchboard"]
[null,65,"Stagefields 132/11kV reinforcement (switchboard extension) + reinforcement","132kV","132kV","a",2011,null,78,2.0590757820926471,2.0590757820926471,0,0,0,0,0,0,0.51561532931218768,1.5434604527804594,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of third 132/11kV transformer and additional 11kV switchgear"]
[null,66,"Stockton and Cleobury Mortimer Reinforcement","33kV","33kV","a",2006,null,10.5,1.3473656762233803,1.3473656762233803,0,0,0,0,0,0.31613501759900503,1.0312306586243754,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of a crossbay at Cleobury Mortimer, a 33kV circuit from the Ludlow – Stockton 33kV circuit to Cleobury Mortimer tee, and 2 x 7.5/15MVA transformers at Cleobury Mortimer."]
[null,67,"Stowfield reinforcement","33kV","33kV","c",2007,null,2,0.30936919758731257,0.30936919758731257,0,0,0,0,0,0,0.30936919758731257,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of interposing transformer to address phasing conflict. 11kV interconnection capacity to be reinforced."]
[null,68,"Summer Lane 132/11kV Reinforcement","132kV","132kV","g",2010,null,39,1.0289736351869729,1.0289736351869729,0,0,0,0,0,0,0,1.0289736351869729,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"132kV mesh re-configuration. "]
[null,69,"Tean 33/11kV reinforcement ","33kV","33kV","a",2008,null,17.5,1.6567348738106928,1.6567348738106928,0,0,0,0,0,0.31613501759900503,1.3405998562116879,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of 11kV interconnector from Cheadle and uprating transformers from 2 x 5MVA to 2 x 12/24MVA units"]
[null,70,"Walsall 132kV reconfiguration (to unpick temporary Bentley GT2 feeder tee to Walsall GT4)","132kV","132kV","g",2009,null,0,0.21075667839933671,0.21075667839933671,0,0,0,0,0,0.21075667839933671,0,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Unpick tee and prepare for link into 132kV feeder bay (403)"]
[null,71,"Weir Hill Roushill group reinforcement \nRoushill 33/11kV Substation & Rowton, harlescott, Malehurst, etc 33kV Ring","33kV","33kV","b",2010,null,31,5.4603879789772005,5.4603879789772005,0,0,0,0,0,0,0,1.9550499068552485,1.9505384886733943,1.5547995834485584,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Transfer Roushill demand to Spring Gardens. Extension of the 33kV circuits from Roushill to the Rowton - Harlescott 33kV circuit."]
[null,72,"Whitfield - Endon 33kV Works (Whit End)","33kV","33kV","f,j",2007,null,14,0.41474753678698095,0.41474753678698095,0,0,0,0,0,0.10537833919966835,0.30936919758731257,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Reinforcement of circuit to 41MVA. Reconfiguration of circuits to teed transformer feeders."]
[null,73,"Whitfield 132kV group network reinforcement","132kV","132kV","b",2012,null,150,9.0652555988890811,9.0652555988890811,0,0,0,0,0,0,0,1.0289736351869729,5.0303361023682278,3.0059458613338794,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Installation of third 132kV circuit from Cellarhead to Whitfield or additional circuit from Cellarhead to supply SP Manweb directly, offloading the Cellarhead to Whitfield circuits."]
[null,74,"Whitfield 33/11kV reinforcement","33kV","33kV","a",2008,null,14.25,1.0425070253105293,1.0425070253105293,0,0,0,0,0,0.52689169599834162,0.51561532931218768,0,0,0,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Uprating transformers to 2 x 12/24 units"]
[null,75]
[null,null,"Total",null,null,null,null,null,{"$f":"SUM(I46:I120)","v":2633.25},133.57112682216822,128.31212682216821,0,0,0,1.4,3.859,24.277599606328032,26.418889531471816,25.312751425599526,25.767640034580104,26.535246224188732,{"$f":"SUM(V46:V120)","v":0},{"$f":"SUM(W46:W120)","v":0},0,0,0,0,0,0,0,0,0,0,0]

{"sheet":"FBPQ LR6","index":16,"n_rows":32,"n_cols":19,"rows_kept":32,"cut":false,"hidden":false,"merged":[[23,1,25,1],[9,1,9,2],[10,1,10,2],[11,1,11,2],[7,1,8,2],[15,1,16,2],[17,1,17,2],[18,1,18,2],[19,1,19,2]]}
["Main Forecast Business Plan DPCR5",null,null,null,null,"Index"]
[]
["LR6 - Fault levels"]
[]
[]
[null,"Fault level system measures"]
[]
[null,null,null,"As at 31st March 2010",null,null,"As at 31st March 2015"]
[null,null,null,"132kV","EHV","HV","132kV","EHV","HV"]
[null,"No. of switchboards",null,50,175,411,51,177,420]
[null,"No. of switchboards @ >95% of F.L.",null,5,12,32,5,10,30]
[null,"No. of switchboards having fault level 'operational restrictions'",null,5,12,32,5,10,30]
[]
[null,"Number of fault level schemes"]
[]
[null,"No. of schemes",null,"DPCR4",null,null,"DPCR5"]
[null,null,null,"132kV","EHV","HV","132kV","EHV","HV"]
[null,"Switchboards",null,0,0,0,4,3,0]
[null,"Transformers",null,0,0,0,0,0,0]
[null,"Other",null,0,0,0,0,0,0]
[]
[null,"Fault level reinforcement"]
[]
[null,null,"DPCR4",null,null,null,null,"DPCR5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,null,"(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)","(£m)",null,"(£m)","(£m)","(£m)",null,"(£m)","(£m)"]
[null,"Fault level reinforcement:"]
[null,"LV ",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"HV",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"EHV ",0,0,0,0,0,0,1.2374767903492503,1.7492551798178539,1.2319190454779334,0,null,0,0,0,null,4.2186510156450376,"0"]
[null,"132kV ",0,0,0,0,0,0,0,4.0129971772291944,5.0303361023682278,6.011891722667758,null,0,0,0,null,15.055225002265182,"0"]
[null,"Total expenditure",0,0,0,0,0,0,1.2374767903492503,5.7622523570470481,6.2622551478461617,6.011891722667758,null,0,0,0,null,19.273876017910219,"0"]

{"sheet":"FBPQ NL1 0309","index":17,"n_rows":153,"n_cols":20,"rows_kept":153,"cut":false,"hidden":false,"merged":[[6,1,8,2],[39,1,41,2],[72,1,74,2],[105,1,107,2],[141,1,143,2],[67,1,67,2],[34,1,34,2],[100,1,100,2],[22,1,27,1],[28,1,33,1],[42,1,43,1],[44,1,45,1],[9,1,10,1],[11,1,12,1],[13,1,15,1],[16,1,21,1],[75,1,76,1],[77,1,78,1],[79,1,81,1],[82,1,87,1],[46,1,48,1],[49,1,54,1],[55,1,60,1],[61,1,66,1],[120,1,123,1],[124,1,127,1],[129,1,132,1],[133,1,136,1],[88,1,93,1],[94,1,99,1],[108,1,113,1],[114,1,119,1]]}
["June Forecast Business Plan DPCR5",null,null,null,null,null," "]
["EDFE SPN"]
["NL1 - Condition based expenditure"]
[]
[null,"Total condition based replacement"]
[]
[null,"Asset Categories",null,"DPCR 4",null,null,null,null,"DPCR 5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,null,null,"£m","£m","£m","£m","£m","£m","£m","£m","£m","£m"]
[null,"Metered LV Services","Overhead",0.29829754130088582,0,0.19930757130482524,0.89307592869675823,1.1117532404936123,2.3315957022593938,2.3858703688355409,2.5898619825362434,2.6870814154358671,2.9234021642228014,null,{"$f":"SUM(D10:G10)","v":1.3906810413024693},{"$f":"H10","v":1.1117532404936123},{"$f":"SUM(D10:H10)","v":2.5024342817960816},null,{"$f":"SUM(I10:M10)","v":12.917811633289846},{"$f":"IF(Q10<>0,(S10-Q10)/Q10,\"0\")","v":4.162098252593589}]
[null,null,"Underground",1.1931901652035435,1.8921689777536406,3.7868438547916794,0.33490347326128433,0.88940259239488995,0.42392649131988985,0.51866747148598735,0.51797239650724869,0.62009571125443097,0.73085054105570035,null,{"$f":"SUM(D11:G11)","v":7.2071064710101478},{"$f":"H11","v":0.88940259239488995},{"$f":"SUM(D11:H11)","v":8.096509063405037},null,{"$f":"SUM(I11:M11)","v":2.8115126116232574},{"$f":"IF(Q11<>0,(S11-Q11)/Q11,\"0\")","v":-0.65275001984116121}]
[null,"Un-metered LV Services","Overhead",0,0,0,0,0,0,0,0,0,0,null,0,0,{"$f":"SUM(D12:H12)","v":0},null,{"$f":"SUM(I12:M12)","v":0},{"$f":"IF(Q12<>0,(S12-Q12)/Q12,\"0\")","v":"0"}]
[null,null,"Underground",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"LV System","Overhead mains",0,0.59752704560641279,0.59792271391447571,1.5628828752193269,1.7788051847897797,2.8615038164092561,3.0082713346187262,3.3150233376463918,3.5138756971084417,3.7586599254293169,null,2.7583326347402153,1.7788051847897797,4.5371378195299954,null,16.457334111212134,2.6272502105560811]
[null,null,"Underground mains",1.5909202202713912,1.9917568186880426,5.4809582108826937,4.6886486256579802,5.7811168505667831,4.9811362730087048,6.1202761635346494,7.4588025097043795,8.6813399575620327,10.231907574779804,null,13.752283875500108,5.7811168505667831,19.53340072606689,null,37.473462478589568,0.91843002680951824]
[null,null,"Switchgear (incl other plant & equipment)",2.1875153028731629,2.6888717052288578,2.4913446413103153,1.4512483841322323,1.889980508839141,2.1196324565994491,2.1784033802411464,2.1754840653304446,2.2736842745995802,2.4013660634687297,null,8.8189800335445696,1.889980508839141,10.708960542383711,null,11.14857024023935,4.1050641293873522E-2]
[null,"HV","Overhead lines",5.8665183122507543,9.1620813659649958,10.363993707850911,12.503063001754613,10.116954488491873,9.9622725460174095,9.0248140038561768,8.3911528234174284,7.8545456758894581,7.4129126307078188,null,37.895656387821276,10.116954488491873,48.012610876313147,null,42.645697679888301,-0.11178132366620776]
[null,null,"Underground cables",1.1931901652035433,1.4938176140160322,4.6837279256633932,1.1163449108709478,1.4452792126416962,0.8478529826397796,1.0373349429719745,1.4503227102202962,1.5502392781360774,1.6705155224130297,null,8.487080615753916,1.4452792126416962,9.9323598283956116,null,6.5562654363811568,-0.33990858671496604]
[null,null,"Submarine",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Switchgear (incl other plant & equipment)",3.5795704956106302,4.879804205785705,4.1854589974013301,4.8002831167450752,4.7805389341225322,5.7230076328185113,7.1576111065066241,7.8731804269101806,6.511004968171525,8.5613920523667755,null,17.44511681554274,4.7805389341225322,22.225655749665272,null,35.826196186773622,0.61192977117506109]
[null,null,"Transformers ",0.1988650275339239,0.89629056840961918,0.69757649956688828,0.89307592869675811,1.2229285645429737,1.9076692109395044,1.9709363916467515,2.2790785446318944,2.4803828450177234,2.8189949440719873,null,2.6858080242071893,1.2229285645429737,3.9087365887501631,null,11.457061936307861,1.9311419882533734]
[null,null,"Substation",2.1875153028731629,0.89629056840961918,1.8934219273958397,2.1210553306548006,3.0017337493327538,3.0734670620692013,3.0082713346187262,3.0042398997420423,2.9971292710630824,3.0278093843736156,null,7.0982831293334216,3.0017337493327538,10.100016878666175,null,15.110916951866667,0.49612789101222177]
[null,"EHV","Overhead lines",0.39773005506784781,9.9587840934402136E-2,0,2.4559588039160856,0.44470129619744503,0.42392649131988985,4.0456062775907,3.8329957341536405,6.5110049681715232,2.5057732836195439,null,2.9532766999183355,0.44470129619744503,3.3979779961157806,null,17.319306754855297,4.096944940388946]
[null,null,"Underground cables",0.79546011013569551,1.0954662502784234,1.1958454278289514,0.11163449108709478,0.11117532404936126,3.0734670620692008,1.5560024144579616,0,1.3435407077179335,0.41762888060325742,null,3.1984062793301655,0.11117532404936126,3.3095816033795269,null,6.3906390648483535,0.93095074565396829]
[null,null,"Submarine",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Switchgear (incl other plant & equipment)",0,0.29876352280320639,0,2.6792277860902742,0.88940259239489006,1.483742719619614,4.2530732661850958,0.6215668758086984,2.1703349893905082,5.1159537873899028,null,2.9779913088934808,0.88940259239489006,3.8673939012883709,null,13.64467163839382,2.5281308257346842]
[null,null,"Transformers ",0.79546011013569562,2.8880473870976617,2.1923832843530775,1.5628828752193269,0.55587662024680617,0.21196324565994493,1.7634694030523566,1.0359447930144974,0.41339714083628726,0.62644332090488597,null,7.4387736568057612,0.55587662024680617,7.9946502770525676,null,4.0512179034679718,-0.49325889650278021]
[null,null,"Substation",1.8892177615722769,0.79670272747521709,1.2954992134813641,2.3443243128289906,2.0011558328885024,1.1657978511296969,0.72613446008038218,0.51797239650724869,0.72344499646350269,2.6101805037703589,null,6.3257440153578486,2.0011558328885024,8.3268998482463505,null,5.7435302079511894,-0.31024387075331766]
[null,"132kV","Overhead lines",9.9432513766961952E-2,4.5810406829824979,6.9757649956688832,12.503063001754615,6.2258181467642295,4.4512281588588438,3.8381392889963055,4.868940527168137,4.2373206935719443,2.0881444030162868,null,24.159301194172958,6.2258181467642295,30.385119340937187,null,19.483773071611516,-0.35877253424634514]
[null,null,"Underground cables",6.363680881085565,9.8591962525058108,3.9861514260965047,0.11163449108709478,1.4452792126416962,6.6768422382882644,0,4.1437791720579895,8.8880385279801768,13.781753059907492,null,20.320663050774975,1.4452792126416962,21.765942263416672,null,33.490412998233921,0.53866129905725568]
[null,null,"Submarine cables",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Switchgear (incl other plant & equipment)",9.7443863491622711,3.0872230689664661,11.858800492637101,8.372586831532109,0.33352597214808372,8.1605849579078793,7.157611106506625,12.949309912681217,10.644976376534398,8.2481703919143321,null,33.062996742297948,0.33352597214808372,33.396522714446029,null,47.160652745544454,0.41214260983957474]
[null,null,"Transformers ",1.590920220271391,8.6641421612929861,2.8899597839199656,1.3396138930451373,0.55587662024680617,2.6495405707493114,8.0912125551814018,10.359447930144972,4.5473685491991596,2.6101805037703585,null,14.484636058529478,0.55587662024680617,15.040512678776285,null,28.257750109045201,0.87877572477431587]
[null,null,"Substation",0.29829754130088582,1.6929932958848362,0,0,0,1.1697794739596694,0.67713446008038214,0.48297239650724866,0.77079428167257447,0.48203610075407166,null,1.9912908371857219,0,1.9912908371857219,null,3.5827167129739466,0.79919308926132371]
[null,"Total non-load replacement (£m)",null,40.270168075619587,57.561772060084429,64.774960674068197,61.845508062250516,44.581304943793853,63.69893694364341,68.51883973044751,77.868048434690195,79.419600325776244,82.024075038540076,null,224.45240887202272,44.581304943793853,269.03371381581655,null,371.52950047309741,0.3809774812366104]
[]
[]
[null,"Proactive condition based replacement (non fault)"]
[]
[null,"Asset Categories",null,"DPCR 4",null,null,null,null,"DPCR 5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,null,null,"£m","£m","£m","£m","£m","£m","£m","£m","£m","£m"]
[null,"Metered LV Services","Overhead",0.29829754130088582,0,0.19930757130482524,0.89307592869675823,1.1117532404936123,2.3315957022593938,2.3858703688355409,2.5898619825362434,2.6870814154358671,2.9234021642228014,null,{"$f":"SUM(D43:G43)","v":1.3906810413024693},{"$f":"H43","v":1.1117532404936123},{"$f":"SUM(D43:H43)","v":2.5024342817960816},null,{"$f":"SUM(I43:M43)","v":12.917811633289846},{"$f":"IF(Q43<>0,(S43-Q43)/Q43,\"0\")","v":4.162098252593589}]
[null,null,"Underground",1.0937576514365814,1.7925811368192384,3.587536283486854,0.22326898217418956,0.77822726834552869,0.31794486848991738,0.41493397718878988,0.41437791720579897,0.51674642604535914,0.62644332090488597,null,6.6971440539168636,0.77822726834552869,7.4753713222623919,null,2.2904465098347515,-0.69360097163152601]
[null,"Un-metered LV Services","Overhead",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Underground",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"LV System","Overhead mains",0,0.59752704560641279,0.59792271391447571,1.5628828752193269,1.7788051847897797,2.8615038164092561,3.0082713346187262,3.3150233376463918,3.5138756971084417,3.7586599254293169,null,2.7583326347402153,1.7788051847897797,4.5371378195299954,null,16.457334111212134,2.6272502105560811]
[null,null,"Underground mains",1.5909202202713912,1.9917568186880426,5.3813044252302813,4.5770141345708852,5.6699415265174222,4.8751546501787324,6.0165426692374524,7.3552080304029301,8.5779906723529606,10.127500354628989,null,13.540995598760599,5.6699415265174222,19.210937125278022,null,36.952396376801062,0.92350826697457555]
[null,null,"Switchgear (incl other plant & equipment)",1.988650275339239,2.4896960233600534,2.29203707000549,1.2279794019580428,1.6676298607404185,1.9076692109395041,1.9709363916467517,1.9682951067275449,2.0669857041814366,2.1925516231671009,null,7.9983627706628244,1.6676298607404185,9.6659926314032436,null,10.106438036662338,4.5566495036232335E-2]
[null,"HV","Overhead lines",5.7670857984837927,9.0624935250305931,10.264339922198499,12.391428510667518,10.005779164442512,9.8562909231874372,8.9210805095589798,8.287558344115979,7.751196390680386,7.3085054105570046,null,37.485347756380399,10.005779164442512,47.491126920822907,null,42.124631578099788,-0.1129999579009807]
[null,null,"Underground cables",0.89489262390265756,1.0954662502784236,3.4878824978344416,0.55817245543547389,0.88940259239489006,0.31794486848991738,0.51866747148598724,0.93235031371304766,1.0334928520907183,1.148479421658958,null,6.0364138274509971,0.88940259239489006,6.9258164198458871,null,3.9509349274386287,-0.42953513521997966]
[null,null,"Submarine",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Switchgear (incl other plant & equipment)",3.1818404405427825,4.2822771601792917,3.6871900691392669,4.3537451523966961,4.3358376379250876,5.2990811414986219,6.7426771293178343,7.4588025097043813,6.0976078273352377,8.1437631717635188,null,15.505052822258039,4.3358376379250876,19.840890460183125,null,33.741931779619591,0.7006258790316493]
[null,null,"Transformers ",9.9432513766961952E-2,0.49793920467201064,0.39861514260965047,0.66980694652256856,1.0005779164442512,1.3777610967896421,1.4522689201607644,1.6575116688231959,1.8602871337632927,2.0881444030162868,null,1.6657938075711916,1.0005779164442512,2.666371724015443,null,8.4359732225531801,2.1638398902044167]
[null,null,"Substation",1.3920551927374671,0.59752704560641279,1.1958454278289514,1.5628828752193267,2.4458571290859474,2.543558947919339,2.4896038631327388,2.4862675032347936,2.4803828450177234,2.5057732836195439,null,4.7483105413921578,2.4458571290859474,7.1941676704781052,null,12.505586442924139,0.73829510455280389]
[null,"EHV","Overhead lines",0.39773005506784781,9.9587840934402136E-2,0,2.4559588039160856,0.44470129619744503,0.42392649131988985,4.0456062775907,3.8329957341536405,6.5110049681715232,2.5057732836195439,null,2.9532766999183355,0.44470129619744503,3.3979779961157806,null,17.319306754855297,4.096944940388946]
[null,null,"Underground cables",0.69602759636873357,0.89629056840961918,0.99653785652412619,0,0,2.8615038164092561,1.3485354258635667,-0.20718895860289949,1.1368421372997899,0.20881444030162871,null,2.5888560213024792,0,2.5888560213024792,null,5.3485068612713409,1.0659730851236964]
[null,null,"Submarine",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Switchgear (incl other plant & equipment)",0,0.29876352280320639,0,2.6792277860902742,0.88940259239489006,1.483742719619614,4.2530732661850958,0.6215668758086984,2.1703349893905082,5.1159537873899028,null,2.9779913088934808,0.88940259239489006,3.8673939012883709,null,13.64467163839382,2.5281308257346842]
[null,null,"Transformers ",0,0,0,0.55817245543547389,0,0.21196324565994493,1.7634694030523566,1.0359447930144974,0.41339714083628726,0.62644332090488597,null,0.55817245543547389,0,0.55817245543547389,null,4.0512179034679718,6.2580039807003738]
[null,null,"Substation",1.8892177615722769,0.79670272747521709,1.2954992134813641,2.3443243128289906,2.0011558328885024,1.1657978511296969,0.72613446008038218,0.51797239650724869,0.72344499646350269,2.6101805037703589,null,6.3257440153578486,2.0011558328885024,8.3268998482463505,null,5.7435302079511894,-0.31024387075331766]
[null,"132kV","Overhead lines",9.9432513766961952E-2,4.5810406829824979,6.9757649956688832,12.503063001754615,6.2258181467642295,4.4512281588588438,3.8381392889963055,4.868940527168137,4.2373206935719443,2.0881444030162868,null,24.159301194172958,6.2258181467642295,30.385119340937187,null,19.483773071611516,-0.35877253424634514]
[null,null,"Underground cables",6.363680881085565,9.8591962525058108,3.9861514260965047,0.11163449108709478,1.4452792126416962,6.6768422382882644,0,4.1437791720579895,8.8880385279801768,13.781753059907492,null,20.320663050774975,1.4452792126416962,21.765942263416672,null,33.490412998233921,0.53866129905725568]
[null,null,"Submarine cables",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Switchgear (incl other plant & equipment)",9.7443863491622711,3.0872230689664661,11.858800492637101,8.372586831532109,0.33352597214808372,8.1605849579078793,7.157611106506625,12.949309912681217,10.644976376534398,8.2481703919143321,null,33.062996742297948,0.33352597214808372,33.396522714446029,null,47.160652745544454,0.41214260983957474]
[null,null,"Transformers ",1.3920551927374671,7.4690880700801596,2.4913446413103153,0.78144143760966334,0,2.0136508337694767,7.468811589398217,9.7378810543362739,3.9272728379447286,1.9837371828654726,null,12.133929341737606,0,12.133929341737606,null,25.131353498314166,1.0711636593983414]
[null,null,"Substation",0.29829754130088582,1.6929932958848362,0,0,0,1.1697794739596694,0.67713446008038214,0.48297239650724866,0.77079428167257447,0.48203610075407166,null,1.9912908371857219,0,1.9912908371857219,null,3.5827167129739466,0.79919308926132371]
[null,"Total proactive condition based replacement (£m)",null,37.187760148843765,51.188150240282695,58.696079749271028,57.826666383115104,41.023694574214289,60.307525013084295,65.199367912937191,74.449430617742351,76.009073913876875,78.474229553412385,null,204.89865652151261,41.023694574214289,245.9223510957269,null,354.43962701105312,0.4412664218271285]
[]
[]
[null,"Reactive condition-based replacement (fault)"]
[]
[null,"Asset Categories",null,"DPCR 4",null,null,null,null,"DPCR 5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,null,null,"£m","£m","£m","£m","£m","£m","£m","£m","£m","£m"]
[null,"Metered LV Services","Overhead",0,0,0,0,0,0,0,0,0,0,null,{"$f":"SUM(D76:G76)","v":0},{"$f":"H76","v":0},{"$f":"SUM(D76:H76)","v":0},null,{"$f":"SUM(I76:M76)","v":0},{"$f":"IF(Q76<>0,(S76-Q76)/Q76,\"0\")","v":"0"}]
[null,null,"Underground",9.9432513766961952E-2,9.9587840934402136E-2,0.19930757130482524,0.11163449108709478,0.11117532404936126,0.10598162282997246,0.10373349429719747,0.10359447930144974,0.10334928520907181,0.10440722015081436,null,0.50996241709328416,0.11117532404936126,0.62113774114264542,null,0.52106610178850588,{"$f":"IF(Q77<>0,(S77-Q77)/Q77,\"0\")","v":-0.16111022197757247}]
[null,"Un-metered LV Services","Overhead",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Underground",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"LV System","Overhead mains",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Underground mains",0,0,9.9653785652412619E-2,0.11163449108709478,0.11117532404936126,0.10598162282997246,0.10373349429719747,0.10359447930144974,0.10334928520907181,0.10440722015081436,null,0.2112882767395074,0.11117532404936126,0.32246360078886865,null,0.52106610178850588,0.61589122156354992]
[null,null,"Switchgear (incl other plant & equipment)",0.1988650275339239,0.19917568186880427,0.19930757130482524,0.22326898217418956,0.22235064809872251,0.21196324565994493,0.20746698859439494,0.20718895860289949,0.20669857041814363,0.20881444030162871,null,0.82061726288174297,0.22235064809872251,1.0429679109804655,null,1.0421322035770118,-8.0127815501831513E-4]
[null,"HV","Overhead lines",9.9432513766961952E-2,9.9587840934402136E-2,9.9653785652412619E-2,0.11163449108709478,0.11117532404936126,0.10598162282997246,0.10373349429719747,0.10359447930144974,0.10334928520907181,0.10440722015081436,null,0.41030863144087149,0.11117532404936126,0.52148395549023274,null,0.52106610178850588,-8.0127815501831513E-4]
[null,null,"Underground cables",0.29829754130088582,0.39835136373760854,1.1958454278289514,0.55817245543547389,0.55587662024680617,0.52990811414986216,0.51866747148598724,0.51797239650724869,0.51674642604535914,0.5220361007540717,null,2.4506667883029198,0.55587662024680617,3.0065434085497262,null,2.6053305089425289,-0.13344656806426466]
[null,null,"Submarine",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Switchgear (incl other plant & equipment)",0.39773005506784781,0.59752704560641279,0.49826892826206309,0.44653796434837911,0.44470129619744503,0.42392649131988985,0.41493397718878988,0.41437791720579897,0.41339714083628726,0.41762888060325742,null,1.9400639932847028,0.44470129619744503,2.3847652894821478,null,2.0842644071540235,-0.12600857772186802]
[null,null,"Transformers ",9.9432513766961952E-2,0.39835136373760854,0.29896135695723786,0.22326898217418956,0.22235064809872251,0.52990811414986216,0.51866747148598724,0.6215668758086984,0.62009571125443086,0.73085054105570035,null,1.0200142166359978,0.22235064809872251,1.2423648647347203,null,3.0210887137546791,1.431724205593794]
[null,null,"Substation",0.79546011013569562,0.29876352280320639,0.69757649956688828,0.55817245543547389,0.55587662024680617,0.52990811414986216,0.51866747148598724,0.51797239650724869,0.51674642604535914,0.5220361007540717,null,2.3499725879412643,0.55587662024680617,2.9058492081880702,null,2.6053305089425289,-0.10341854573827954]
[null,"EHV","Overhead lines",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Underground cables",9.9432513766961952E-2,0.19917568186880427,0.19930757130482524,0.11163449108709478,0.11117532404936126,0.21196324565994493,0.20746698859439494,0.20718895860289949,0.20669857041814363,0.20881444030162871,null,0.60955025802768625,0.11117532404936126,0.72072558207704751,null,1.0421322035770118,0.44594867934853605]
[null,null,"Submarine",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Switchgear (incl other plant & equipment)",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Transformers ",0.79546011013569562,2.8880473870976617,2.1923832843530775,1.004710419783853,0.55587662024680617,0,0,0,0,0,null,6.880601201370288,0.55587662024680617,7.4364778216170944,null,0,-1]
[null,null,"Substation",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"132kV","Overhead lines",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Underground cables",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Submarine cables",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Switchgear (incl other plant & equipment)",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Transformers ",0.1988650275339239,1.1950540912128256,0.39861514260965047,0.55817245543547389,0.55587662024680617,0.63588973697983475,0.62240096578318471,0.6215668758086984,0.62009571125443086,0.62644332090488597,null,2.3507067167918736,0.55587662024680617,2.90658333703868,null,3.1263966107310348,7.5626000772545401E-2]
[null,null,"Substation",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"Total reactive condition based replacement (£m)",null,3.0824079267758209,6.3736218198017367,6.0788809247971693,4.0188416791354129,3.5576103695795602,3.3914119305591184,3.3194718175103191,3.4186178169478416,3.4105264118993706,3.5498454851276877,null,19.553752350510141,3.5576103695795602,23.111362720089701,null,17.089873462044338,-0.26054237177503797]
[]
[]
[null,"Overhead line refurbishment / replacement"]
[]
[null,"Asset Categories",null,"DPCR 4",null,null,null,null,"DPCR 5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/015",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,null,null,"£m","£m","£m","£m","£m","£m","£m","£m","£m","£m"]
[null,"LV Mains","Refurbishment",0,0,0,0,0.77822726834552869,0,0,0,0,0,null,{"$f":"SUM(D109:G109)","v":0},{"$f":"H109","v":0.77822726834552869},{"$f":"SUM(D109:H109)","v":0.77822726834552869},null,{"$f":"SUM(I109:M109)","v":0},{"$f":"IF(Q109<>0,(S109-Q109)/Q109,\"0\")","v":-1}]
[null,null,"Full rebuild",0,0.39835136373760854,0.39861514260965047,1.004710419783853,0.66705194429616743,1.0598162282997243,1.1410684372691722,1.2431337516173968,1.3435407077179335,1.4617010821114007,null,1.8016769261311121,0.66705194429616743,2.4687288704272796,null,6.2492602070156282,{"$f":"IF(Q110<>0,(S110-Q110)/Q110,\"0\")","v":1.531367572144132}]
[null,null,"Undergrounding",0,0.19917568186880427,0.19930757130482524,0.55817245543547389,0.33352597214808372,1.8016875881095318,1.8672028973495542,2.0718895860289948,2.1703349893905082,2.296958843317916,null,0.95665570860910343,0.33352597214808372,1.2901816807571871,null,10.208073904196503,6.9121212589265317]
[null,null,"Covered Conductor",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Pole replacement only (i.e. D poles)",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Total OHL expenditure (£m)",0,0.59752704560641279,0.59792271391447571,1.5628828752193269,1.7788051847897797,2.8615038164092561,3.0082713346187262,3.3150233376463918,3.5138756971084417,3.7586599254293169,null,2.7583326347402153,1.7788051847897797,4.5371378195299954,null,16.457334111212134,2.6272502105560811]
[null,"HV","Refurbishment",5.468788257182907,8.6641421612929843,9.7660709939364363,11.833256055232045,9.4499025441957052,9.8562909231874372,8.9210805095589798,8.287558344115979,7.751196390680386,7.3085054105570046,null,35.732257467644374,9.4499025441957052,45.182160011840082,null,42.124631578099788,-6.7671143498652192E-2]
[null,null,"Full rebuild",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Undergrounding",0.29829754130088582,0.39835136373760854,0.49826892826206309,0.55817245543547389,0.55587662024680617,0,0,0,0,0,null,1.7530902887360313,0.55587662024680617,2.3089669089828373,null,0,-1]
[null,null,"Covered Conductor",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Pole replacement only (i.e. D poles)",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Total OHL expenditure (£m)",5.7670857984837927,9.0624935250305931,10.264339922198499,12.391428510667518,10.005779164442512,9.8562909231874372,8.9210805095589798,8.287558344115979,7.751196390680386,7.3085054105570046,null,37.485347756380399,10.005779164442512,47.491126920822907,null,42.124631578099788,-0.1129999579009807]
[null,"EHV - Pole line","Refurbishment",0.39773005506784781,9.9587840934402136E-2,0,2.4559588039160856,0.44470129619744503,0.21196324565994493,0,0.82875583441159795,0.41339714083628726,0,null,2.9532766999183355,0.44470129619744503,3.3979779961157806,null,1.4541162209078302,-0.57206426216708095]
[null,null,"Full rebuild",0,0,0,0,0,0.21196324565994493,3.8381392889963055,1.8647006274260953,5.4775121160808053,2.5057732836195439,null,0,0,0,null,13.898088561782695,"0"]
[null,null,"Undergrounding",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Pole replacement only (i.e. D poles)",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"EHV - Tower line","Fittings only",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Reconductoring",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Undergrounding",0,0,0,0,0,0,0.20746698859439494,0,0,0,null,0,0,0,null,0.20746698859439494,"0"]
[null,null,"Tower Refurbishment",0,0,0,0,0,0,0,1.1395392723159472,0.62009571125443086,0,null,0,0,0,null,1.7596349835703782,"0"]
[null,"EHV Total","Total OHL expenditure (£m)",0.39773005506784781,9.9587840934402136E-2,0,2.4559588039160856,0.44470129619744503,0.42392649131988985,4.0456062775907,3.8329957341536405,6.5110049681715232,2.5057732836195439,null,2.9532766999183355,0.44470129619744503,3.3979779961157806,null,17.319306754855297,4.096944940388946]
[null,"132kV - Pole Line","Refurbishment",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Full rebuild",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Undergrounding",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Pole replacement only (i.e. D poles)",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"132kV - Tower line","Fittings only",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,null,"Reconductoring",9.9432513766961952E-2,4.5810406829824979,6.9757649956688832,4.6886486256579811,2.3346818050365865,4.4512281588588438,3.8381392889963055,4.868940527168137,4.2373206935719443,2.0881444030162868,null,16.344886818076326,2.3346818050365865,18.679568623112914,null,19.483773071611516,4.3052624218716196E-2]
[null,null,"Undergrounding",0,0,0,7.814414376096634,3.8911363417276434,0,0,0,0,0,null,7.814414376096634,3.8911363417276434,11.705550717824277,null,0,-1]
[null,null,"Tower Refurbishment",0,0,0,0,0,0,0,0,0,0,null,0,0,0,null,0,"0"]
[null,"132 kV Total","Total OHL expenditure (£m)",9.9432513766961952E-2,4.5810406829824979,6.9757649956688832,12.503063001754615,6.2258181467642295,4.4512281588588438,3.8381392889963055,4.868940527168137,4.2373206935719443,2.0881444030162868,null,24.159301194172958,6.2258181467642295,30.385119340937187,null,19.483773071611516,-0.35877253424634514]
[]
[null,"LV Services - Split of activities "]
[]
[null,"Asset Categories",null,"DPCR 4",null,null,null,null,"DPCR 5",null,null,null,null,null,"DPCR4",null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/015",null,"Actuals","Forecast","Total",null,"Forecast","% change"]
[null,null,null,"£m","£m","£m","£m","£m","£m","£m","£m","£m","£m"]
[null,"LV Services - metered only","OHL"]
[null,null,"Service Replacement",null,null,null,null,null,null,null,null,null,null,null,{"$f":"SUM(D146:G146)","v":0},{"$f":"H146","v":0},{"$f":"SUM(D146:H146)","v":0},null,{"$f":"SUM(I146:M146)","v":0},{"$f":"IF(Q146<>0,(S146-Q146)/Q146,\"0\")","v":"0"}]
[null,null,"Cut out Replacement",null,null,null,null,null,null,null,null,null,null,null,0,0,0,null,0,"0"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,0,0,0,null,0,"0"]
[]
[null,null,"UG"]
[null,null,"Service Replacement",null,null,null,null,null,null,null,null,null,null,null,0,0,0,null,0,"0"]
[null,null,"Cut out Replacement",null,null,null,null,null,null,null,null,null,null,null,0,0,0,null,0,"0"]
[null,null,null,null,null,null,null,null,null,null,null,null,null,null,0,0,0,null,0,"0"]

{"sheet":"NL9 - Legal & Safety","index":18,"n_rows":137,"n_cols":24,"rows_kept":137,"cut":false,"hidden":false,"merged":[[6,1,7,2],[30,1,31,2],[39,1,40,2],[58,1,59,1],[67,1,68,1],[57,1,57,7],[131,2,132,2],[131,10,132,10],[131,18,132,18],[121,1,121,7],[121,9,121,15],[121,17,121,23],[122,2,123,2],[122,10,123,10],[122,18,123,18],[130,1,130,7],[122,1,123,1],[131,1,132,1],[75,1,75,7],[75,9,75,15],[76,2,77,2],[76,10,77,10],[75,17,75,23],[76,18,77,18],[76,1,77,1],[76,17,77,17],[113,2,114,2],[112,1,112,7],[112,9,112,15],[112,17,112,23],[130,9,130,15],[130,17,130,23],[113,10,114,10],[113,18,114,18],[113,1,114,1],[103,1,103,7],[103,9,103,15],[103,17,103,23],[104,2,105,2],[104,3,104,7],[104,10,105,10],[104,18,105,18],[104,1,105,1],[66,9,66,15],[66,17,66,23],[67,18,68,18],[66,1,66,7],[67,2,68,2],[67,10,68,10],[67,17,68,17],[84,1,84,7],[84,9,84,15],[84,17,84,23],[85,2,86,2],[85,10,86,10],[85,18,86,18],[85,3,85,7],[85,1,86,1],[85,17,86,17],[57,9,57,15],[57,17,57,23],[58,2,59,2],[58,10,59,10],[58,18,59,18],[58,3,58,7],[58,19,58,23],[58,17,59,17]]}
["June Forecast Business Plan DPCR5"]
["EDFE SPN"]
["NL9 - Legal and safety"]
[]
[null,"Legal and Safety"]
[]
[null,null,null,"DPCR4",null,null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15"]
[null,"ESQCR"]
[null,"ESQCR 43-8 Clearance","£m"]
[null,"ESQCR tree continuity","£m"]
[null,"ESQCR Other","£m"]
[null,"CNI"]
[null,"Black Start","£m"]
[null,"Emergency Batteries","£m"]
[null,"Critical National Infrastructure","£m"]
[null,"Other"]
[null,"Site Security","£m"]
[null,"Asbestos clearance","£m"]
[null,"Safety climbing devices","£m"]
[null,"Rising mains and laterals","£m"]
[null,null,"£m"]
[null,"Retrofit ABSD & Earthing theft & Replace 0.025 OH conductor","£m"]
[null,"Fire Prevention","£m"]
[null,"Total","£m",{"$f":"SUM(D10:D24)","v":0},0,0,0,0,0,0,0,0,0]
[]
[]
[null,"ESQCR 43-8 Safety Clearance Expenditure"]
[]
[null,"Horizontal"]
[null,null,null,"DPCR4",null,null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15"]
[null,"LV ","£m"]
[null,"HV","£m"]
[null,"EHV","£m"]
[null,"132 kV","£m"]
[null,"Total","£m",{"$f":"SUM(D33:D36)","v":0},0,0,0,0,0,0,0,0,0]
[]
[null,"Vertical"]
[null,null,null,"DPCR4",null,null,null,null,"DPCR5"]
[null,null,null,"2005/06","2006/07","2007/08","2008/09","2009/10","2010/11","2011/12","2012/13","2013/14","2014/15"]
[null,"LV ","£m"]
[null,"HV","£m"]
[null,"EHV","£m"]
[null,"132 kV","£m"]
[null,"Total","£m",{"$f":"SUM(D42:D45)","v":0},0,0,0,0,0,0,0,0,0]
[]
[null,"Horizontal - Detailed Information"]
[]
[null,null,"Sites affected as at April 2005","No of sites resolved 05/06 - 07/08","Sites affected as at April 2008","No of sites to be resolved 08/09 - 09/10","No of sites to be resolved in DPCR5","Sites affected as at April 2015"]
[null,"LV ",{"$f":"D51+E51","v":0},{"$f":"C61","v":0},null,{"$f":"K61","v":0},{"$f":"S61","v":0},{"$f":"E51-SUM(F51:G51)","v":0}]
[null,"HV",{"$f":"D52+E52","v":0},{"$f":"C62","v":0},null,{"$f":"K62","v":0},{"$f":"S62","v":0},{"$f":"E52-SUM(F52:G52)","v":0}]
[null,"EHV",{"$f":"D53+E53","v":0},{"$f":"C63","v":0},null,{"$f":"K63","v":0},{"$f":"S63","v":0},{"$f":"E53-SUM(F53:G53)","v":0}]
[null,"132 kV",{"$f":"D54+E54","v":0},{"$f":"C64","v":0},null,{"$f":"K64","v":0},{"$f":"S64","v":0},{"$f":"E54-SUM(F54:G54)","v":0}]
[null,"Total",{"$f":"SUM(C51:C54)","v":0},0,0,0,0,0]
[]
[]
[null,"05/06 - 07/08",null,null,null,null,null,null,null,"08/09-09/10",null,null,null,null,null,null,null,"DPCR5"]
[null,null,"No of sites resolved","Actual Solutions (#)",null,null,null,null,null,null,"No of sites resolved","Forecast Solutions (#)",null,null,null,null,null,null,"No of sites resolved","Forecast Solutions (#)"]
[null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors","As part of other planned work",null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors","As part of other planned work",null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors","As part of other planned work"]
[null,"LV ",{"$f":"SUM(D61:H61)","v":0},null,null,null,null,null,null,"LV ",{"$f":"SUM(L61:P61)","v":0},null,null,null,null,null,null,"LV ",{"$f":"SUM(T61:X61)","v":0}]
[null,"HV",{"$f":"SUM(D62:H62)","v":0},null,null,null,null,null,null,"HV",{"$f":"SUM(L62:P62)","v":0},null,null,null,null,null,null,"HV",{"$f":"SUM(T62:X62)","v":0}]
[null,"EHV",{"$f":"SUM(D63:H63)","v":0},null,null,null,null,null,null,"EHV",{"$f":"SUM(L63:P63)","v":0},null,null,null,null,null,null,"EHV",{"$f":"SUM(T63:X63)","v":0}]
[null,"132 kV",{"$f":"SUM(D64:H64)","v":0},null,null,null,null,null,null,"132 kV",{"$f":"SUM(L64:P64)","v":0},null,null,null,null,null,null,"132 kV",{"$f":"SUM(T64:X64)","v":0}]
[null,"Total",{"$f":"SUM(C61:C64)","v":0},0,0,0,0,0,null,"Total",{"$f":"SUM(K61:K64)","v":0},0,0,0,0,0,null,"Total",{"$f":"SUM(S61:S64)","v":0},0,0,0,0,0]
[]
[null,"05/06 - 07/08",null,null,null,null,null,null,null,"08/09-09/10",null,null,null,null,null,null,null,"DPCR5"]
[null,null,"No of spans changed","Actual Solutions (#)",null,null,null,null,null,null,"No of spans changed","Forecast Solutions (#)",null,null,null,null,null,null,"No of spans changed","Forecast Solutions (#)"]
[null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors","As part of other planned work",null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors","As part of other planned work",null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors","As part of other planned work"]
[null,"LV ",null,null,null,null,null,null,null,"LV ",null,null,null,null,null,null,null,"LV "]
[null,"HV",null,null,null,null,null,null,null,"HV",null,null,null,null,null,null,null,"HV"]
[null,"EHV",null,null,null,null,null,null,null,"EHV",null,null,null,null,null,null,null,"EHV"]
[null,"132 kV",null,null,null,null,null,null,null,"132 kV",null,null,null,null,null,null,null,"132 kV"]
[null,"Total",{"$f":"SUM(C70:C73)","v":0},0,0,0,0,0,null,"Total",{"$f":"SUM(K70:K73)","v":0},0,0,0,0,0,null,"Total",{"$f":"SUM(S70:S73)","v":0},0,0,0,0,0]
[]
[null,"05/06 - 07/08",null,null,null,null,null,null,null,"08/09-09/10",null,null,null,null,null,null,null,"DPCR5"]
[null,null,"Total Cost £m","Expenditure £m",null,null,null,null,null,null,"Total Cost £m","Forecast Solutions (£m)",null,null,null,null,null,null,"Total Cost £m","Forecast Solutions (£m)"]
[null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors","As part of other planned work",null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors","As part of other planned work",null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors","As part of other planned work"]
[null,"LV ",null,null,null,null,null,null,null,"LV ",{"$f":"SUM(G33:H33)","v":0},null,null,null,null,null,null,"LV ",{"$f":"SUM(I33:M33)","v":0}]
[null,"HV",null,null,null,null,null,null,null,"HV",{"$f":"SUM(G34:H34)","v":0},null,null,null,null,null,null,"HV",{"$f":"SUM(I34:M34)","v":0}]
[null,"EHV",null,null,null,null,null,null,null,"EHV",{"$f":"SUM(G35:H35)","v":0},null,null,null,null,null,null,"EHV",{"$f":"SUM(I35:M35)","v":0}]
[null,"132 kV",null,null,null,null,null,null,null,"132 kV",{"$f":"SUM(G36:H36)","v":0},null,null,null,null,null,null,"132 kV",{"$f":"SUM(I36:M36)","v":0}]
[null,"Total",{"$f":"SUM(C79:C82)","v":0},0,0,0,0,0,null,"Total",{"$f":"SUM(K79:K82)","v":0},0,0,0,0,0,null,"Total",{"$f":"SUM(S79:S82)","v":0},0,0,0,0,0]
[]
[null,"05/06 - 07/08",null,null,null,null,null,null,null,"08/09-09/10",null,null,null,null,null,null,null,"DPCR5"]
[null,null,"Total unit Cost £k/per span","Unit cost £k/span",null,null,null,null,null,null,"Total unit Cost £k/per span","Forecast Unit cost £k/span",null,null,null,null,null,null,"Total unit Cost £k/per span","Forecast Unit cost £k/span"]
[null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors","As part of other planned work",null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors",null,null,null,null,"Shrouding","Diversions","Under-grounding","Covered conductors"]
[null,"LV ",{"$f":"IF(C70>0,C79*1000/C70,0)","v":0},0,0,0,0,null,null,"LV ",{"$f":"IF(K70>0,K79*1000/K70,0)","v":0},0,0,0,0,null,null,"LV ",{"$f":"IF(S70>0,S79*1000/S70,0)","v":0},0,0,0,0]
[null,"HV",0,0,0,0,0,null,null,"HV",0,0,0,0,0,null,null,"HV",0,0,0,0,0]
[null,"EHV",0,0,0,0,0,null,null,"EHV",0,0,0,0,0,null,null,"EHV",0,0,0,0,0]
[null,"132 kV",0,0,0,0,0,null,null,"132 kV",0,0,0,0,0,null,null,"132 kV",0,0,0,0,0]
[]
[]
[null,"Vertical - Detailed Information"]
[]
[null,null,"Sites affected as at April 2005","No of sites resolved 05/06 - 07/08","Sites affected as at April 2008","No of sites to be resolved 08/09 - 09/10","No of sites to be resolved in DPCR5","Sites affected as at April 2015"]
[null,"LV ",{"$f":"D97+E97","v":0},{"$f":"C107","v":0},null,{"$f":"K107","v":0},{"$f":"S107","v":0},{"$f":"E97-SUM(F97:G97)","v":0}]
[null,"HV",{"$f":"D98+E98","v":0},{"$f":"C108","v":0},null,{"$f":"K108","v":0},{"$f":"S108","v":0},{"$f":"E98-SUM(F98:G98)","v":0}]
[null,"EHV",{"$f":"D99+E99","v":0},{"$f":"C109","v":0},null,{"$f":"K109","v":0},{"$f":"S109","v":0},{"$f":"E99-SUM(F99:G99)","v":0}]
[null,"132 kV",{"$f":"D100+E100","v":0},{"$f":"C110","v":0},null,{"$f":"K110","v":0},{"$f":"S110","v":0},{"$f":"E100-SUM(F100:G100)","v":0}]
[null,"Total",{"$f":"SUM(C97:C100)","v":0},0,0,0,0,0]
[]
[]
[null,"05/06 - 07/08",null,null,null,null,null,null,null,"08/09-09/10",null,null,null,null,null,null,null,"DPCR5"]
[null,null,"No of sites resolved","Actual Solutions (#)",null,null,null,null,null,null,"No of sites resolved","Forecast Solutions (#)",null,null,null,null,null,null,"No of sites resolved","Forecast Solutions (#)"]
[null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work",null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work",null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work"]
[null,"LV ",{"$f":"SUM(D107:H107)","v":0},null,null,null,null,null,null,"LV ",{"$f":"SUM(L107:P107)","v":0},null,null,null,null,null,null,"LV ",{"$f":"SUM(T107:X107)","v":0}]
[null,"HV",{"$f":"SUM(D108:H108)","v":0},null,null,null,null,null,null,"HV",{"$f":"SUM(L108:P108)","v":0},null,null,null,null,null,null,"HV",{"$f":"SUM(T108:X108)","v":0}]
[null,"EHV",{"$f":"SUM(D109:H109)","v":0},null,null,null,null,null,null,"EHV",{"$f":"SUM(L109:P109)","v":0},null,null,null,null,null,null,"EHV",{"$f":"SUM(T109:X109)","v":0}]
[null,"132 kV",{"$f":"SUM(D110:H110)","v":0},null,null,null,null,null,null,"132 kV",{"$f":"SUM(L110:P110)","v":0},null,null,null,null,null,null,"132 kV",{"$f":"SUM(T110:X110)","v":0}]
[null,"Total",{"$f":"SUM(C107:C110)","v":0},0,0,0,0,0,null,"Total",{"$f":"SUM(K107:K110)","v":0},0,0,0,0,0,null,"Total",{"$f":"SUM(S107:S110)","v":0},0,0,0,0,0]
[]
[null,"05/06 - 07/08",null,null,null,null,null,null,null,"08/09-09/10",null,null,null,null,null,null,null,"DPCR5"]
[null,null,"No of spans changed","Actual Solutions (#)",null,null,null,null,null,null,"No of spans changed","Forecast Solutions (#)",null,null,null,null,null,null,"No of spans changed","Forecast Solutions (#)"]
[null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work",null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work",null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work"]
[null,"LV ",null,null,null,null,null,null,null,"LV ",null,null,null,null,null,null,null,"LV "]
[null,"HV",null,null,null,null,null,null,null,"HV",null,null,null,null,null,null,null,"HV"]
[null,"EHV",null,null,null,null,null,null,null,"EHV",null,null,null,null,null,null,null,"EHV"]
[null,"132 kV",null,null,null,null,null,null,null,"132 kV",null,null,null,null,null,null,null,"132 kV"]
[null,"Total",{"$f":"SUM(C116:C119)","v":0},{"$f":"SUM(D116:D119)","v":0},{"$f":"SUM(E116:E119)","v":0},{"$f":"SUM(F116:F119)","v":0},null,{"$f":"SUM(H116:H119)","v":0},null,"Total",{"$f":"SUM(K116:K119)","v":0},0,0,0,0,0,null,"Total",{"$f":"SUM(S116:S119)","v":0},0,0,0,0,0]
[]
[null,"05/06 - 07/08",null,null,null,null,null,null,null,"08/09-09/10",null,null,null,null,null,null,null,"DPCR5"]
[null,null,"Total Cost £m","Expenditure £m",null,null,null,null,null,null,"Total Cost £m","Forecast Solutions (£m)",null,null,null,null,null,null,"Total Cost £m","Forecast Solutions (£m)"]
[null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work",null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work",null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work"]
[null,"LV ",{"$f":"SUM(D42:F42)","v":0},null,null,null,null,null,null,"LV ",{"$f":"SUM(G42:H42)","v":0},null,null,null,null,null,null,"LV ",{"$f":"SUM(I42:M42)","v":0}]
[null,"HV",{"$f":"SUM(D43:F43)","v":0},null,null,null,null,null,null,"HV",{"$f":"SUM(G43:H43)","v":0},null,null,null,null,null,null,"HV",{"$f":"SUM(I43:M43)","v":0}]
[null,"EHV",{"$f":"SUM(D44:F44)","v":0},null,null,null,null,null,null,"EHV",{"$f":"SUM(G44:H44)","v":0},null,null,null,null,null,null,"EHV",{"$f":"SUM(I44:M44)","v":0}]
[null,"132 kV",{"$f":"SUM(D45:F45)","v":0},null,null,null,null,null,null,"132 kV",{"$f":"SUM(G45:H45)","v":0},null,null,null,null,null,null,"132 kV",{"$f":"SUM(I45:M45)","v":0}]
[null,"Total",{"$f":"SUM(C125:C128)","v":0},{"$f":"SUM(D125:D128)","v":0},{"$f":"SUM(E125:E128)","v":0},{"$f":"SUM(F125:F128)","v":0},null,{"$f":"SUM(H125:H128)","v":0},null,"Total",{"$f":"SUM(K125:K128)","v":0},{"$f":"SUM(L125:L128)","v":0},{"$f":"SUM(M125:M128)","v":0},{"$f":"SUM(N125:N128)","v":0},null,{"$f":"SUM(P125:P128)","v":0},null,"Total",{"$f":"SUM(S125:S128)","v":0},{"$f":"SUM(T125:T128)","v":0},{"$f":"SUM(U125:U128)","v":0},{"$f":"SUM(V125:V128)","v":0},null,{"$f":"SUM(X125:X128)","v":0}]
[]
[null,"05/06 - 07/08",null,null,null,null,null,null,null,"08/09-09/10",null,null,null,null,null,null,null,"DPCR5"]
[null,null,"Total unit Cost £k/per span","Unit cost £k/span",null,null,null,null,null,null,"Total unit Cost £k/per span","Forecast Unit cost £k/span",null,null,null,null,null,null,"Total unit Cost £k/per span","Forecast Unit cost £k/span"]
[null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work",null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work",null,null,null,"Rebuild","Under-grounding","Other","Derogation","As part of other planned work"]
[null,"LV ",{"$f":"IF(C116>0,C125*1000/C116,0)","v":0},0,0,0,null,null,null,"LV ",{"$f":"IF(K116>0,K125*1000/K116,0)","v":0},0,0,0,null,null,null,"LV ",{"$f":"IF(S116>0,S125*1000/S116,0)","v":0},0,0,0]
[null,"HV",0,0,0,0,null,null,null,"HV",0,0,0,0,null,null,null,"HV",0,0,0,0]
[null,"EHV",0,0,0,0,null,null,null,"EHV",0,0,0,0,null,null,null,"EHV",0,0,0,0]
[null,"132 kV",0,0,0,0,null,null,null,"132 kV",0,0,0,0,null,null,null,"132 kV",0,0,0,0]

{"sheet":"FBPQ C2","index":19,"n_rows":155,"n_cols":10,"rows_kept":155,"cut":false,"hidden":false,"merged":[[6,1,8,4],[6,5,8,5],[6,6,6,7],[6,8,6,9]]}
["Main Forecast Business Plan DPCR5",null,null,null,null,"Index"]
[]
["C2 - Unit costs"]
[]
[]
[]
[null,"Asset categories",null,null,null,"Units","New build ",null,"Replacement"]
[null,null,null,null,null,null,"Direct costs","Cost including indirects (absorbed costs in T2A)","Direct costs","Cost including indirects (absorbed costs in T2A)"]
[null,null,null,null,null,null,"(£k)","(£k)","(£k)","(£k)"]
[null,null,"LV Network"]
[null,null,null,"Overhead lines"]
[null,null,null,null,"LV Main (OHL)","km",null,null,null,41.700246577433042]
[null,null,null,null,"LV Service (OHL)","Each",null,null,null,0.50853959240772006]
[]
[null,null,null,"Overhead lines - Support"]
[null,null,null,null,"LV Support","Each",null,null,null,0]
[]
[null,null,null,"Underground cables"]
[null,null,null,null,"LV Main (UG Consac)","km",null,null,null,127.13489810193002]
[null,null,null,null,"LV Main (UG Plastic)","km",null,null,null,127.13489810193002]
[null,null,null,null,"LV Main (UG Paper)","km",null,null,null,127.13489810193002]
[null,null,null,null,"LV Service (UG)","Each",null,null,null,1.7000732843986286]
[]
[null,null,null,"Switchgear "]
[null,null,null,null,"LV Pillar (ID)","Each",null,null,null,5.7210704145868512]
[null,null,null,null,"LV Pillar (OD)","Each",null,null,null,5.7210704145868512]
[null,null,null,null,"LV Board (WM)","Each",null,null,null,5.7210704145868512]
[null,null,null,null,"LV UGB","Each",null,null,null,4.8311261278733406]
[null,null,null,null,"LV Fuses (PM)","Each"]
[null,null,null,null,"LV Fuses (TM)","Each"]
[]
[null,null,"HV network"]
[null,null,null,"Overhead lines"]
[null,null,null,null,"6.6/11 kV OHL (Open)","km",null,null,null,43.098730456554271]
[null,null,null,null,"6.6/11 kV OHL (Covered)","km",null,null,null,43.098730456554271]
[null,null,null,null,"20 kV OHL (Open)","km",null,null,null,0]
[null,null,null,null,"20 kV OHL (Covered)","km",null,null,null,0]
[]
[null,null,null,"Overhead lines - Support"]
[null,null,null,null,"6.6/11 kV Support","Each",null,null,null,0]
[null,null,null,null,"20 kV Support","Each",null,null,null,0]
[]
[null,null,null,"Underground cables (kms)"]
[null,null,null,null,"6.6/11kV UG Cable","km",null,null,null,84.544707237783456]
[null,null,null,null,"20kV UG Cable","km",null,null,null,0]
[]
[null,null,null,"Submarine cables (kms)"]
[null,null,null,null,"HV Sub Cable","km",null,null,null,0]
[]
[null,null,null,"Switchgear "]
[null,null,null,null,"6.6/11 kV CB (PM)","Each",null,null,null,13.984838791212301]
[null,null,null,null,"6.6/11 kV CB (GM)","Each",null,null,null,30.893780238768993]
[null,null,null,null,"6.6/11 kV Switch (PM)","Each",null,null,null,1.6527536753250902]
[null,null,null,null,"6.6/11 kV Switch (GM)","Each",null,null,null,5.2125308221791302]
[null,null,null,null,"6.6/11 kV RMU","Each",null,null,null,16.400401855148971]
[null,null,null,null,"6.6/11 kV Switchgear - Other (PM)","Each"]
[null,null,null,null,"6.6/11 kV Switchgear - Other (GM)","Each"]
[null,null,null,null,"20 kV CB (PM)","Each",null,null,null,0]
[null,null,null,null,"20 kV CB (GM)","Each",null,null,null,0]
[null,null,null,null,"20 kV Switch (PM)","Each",null,null,null,0]
[null,null,null,null,"20 kV Switch (GM)","Each",null,null,null,0]
[null,null,null,null,"20 kV RMU","Each",null,null,null,0]
[null,null,null,null,"20 kV Switchgear - Other (PM)","Each"]
[null,null,null,null,"20 kV Switchgear - Other (GM)","Each"]
[]
[null,null,null,"Transformers  "]
[null,null,null,null,"6.6/11 kV Transformer (PM)","Each",null,null,null,3.68691204495597]
[null,null,null,null,"6.6/11 kV Transformer (GM)","Each",null,null,null,11.950680421581421]
[null,null,null,null,"20 kV Transformer (PM)","Each",null,null,null,0]
[null,null,null,null,"20 kV Transformer (GM)","Each",null,null,null,0]
[]
[null,null,"EHV Network"]
[null,null,null,"Overhead lines"]
[null,null,null,null,"33kV OHL (Pole Line)","km",null,null,null,98.402411130893839]
[null,null,null,null,"33kV OHL (Tower Line)","km",null,null,null,156.75732935967969]
[null,null,null,null,"66kV OHL (Pole Line)","km",null,null,null,185.61695122881781]
[null,null,null,null,"66kV OHL (Tower Line)","km",null,null,null,185.61695122881781]
[]
[null,null,null,"Overhead lines - Support"]
[null,null,null,null,"33kV Pole","Each",null,null,null,0]
[null,null,null,null,"33kV Tower","Each",null,null,null,0]
[null,null,null,null,"66kV Pole","Each",null,null,null,0]
[null,null,null,null,"66kV Tower","Each",null,null,null,0]
[]
[null,null,null,"Underground cables (kms)"]
[null,null,null,null,"33kV UG Cable (Non Pressurised)","km",null,null,null,257.06676396210247]
[null,null,null,null,"33kV UG Cable (Oil)","km",null,null,null,257.06676396210247]
[null,null,null,null,"33kV UG Cable (Gas)","km",null,null,null,0]
[null,null,null,null,"66kV UG Cable (Non Pressurised)","km",null,null,null,1206.5101829873158]
[null,null,null,null,"66kV UG Cable (Oil)","km",null,null,null,1206.5101829873158]
[null,null,null,null,"66kV UG Cable (Gas)","km",null,null,null,0]
[]
[null,null,null,"Submarine cables (kms)"]
[null,null,null,null,"EHV Sub Cable","km",null,null,null,0]
[]
[null,null,null,"Switchgear "]
[null,null,null,null,"33 KV CB (ID)","Each",null,null,null,184.98127673830817]
[null,null,null,null,"33 kV CB (OD)","Each",null,null,null,184.98127673830817]
[null,null,null,null,"33 kV Switch (GM)","Each",null,null,null,0]
[null,null,null,null,"33 kV Switch (PM)","Each",null,null,null,0]
[null,null,null,null,"33 kV RMU","Each",null,null,null,588.50744331383407]
[null,null,null,null,"33 kV Switchgear - Other","Each"]
[null,null,null,null,"66 KV CB (ID & OD)","Each",null,null,null,697.84345568149388]
[null,null,null,null,"66 KV Switchgear - Other","Each"]
[]
[null,null,null,"Transformers  "]
[null,null,null,null,"33 kV Transformer (PM)","Each",null,null,null,532.56808814898477]
[null,null,null,null,"33 kV Transformer (GM)","Each",null,null,null,571.97990656058312]
[null,null,null,null,"33 kV AuxiliaryTransfomer","Each"]
[null,null,null,null,"66 kV Transformer","Each",null,null,null,2234.9043737338279]
[null,null,null,null,"66 kV AuxiliaryTransfomer","Each"]
[]
[null,null,"132kV Network"]
[null,null,null,"Overhead lines"]
[null,null,null,null,"132kV OHL Conductor (Pole Line)","km",null,null,null,714.87953202715244]
[null,null,null,null,"132kV OHL Conductor (Tower Line)","km",null,null,null,1228.5045203589498]
[]
[null,null,null,"Overhead lines - Support"]
[null,null,null,null,"132kV Pole","Each",null,null,null,0]
[null,null,null,null,"132kV Tower","Each",null,null,null,0]
[null,null,null,null,"132kV Fittings (Tower Line)","Each",null,null,null,0]
[]
[null,null,null,"Underground cables (kms)"]
[null,null,null,null,"132kV UG Cable (Non Pressurised)","km",null,null,null,1239.5652564938177]
[null,null,null,null,"132kV UG Cable (Oil)","km",null,null,null,1239.5652564938177]
[null,null,null,null,"132kV UG Cable (Gas)","km",null,null,null,0]
[]
[null,null,null,"Submarine cables (kms)"]
[null,null,null,null,"132 kV Sub Cable","km",null,null,null,0]
[]
[null,null,null,"Switchgear "]
[null,null,null,null,"132 kV CB (ID & OD)","Each",null,null,null,1106.4550181810969]
[null,null,null,null,"132 kV Switchgear (other)","Each"]
[]
[null,null,null,"Transformers  "]
[null,null,null,null,"132 kV Transformer","Each",null,null,null,2234.9043737338279]
[null,null,null,null,"132 kV AuxiliaryTransfomer","Each"]
[]
[null,null,"Tele-control / SCADA"]
[null,null,null,"Primary substation"]
[null,null,null,null,"132 kV/EHV RTU (PM)","Each"]
[null,null,null,null,"132 kV/EHV RTU (GM)","Each"]
[]
[null,null,null,"Secondary substation"]
[null,null,null,null,"HV RTU (PM)","Each"]
[null,null,null,null,"HV RTU (GM)","Each"]
[]
[]
[null,null,"HV network switchgear"]
[null,null,null,null,"6.6/11 kV CB (GM)"]
[null,null,null,null,"Primary","Each",null,null,null,30.893780238768993]
[null,null,null,null,"Distribution","Each",null,null,null,7.882363682319661]
[null,null,null,null,"20 kV Switch (GM)"]
[null,null,null,null,"Primary","Each",null,null,null,0]
[null,null,null,null,"Distribution","Each",null,null,null,0]

{"sheet":"RRP 1.3","index":20,"n_rows":26,"n_cols":37,"rows_kept":26,"cut":false,"hidden":false,"merged":[[6,26,8,26],[6,36,8,36],[7,3,7,8],[7,9,7,23],[6,31,8,31],[6,32,8,32],[6,33,8,33],[6,34,8,34],[6,27,8,27],[6,28,8,28],[6,29,8,29],[6,35,8,35],[6,30,8,30],[6,3,6,23],[6,24,8,24],[6,25,8,25],[25,3,25,26],[21,3,21,26],[22,3,22,26],[23,3,23,26],[24,3,24,26]]}
["Regulatory Reporting Pack (RRP)",null,null,null,null,"Index",null,"CAUTION - THIS PACK DOES NOT BALANCE"]
[]
["2007/08"]
[]
[null,null,"Electricity Distribution Industry Activity Costs - individual DNO input"]
[]
[null,null,null,"Cash typical costs (excluding disallowed related party margins)",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,"Atypical cash costs","Pension deficit payments","Metering","Excluded services & de minimis","Relevant distributed generation (less contributions)","IFI","Disallowed Related Party Margins","Statutory Depreciation","Network Rates","Transmission Exit Charges","Pension deficit repair payments by related parties (note 2)","Non activity costs and reconciling amounts (note 3)","Total Annual Operating & Capital Expenditure per Regulatory Accounts"]
[null,null,null,"Direct activities",null,null,null,null,null,"Indirect activities"]
[null,null,"Year ended","Load related new connections & reinforcement (net of contributions)","Non-load new & replacement assets (net of contributions)","Non-operational capex","Faults","Inspections, & Maintenance","Tree Cutting","Network Policy","Network Design & Engineering","Project Management","Engineering Mgt & Clerical Support","Control Centre","System Mapping - Cartographical","Customer Call Centre","Stores","Vehicles & Transport","IT & Telecoms","Property Mgt","HR & Non-operational Training","Health & Safety & Operational Training","Finance & Regulation","CEO etc"]
[null,null,null,"£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m"]
[]
[null,null,"31 March 2008",11.260750888044793,86.73865287324719,2.2901999883199999,23.607461477008215,11.683384510026801,4.9082775940000003,0.77486938446319986,5.6235967952637829,4.1962810579107463,23.39222530593641,3.9932671215815496,1.8430952204672004,1.4394826722359997,1.3630810727301883,5.4399459945200013,11.413705956353251,5.5343552999991585,1.3726373768207174,1.9614634264481019,7.7816755968572568,1.536754324034403,2.24185108,7.62,0.81564207,12.183907341469606,1.3999999737279722E-7,1.0147458008000003,-5.1969463263321618,39.130465450300001,20.184226800000001,8,-7.62,2.4709437074936318,299]
[null,null,"Adjustments on T4.3",null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,null,0]
[null,null,"31 March 2008",11.260750888044793,86.73865287324719,2.2901999883199999,23.607461477008215,11.683384510026801,4.9082775940000003,0.77486938446319986,5.6235967952637829,4.1962810579107463,23.39222530593641,3.9932671215815496,1.8430952204672004,1.4394826722359997,1.3630810727301883,5.4399459945200013,11.413705956353251,5.5343552999991585,1.3726373768207174,1.9614634264481019,7.7816755968572568,1.536754324034403,2.24185108,7.62,0.81564207,12.183907341469606,1.3999999737279722E-7,1.0147458008000003,-5.1969463263321618,39.130465450300001,20.184226800000001,8,-7.62,2.4709437074936318,299]
[]
[null,null,"31 March 2007",8.6406930528630213,69.050320620092407,2.6978757939299998,26.585929994545726,8.4933534972528744,5.7800996575720154,1.1741027657412046,3.8077610766246233,5.041970767615255,18.204079436995361,4.1451310361827716,1.7043014022479737,1.5747594627143606,1.4758625624493948,4.6742188521986732,11.684030483425074,4.6000640042730518,2.0876733918815966,2.3444157040209626,7.71819896534008,1.8922248593075113,3.1853175699999996,2.1,5.2757375245545637,10.839291641651382,0,0,1.1714051563517915,39.324080569530004,20.276195809999997,7.2444885000000001,-2.1,11.876043500638502,292.56962766000015]
[]
[null,null,"31 March 2006",22.05381964681996,52.010151581557103,1.665331330495831,25.739669644938481,6.2838761175158684,2.1592628089684665,0.46992086685698797,3.7710730875040674,6.1367485042863796,10.797410407551657,3.2603866279764602,2.0259238623696421,1.3641478864905945,2.1503455470888513,2.7402381048519571,7.4525859839648003,5.0306563330394072,1.1978004536561848,1.7612408126809169,8.0876763651092158,2.2973169665637538,3.7657640000000003,68.099999999999994,8.7183465799999986,9.9484680436074697,0,0,0,44.999360189999997,21.829069,6.6293233200000001,-68.099999999999994,-3.9633140738940824,260.38259999999997]
[]
[]
[null,null,"Notes"]
[null,null,1,"The individual activities are defined in the Electricity Distribution Price Control Review Price control cost reporting rules: Instructions and Guidance April 2008 "]
[null,null,2,"Pension deficit payments made by a related party and not charged in the regulatory accounts of the DNO"]
[null,null,3,"Non-activity costs include Ofgem licence fee, Shetland Balancing Costs (SHEPD only), Scottish Electricity Settlements run-off (Scottish DNOs only) and proceeds of asset sales; and reconciling amounts, e.g. intra-group recharges treated as de minimis costs"]
[null,null,4,"Total Annual Operating & Capital Expenditure per Regulatory Accounts has been adjusted, where appropriate, to include intangible fixed assets and customer contributions, the latter may be reported within Creditors as deferred income"]
[null,null,5,"This information has not been audited."]

{"sheet":"RRP 2.3","index":21,"n_rows":48,"n_cols":17,"rows_kept":48,"cut":false,"hidden":false,"merged":[[46,2,46,5],[43,12,43,13],[41,14,42,14],[33,0,33,2],[43,2,43,5],[44,2,44,5],[45,2,45,5],[36,4,36,7],[41,12,42,13],[37,4,37,7],[38,4,38,7],[39,4,39,7],[41,2,42,5],[41,6,42,6],[10,4,11,4],[5,12,5,16],[6,4,6,6],[6,8,6,10],[6,12,7,14],[6,16,7,16],[10,6,11,6],[10,5,11,5],[19,0,22,0],[19,1,19,2],[22,1,22,2],[23,0,26,0],[8,0,9,2],[10,0,11,0],[10,1,10,2],[11,1,11,2],[13,6,15,6],[14,1,14,2],[15,1,15,2],[16,0,18,0],[16,1,16,2],[17,1,17,2],[18,1,18,2],[12,0,15,0],[12,1,12,2],[13,1,13,2],[13,4,15,4],[23,1,23,2],[26,1,26,2],[31,0,31,2],[32,0,32,2],[28,0,28,2],[29,0,29,2],[30,0,30,2],[27,0,27,2]]}
["Regulatory Reporting Pack (RRP)",null,null,null,"Index"]
[]
["2007/08"]
[]
["Inspections & Maintenance, Tree Cutting and Fault Costs"]
[null,null,null,null,null,null,null,null,null,null,null,null,"Memorandum Information - Scottish DNOs 132kV"]
[null,null,null,null,"Inspections & Maintenance",null,null,null,"Fault Costs",null,null,null,"Inspections & Maintenance",null,null,null,"Faults"]
[null,null,null,null,null,"Cash typicals",null,null,"Cash typicals",null,"Atypicals"]
["Inspection and Maintenance",null,null,null,"Inspections ","Maintenance ","Total ",null,"Total ",null,"Total ",null,"Inspections ","Maintenance ","Total ",null,"Total "]
[null,null,null,null,"£'m","£'m","£'m",null,"£'m",null,"£'m",null,"£'m","£'m","£'m",null,"£'m"]
["LV Services","Overhead",null,null,0,0.34993341352313201,{"$f":"SUM(E11:F11)","v":0.34993341352313201},null,0.750282044999384,null,7.2265999999999997E-4]
[null,"Underground",null,null,null,null,null,null,3.7494364493580301,null,0]
["LV System","Overhead Mains",null,null,0.64932876832459596,0.18712151797780699,{"$f":"SUM(E13:F13)","v":0.83645028630240292},null,1.09166607072265,null,0.7483930894199875]
[null,"Underground Mains - Consac",null,null,0.16515536945699799,0.192573506393558,{"$f":"SUM(E14:F14)","v":0.35772887585055602},null,2.6923878675880899,null,0]
[null,"Underground Mains - Non Consac",null,null,null,null,null,null,6.7963406163688802,null,0]
[null,"Switchgear (incl other plant & equipment)",null,null,null,null,null,null,0.192313844854368,null,0]
["HV ","Overhead lines",null,null,0.14861498138415599,0.24474836257274399,{"$f":"SUM(E17:F17)","v":0.39336334395689998},null,1.47726639751246,null,0.43748758058001225]
[null,"Underground Cables",null,null,0,4.2900229690369149E-2,4.2900229690369149E-2,null,3.8019044614310622,null,0]
[null,"Switchgear, Transformers, Substation",null,null,0.45718946854354298,4.8268610279176496,5.2840504964611927,null,0.58234466945385643,null,0]
["EHV","Overhead lines",null,null,0,0,0,null,0.10286285655124124,null,2.6301700000000003E-3]
[null,"Underground - Pressure assisted",null,null,0,0,0,null,1.0527538188574297,null,0]
[null,"Underground - Non Pressure assisted",null,null,0,0,0,null,0.66604675170182615,null,0]
[null,"Switchgear, Transformers, Substation",null,null,2.4184737508563749E-4,0.2212328773344254,0.22147472470951104,null,0,null,0]
["132kV","Overhead lines",null,null,0.24942627845677406,3.2279712653340712E-3,0.25265424972210815,null,4.6926150673739543E-3,null,0,null,null,null,0]
[null,"Underground - Pressure assisted",null,null,0.33499169835022374,0,0.33499169835022374,null,0.68781357599986381,null,0,null,null,null,0]
[null,"Underground - Non Pressure assisted",null,null,0,0,0,null,0,null,0,null,null,null,0]
[null,"Switchgear, Transformers, Substation",null,null,9.3964691992447169E-2,1.8011344994679559,1.8950991914604032,null,0.20076310582399742,null,0,null,null,null,0]
["Submarine cables - all voltages",null,null,null,0,0,{"$f":"SUM(E28:F28)","v":0},null,0,null,0,null,null,null,0]
["Non-QoS Faults",null,null,null,null,null,null,null,1.5263867188186959,null,0]
["Substation electricity",null,null,null,null,0,{"$f":"SUM(E30:F30)","v":0}]
["Diesel generation costs (permanent emergency back up on islands)",null,null,null,null,0,{"$f":"SUM(E31:F31)","v":0}]
["Third party cable damage - recoveries",null,null,null,null,null,null,null,-2.2974669300000001]
["Dismantlement",null,null,null,null,1.7147380000000001,{"$f":"SUM(E33:F33)","v":1.7147380000000001}]
["Total",null,null,null,{"$f":"SUM(E11:E33)","v":2.0989131038838234},{"$f":"SUM(F11:F33)","v":9.5844714061429741},{"$f":"SUM(G11:G33)","v":11.6833845100268},null,{"$f":"SUM(I11:I33)","v":23.07779493510921},null,{"$f":"SUM(K11:K33)","v":1.1892334999999996},null,0,0,0,null,0]
[]
[null,null,null,null,"Fault costs allocated to Opex and Capex",null,null,null,"Cash typicals",null,"Atypicals"]
[null,null,null,null,null,null,null,null,"£'m",null,"£'m"]
[null,null,null,null,"Fault opex",null,null,null,6.2858851681558727,null,1.1892334999999996]
[null,null,null,null,"Fault capex",null,null,null,16.791909766953342,null,0]
[null,null,null,null,"Total Fault Costs",null,null,null,23.077794935109214,null,1.1892334999999996]
[]
[null,null,"Tree Cutting",null,null,null,"£'m",null,null,null,null,null,"Tree Cutting",null,"£'m"]
[]
[null,null,"LV",null,null,null,3.1008321843072717,null,null,null,null,null,"132kV"]
[null,null,"HV",null,null,null,5.2820475418532782]
[null,null,"EHV",null,null,null,0.31448978018040508]
[null,null,"132kV",null,null,null,0.22677157365904441]
[null,null,"Total Tree Cutting",null,null,null,8.9241410800000001]

{"sheet":"RRP 2.4","index":22,"n_rows":89,"n_cols":12,"rows_kept":89,"cut":false,"hidden":false,"merged":[[75,2,75,3],[76,2,76,3],[81,2,81,3],[87,2,87,3],[88,2,88,3],[79,2,80,3],[82,2,82,3],[83,2,83,3],[84,2,84,3],[85,2,85,3],[86,2,86,3],[69,2,69,3],[70,2,70,3],[71,2,71,3],[72,2,72,3],[74,2,74,3],[64,2,64,3],[65,2,65,3],[66,2,66,3],[67,2,67,3],[68,2,68,3],[57,2,57,3],[60,2,60,3],[61,2,61,3],[62,2,62,3],[63,2,63,3],[17,2,17,3],[18,2,18,3],[19,2,19,3],[55,2,55,3],[56,2,56,3],[20,2,20,3],[21,2,21,3],[43,2,48,2],[49,2,54,2],[22,2,22,3],[23,2,23,3],[24,2,24,3],[7,2,8,3],[9,2,9,3],[14,2,14,3],[15,2,15,3],[16,2,16,3],[10,2,10,3],[11,2,11,3],[12,2,12,3],[13,2,13,3],[27,4,27,5],[30,2,31,2],[32,2,33,2],[34,2,36,2],[37,2,42,2],[27,2,29,3]]}
["Regulatory Reporting Pack (RRP)",null,null,null,"Index"]
[]
["2007/08"]
[]
["NEW AND REPLACEMENT ASSETS (EXCL. FAULTS)"]
[]
[null,null,"          Load Related New Connections & Reinforcement"]
[null,null,"Direct Costs only",null,"New Connections (carried out by DNO/RP)","New Connections (carried out by Third Parties)","Customer Specific Reinforcement - Chargeable","Customer Specific Reinforcement - Non Chargeable","General Reinforcement","Fault Level Reinforcement","Non Relevant Distributed Generation","Total"]
[null,null,null,null,"£'m","£'m","£'m","£'m","£'m","£'m","£'m","£'m"]
[null,null,"New Connections & Customer Specific Reinforcement:",null,null,null,null,null,null,null,null,0]
[null,null,"Connections provided at LV",null,30.64,0,0,6.24,null,null,null,36.880000000000003]
[null,null,"Connections provided at HV",null,5.54,0,0,1.74,null,null,null,7.28]
[null,null,"Connections provided at EHV",null,2.9520820421511697E-4,0,0,2.2740721737946355E-2,null,null,null,2.303592994216147E-2]
[null,null,"Connections provided at 132kV",null,0,0,0,0,null,null,null,0]
[null,null,"General Reinforcement:",null,null,null,null,null,null,null,null,0]
[null,null,"LV System",null,null,null,null,null,0.84,0,null,0.84]
[null,null,"HV System",null,null,null,null,null,4.6399999999999997,0,null,4.6399999999999997]
[null,null,"EHV System",null,null,null,null,null,8.34,0,null,8.34]
[null,null,"132kV System",null,null,null,null,null,1.84,0,null,1.84]
[null,null,"Non Relevant Distributed Generation",null,null,null,null,null,null,null,0,0]
[null,null,"Total Direct Costs excluding Reallocations",null,36.180295208204214,0,0,8.0027407217379469,15.66,0,0,59.843035929942175]
[null,null,"Direct Cost Reallocation ",null,0,null,0,0,0,0,0,0]
[null,null,"Total Costs including Reallocations",null,36.180295208204214,0,0,8.0027407217379469,15.66,0,0,59.843035929942161]
[null,null,"Customer Contributions (-ve)",null,-54.2,0,0,null,null,null,0,-54.2]
[null,null,"Total Costs less Capital Contributions",null,-18.019704791795789,0,0,8.0027407217379469,15.66,0,0,5.6430359299421582]
[]
[null,null,"          Non-load related replacement (Condition based)"]
[null,null,"Direct Costs only",null,"Condition based"]
[null,null,null,null,"Non-fault Related","Fault Related","Total\n"]
[null,null,null,null,"£'m","£'m","£'m"]
[null,null,"Metered LV Services","Overhead",0.24,4.6292713318415564E-2,0.28629271331841555]
[null,null,null,"Underground",3.64,0.21368979761934548,3.8536897976193458]
[null,null,"Un-metered LV Services","Overhead",0,0,0]
[null,null,null,"Underground",0,0,0]
[null,null,"LV System","Overhead Mains",0.58803843337182204,8.1542676024189704E-3,0.59619270097424104]
[null,null,null,"Underground Mains",5.3744597642332632,7.1868956503129411E-2,5.4463287207363926]
[null,null,null,"Switchgear (incl other plant & equipment)",2.3075336631865913,0.19078495292205472,2.4983186161086461]
[null,null,"HV","Overhead lines",10.349688615538659,6.9203446524298495E-2,10.418892062062957]
[null,null,null,"Underground Cables",3.54,1.24,4.78]
[null,null,null,"Submarine",0,0,0]
[null,null,null,"Switchgear (incl other plant & equipment)",3.74,0.54821908400879216,4.2882190840087926]
[null,null,null,"Transformers ",0.37899100091533766,0.32116813541497696,0.70015913633031457]
[null,null,null,"Substation",1.24,0.7,1.94]
[null,null,"EHV","Overhead lines",4.5747654658786413E-2,5.8758471721742428E-3,5.1623501830960657E-2]
[null,null,null,"Underground Cables",1.04,0.22404121029423843,1.2640412102942384]
[null,null,null,"Submarine",0,0,0]
[null,null,null,"Switchgear (incl other plant & equipment)",3.8405046976352872E-2,3.1893983520429048E-2,7.029903049678192E-2]
[null,null,null,"Transformers ",-4.391021798885289E-2,2.2469662936353614,2.2030560756465083]
[null,null,null,"Substation",1.592475814205339,4.2914531994428925E-3,1.5967672674047819]
[null,null,"132kV","Overhead lines",7.04,0,7.04]
[null,null,null,"Underground Cables",3.9669160593351322,0,3.9669160593351322]
[null,null,null,"Submarine Cables",0,0,0]
[null,null,null,"Switchgear (incl other plant & equipment)",11.94,0,11.94]
[null,null,null,"Transformers ",2.5499467560803706,0.4007368773762815,2.9506836334566522]
[null,null,null,"Substation",-2.0865269887229355E-2,1.1137266114561692E-2,-9.7280037726676632E-3]
[null,null,"Total Non-load replacement",null,59.547427320625566,6.3343242852259216,65.881751605851491]
[null,null,"Customer Contributions (-ve)",null,0,0,0]
[null,null,"Total Net Non-load replacement",null,59.547427320625566,6.3343242852259216,65.881751605851491]
[]
[null,null,"Non-load related (other)",null,"LV","HV","EHV","132kV","Total"]
[null,null,"Direct Costs only",null,"£'m","£'m","£'m","£'m","£'m"]
[null,null,"Quality of Service",null,0.11144405232676594,7.8516595613712017,1.2426650420184003E-2,0,7.9755302641181514]
[null,null,"Safety",null,1.44,0.81453474669442516,0.27667550609523239,5.6893104787277327E-2,2.5881033575769345]
[null,null,"Environment",null,7.9133040677175793E-3,3.1718213737327888E-2,6.7633462599588051E-2,0,0.10726498040463352]
[null,null,"Visual Amenity",null,1.7022079061462941E-2,2.8012541419207761E-2,0,0,4.5034620480670702E-2]
[null,null,"ESQCR",null,0,8.754704549918375E-3,0,0,8.754704549918375E-3]
[null,null,"Resilience",null,0,0,0,0,0]
[null,null,"Operational IT & Telecoms - BT 21CN",null,0,0,0,0,0]
[null,null,"Operational IT & Telecoms - other",null,0,2.0674791032064717E-4,5.2094717843987601E-2,0,5.2301465754308246E-2]
[null,null,"Non - rechargeable diversions",null,1.7071761753133965,1.9141859817989475,0.12842695304841664,2.2767498048319061,6.0265389149926669]
[null,null,"Total Non-load related (other non-fault)",null,3.2835556107693429,10.649072497481351,0.53725729000740863,2.3336429096191833,16.803528307877283]
[null,null,"Customer Contributions (-ve)",null,0,0,0,0,0]
[null,null,"Total Net Non-load related (other non-fault)",null,3.2835556107693429,10.649072497481351,0.53725729000740863,2.3336429096191833,16.803528307877283]
[]
[null,null,"Total Non-load related expenditure (direct costs)",null,{"$f":"+I71+G56","v":82.685279913728778}]
[null,null,"Customer Contributions (-ve)",null,0]
[null,null,"Total Net Non-load replacement (Direct Costs)",null,82.685279913728778]
[]
[null,null,"          Non-operational "]
[null,null,"Direct Costs only",null,"Total","Owned by DNO","Owned by related party"]
[null,null,null,null,"£'m","£'m","£'m"]
[null,null,"Vehicles",null,0.2,0.2]
[null,null,"Plant & Machinery",null,0]
[null,null,"Small Tools & Equipment",null,1.359,1.359]
[null,null,"Office Equipment",null,0]
[null,null,"Non-operational property",null,0]
[null,null,"IT Non-operational Capital Expenditure",null,0.68900000000000006,0.68900000000000006]
[null,null,"Telecoms Non-operational Capital Expenditures",null,0]
[null,null,"Total Non-operational New Assets & Replacement",null,2.2480000000000002,2.2480000000000002,0]

{"sheet":"RRP 2.6","index":23,"n_rows":99,"n_cols":12,"rows_kept":99,"cut":false,"hidden":false,"merged":[[98,2,98,5],[97,4,97,5],[82,3,82,5],[87,3,87,5],[88,3,88,5],[91,3,91,5],[93,3,93,5],[75,3,75,5],[77,4,77,5],[78,4,78,5],[79,4,79,5],[80,4,80,5],[13,3,13,5],[15,2,15,5],[19,2,19,5],[24,2,24,5],[21,3,21,5],[22,3,22,5],[17,3,17,5],[18,3,18,5],[8,2,8,5],[9,3,9,5],[10,3,10,5],[11,3,11,5],[12,3,12,5],[48,4,48,5],[49,4,49,5],[50,4,50,5],[33,4,33,5],[35,4,35,5],[36,4,36,5],[59,3,59,4],[64,3,64,4],[14,3,14,5],[16,3,16,5],[20,3,20,5],[37,4,37,5],[38,4,38,5],[39,4,39,5],[40,4,40,5],[41,4,41,5],[42,4,42,5],[43,4,43,5],[44,4,44,5],[45,4,45,5],[46,4,46,5],[47,4,47,5]]}
["Regulatory Reporting Pack",null,null,null,null,"Index"]
[]
["2007/08"]
[]
["MISCELLANEOUS"]
[]
[null,null,"Non-activity based costs (excluded from Table 2.2)(enter as positive)"]
[null,null,null,null,null,null,"£'m","£'m"]
[null,null,"Pass through Costs"]
[null,null,null,"Transmission exit charges",null,null,8]
[null,null,null,"Wheeled units imported",null,null,0]
[null,null,null,"Network rates",null,null,20.184226800000001]
[null,null,null,"Ofgem licence fee",null,null,1.45009349]
[null,null,null,"Shetland Balancing Costs (SHEPD only)",null,null,0]
[null,null,null,"Scottish Electricity Settlements run-off (Scottish DNOs only)",null,null,0,29.634320290000002]
[null,null,"Costs inside scope of DPCR4 allowances"]
[null,null,null,"Guaranteed standard of performance compensation payments",null,null,0]
[null,null,null,"Ex-gratia compensation payments",null,null,0.68664242000000009]
[null,null,null,"Bad debt expense (net of recoveries)",null,null,0.31245005660000003,0.99909247660000011]
[null,null,"Costs outside scope of DPCR4 allowances"]
[null,null,null,"(Profit)/loss on sale of fixed assets and scrap[(-ve)/+ve]",null,null,7.889699999997779E-4]
[null,null,null,"Statutory Depreciation on operational assets",null,null,36.130465450300001]
[null,null,null,"Pension deficit repair payments",null,null,7.62,43.7512544203]
[]
[null,null,"Total Non-Activity Based Costs",null,null,null,null,74.384667186900003]
[]
[]
[null,null,"OTHER ITEMS adjusting RAV"]
[null,null,null,"Proceeds of sale of assets and scrap (not recorded on Table 2.2)"]
[null,null,null,null,"Cash proceeds received on sale of:",null,"£'m"]
[null,null,null,null,"Operational assets (-ve)"]
[null,null,null,null,"Sales of scrap (-ve)",null,-0.50689503000000002]
[null,null,null,null,"Non-operational assets (-ve)",null,-0.17633336999999999]
[null,null,null,null,"Total",null,-0.68322839999999996]
[]
[null,null,null,null,"ANALYSIS OF ASSET DISPOSALS",null,"Cost","Depn.","Net Book Value","Net Sales Proceeds","(Profit) / Loss on Disposal","Asset Owner"]
[null,null,null,null,"Asset Type",null,"£m","£m","£m","£m","£m"]
[null,null,null,null,"Operational Land",null,1.5407160099999999,0.86561200999999999,0.67510399999999993,null,0.67510399999999993]
[null,null,null,null,"Operational Plant & Machinery ",null,1.36656172,1.3576483500000001,8.9133699999999205E-3,0.17633336999999999,-0.16742000000000007]
[null,null,null,null,"Scrap Metal",null,null,null,0,0.50689503000000002,-0.50689503000000002]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,null,null,"Total"]
[null,null,null,null,null,null,null,null,null,"OK","OK"]
[]
[null,null,null,"Use of System Bad Debts",null,null,"£m","£m"]
[null,null,null,null,null,null,null,"previously allowed"]
[null,null,null,null,"Costs incurred (excluding VAT)",null,0,0]
[null,null,null,null,"Receipts/(recoveries)",null,0,0]
[null,null,null,null,"Total Use of System Bad Debts",null,0]
[]
[null,null,null,"Salary sacrifice schemes (including flexible benefit schemes)",null,null,"Total","Direct capex","Direct opex, faults & Non-op capex","Indirect costs","All Other non-distrib'n activities"]
[null,null,null,null,null,null,"£m","£m","£m","£m","£m"]
[null,null,null,null,"Salary element sacrificed by employee(-ve)",null,0,0,0,0,0]
[null,null,null,null,"Additional employer pension contributions (+ve)",null,0,0,0,0,0]
[]
[null,null,null,"Lane rentals analysis: including logged up costs (see below):",null,null,"Total","Load Related New Connections & Reinforcement","Non-load non-fault new & replacement assets","Faults","Inspectns & Maint. (exc. Tree Cutting)","Tree Cutting"]
[null,null,null,null,null,null,"£m","£m","£m","£m","£m","£m"]
[null,null,null,null,"Fines and penalties",null,0.72593800000000008,0.51738600000000001,9.9901999999999991E-2,0.10865]
[null,null,null,null,"Road occupation costs",null,0]
[null,null,null,null,"Permit scheme costs",null,0]
[null,null,null,null,"Congestion charges",null,0]
[null,null,null,null,"Total per Table 2.2",null,0.72593800000000008,0.51738600000000001,9.9901999999999991E-2,0.10865,0,0]
[]
[]
[null,null,"Uncertain Costs (included in table 2.2 costs)"]
[]
[null,null,null,"Road Occupation & Permit Scheme Costs included within Lane Rentals, previously agreed in writing with Ofgem to be treated as logged up costs:",null,null,"Total","Load Related New Connections & Reinforcement","Non-load non-fault new & replacement assets","Faults","Inspectns & Maint. (exc. Tree Cutting)","Tree Cutting"]
[null,null,null,null,null,null,"£m","£m","£m","£m","£m","£m"]
[null,null,null,null,"Road occupation costs",null,0]
[null,null,null,null,"Permit scheme costs",null,0]
[null,null,null,null,"Congestion charges",null,0]
[null,null,null,null,"Total",null,0,0,0,0,0,0]
[]
[null,null,null,"Costs previously agreed with Ofgem in writing for additional security",null,null,0,null,0]
[]
[]
[null,null,"Miscellaneous costs (included in table 2.2 costs)"]
[null,null,null,null,null,null,"£m"]
[null,null,null,"Pension administration costs (reported in HR & Non-op training)"]
[null,null,null,"LV Control centre costs (where it remotely controls LV network)"]
[]
[null,null,null,null,null,null,"£m","km"]
[null,null,null,"Expenditure replacing Pressure Assisted cables"]
[]
[null,null,null,"Undergrounding in National Parks / AONB - direct costs",null,null,"£m","km"]
[null,null,null,null,"LV"]
[null,null,null,null,"HV"]
[null,null,null,null,"EHV/132kV"]
[null,null,null,null,"Undergrounding in National Parks / AONB - indirect costs"]
[null,null,"Total Undergrounding in National Parks / AONB"]

{"sheet":"RRP 5.1","index":24,"n_rows":73,"n_cols":9,"rows_kept":73,"cut":false,"hidden":false,"merged":[[4,0,4,2],[7,7,7,8],[7,4,7,6]]}
["Regulatory Reporting Pack (RRP)",null,null,null,null,"Index"]
[]
["2007/08"]
[]
["Network Data"]
[]
[null,null,null,"Units","2005/06","2006/07","2007/08","2008/09","2009/10"]
[null,null,"QUALITY OF SERVICE",null,"Historical data",null,null,"For Future years"]
[null,null,"Customer Numbers ","Millions",null,null,2434837]
[null,null,"Total CIs (Excluding EE)","CIs",null,null,2920359]
[null,null,"Total CMLs (Excluding EE)","CMLs",null,null,270558581]
[]
[null,null,"NETWORK ACTIVITY INDICATORS"]
[]
[null,null,"CONNECTIONS"]
[null,null,"Number of new connections"]
[null,null,"EHV (Includes 132kV)","No. Connections",null,null,0]
[null,null,"HV","No. Connections",null,null,20]
[null,null,"LV","No. Connections",null,null,20219]
[null,null,"DG","No. Connections",null,null,9]
[]
[null,null,"Total Connected Distributed Generation "]
[null,null,"132kV","MW",null,null,0]
[null,null,"EHV","MW",null,null,65]
[null,null,"HV","MW",null,null,95.1]
[null,null,"LV","MW",null,null,2.9]
[null,null,"Total",null,null,null,163]
[]
[null,null,"DEMANDS"]
[null,null,"System Maximum Demand ","MW",null,null,5215]
[null,null,"System Maximum Demand (Weather corrected)","MW",null,null,4974]
[]
[null,null,"Units Distributed"]
[null,null,"EHV (Includes 132kV)","GWh",null,null,616]
[null,null,"HV","GWh",null,null,9051]
[null,null,"LV","GWh",null,null,17084]
[null,null,"Total",null,null,null,26751]
[]
[null,null,"LOSSES"]
[null,null,"Units of distribution losses ","(GWh)",null,null,1381]
[null,null,"Losses ","(%)",null,null,5.1624238346230047E-2]
[]
[]
[null,null,"SYSTEM PARAMETERS"]
[]
[null,null,"Distribution Circuit Length - Overhead (km)"]
[null,null,"132kV","Circuit km",null,null,1368]
[null,null,"EHV","Circuit km",null,null,1830]
[null,null,"HV","Circuit km",null,null,14538]
[null,null,"LV","Circuit km",null,null,6120]
[null,null,"Total","Circuit km",null,null,23856]
[]
[null,null,"Distribution Circuit Length - Underground (km)"]
[null,null,"132kV","Circuit km",null,null,303]
[null,null,"EHV","Circuit km",null,null,380]
[null,null,"HV","Circuit km",null,null,12085]
[null,null,"LV","Circuit km",null,null,25340]
[null,null,"Total","Circuit km",null,null,38108]
[]
[null,null,"Distribution Circuit Length - Total (km)"]
[null,null,"132kV","Circuit km",null,null,1671]
[null,null,"EHV","Circuit km",null,null,2210]
[null,null,"HV","Circuit km",null,null,26623]
[null,null,"LV","Circuit km",null,null,31460]
[null,null,"Total","Circuit km",null,null,61964]
[]
[null,null,"Number of Substations and Switching Stations "]
[null,null,"132kV","No. Subs",null,null,84]
[null,null,"EHV ground mounted","No. Subs",null,null,138]
[null,null,"EHV pole mounted","No. Subs",null,null,3]
[null,null,"HV ground mounted","No. Subs",null,null,16210]
[null,null,"HV pole mounted","No. Subs",null,null,34355]
[null,null,"Total","No. Subs",null,null,50790]

{"sheet":"LR1 Refs","index":25,"n_rows":55,"n_cols":3,"rows_kept":55,"cut":false,"hidden":false,"merged":[[37,1,37,2],[38,1,38,2],[7,1,7,2],[8,1,8,2],[16,1,16,2],[17,1,17,2],[28,1,28,2],[29,1,29,2]]}
[]
[]
[]
[null,"LR1 an LR1 (opt3) formula references"]
[]
[null,"LR1 (opt3) variant"]
[null,"Cell Ref: B16"]
[null,"Connections Capex 2005/06 -2014/15 (£m)"]
[null,"Connections spend minus customer contributions (from FBPQ LR1 v5 opt3)"]
[]
[null,"LV",{"$f":"SUM('FBPQ LR1 - V5 opt3'!D227:M227,'FBPQ LR1 - V5 opt3'!I229:M229)-SUM('FBPQ LR1 - V5 opt3'!D250:M250,'FBPQ LR1 - V5 opt3'!I252:M252)","v":0}]
[null,"HV",{"$f":"(SUM('FBPQ LR1 - V5 opt3'!D231:H231,'FBPQ LR1 - V5 opt3'!I230:M230,'FBPQ LR1 - V5 opt3'!I233:M233)-SUM('FBPQ LR1 - V5 opt3'!D254:H254,'FBPQ LR1 - V5 opt3'!I253:M253,'FBPQ LR1 - V5 opt3'!I256:M256))","v":0}]
[null,"EHV",{"$f":"SUM('FBPQ LR1 - V5 opt3'!D235:H235,'FBPQ LR1 - V5 opt3'!I234:M234,'FBPQ LR1 - V5 opt3'!I237:M237)-SUM('FBPQ LR1 - V5 opt3'!D258:H258,'FBPQ LR1 - V5 opt3'!I257:M257,'FBPQ LR1 - V5 opt3'!I260:M260)","v":0}]
[null,"132 kV",{"$f":"SUM('FBPQ LR1 - V5 opt3'!D239:H239,'FBPQ LR1 - V5 opt3'!I238:M238)-SUM('FBPQ LR1 - V5 opt3'!D262:H262,'FBPQ LR1 - V5 opt3'!I261:M261)","v":0}]
[]
[null,"Cell Ref B36"]
[null,"Connections Capex 2005/06 -2014/15 (£m)"]
[null,"Connections spend minus customer contributions (from FBPQ LR1 v5 opt3)"]
[]
[null,"LV",{"$f":"SUM('FBPQ LR1 - V5 opt3'!D227:M227,'FBPQ LR1 - V5 opt3'!I229:M229)-SUM('FBPQ LR1 - V5 opt3'!D250:M250,'FBPQ LR1 - V5 opt3'!I252:M252)","v":0}]
[null,"LV/HV",{"$f":"(SUM('FBPQ LR1 - V5 opt3'!D231:H231,'FBPQ LR1 - V5 opt3'!I230:M230,'FBPQ LR1 - V5 opt3'!I233:M233)-SUM('FBPQ LR1 - V5 opt3'!D254:H254,'FBPQ LR1 - V5 opt3'!I253:M253,'FBPQ LR1 - V5 opt3'!I256:M256))*(C55)","v":0}]
[null,"HV",{"$f":"(SUM('FBPQ LR1 - V5 opt3'!D231:H231,'FBPQ LR1 - V5 opt3'!I230:M230,'FBPQ LR1 - V5 opt3'!I233:M233)-SUM('FBPQ LR1 - V5 opt3'!D254:H254,'FBPQ LR1 - V5 opt3'!I253:M253,'FBPQ LR1 - V5 opt3'!I256:M256))*(1-C55)","v":0}]
[null,"EHV",{"$f":"SUM('FBPQ LR1 - V5 opt3'!D235:H235,'FBPQ LR1 - V5 opt3'!I234:M234,'FBPQ LR1 - V5 opt3'!I237:M237)-SUM('FBPQ LR1 - V5 opt3'!D258:H258,'FBPQ LR1 - V5 opt3'!I257:M257,'FBPQ LR1 - V5 opt3'!I260:M260)","v":0}]
[null,"132 kV",{"$f":"SUM('FBPQ LR1 - V5 opt3'!D239:H239,'FBPQ LR1 - V5 opt3'!I238:M238)-SUM('FBPQ LR1 - V5 opt3'!D262:H262,'FBPQ LR1 - V5 opt3'!I261:M261)","v":0}]
[]
[]
[null,"LR1 variant"]
[null,"Cell Ref: B16"]
[null,"Connections Capex 2005/06 -2014/15 (£m)"]
[null,"Connections spend minus customer contributions (from FBPQ LR1 v5 opt3)"]
[]
[null,"LV",{"$f":"SUM('FBPQ LR1'!D82:M82)-SUM('FBPQ LR1'!D110:M110)","v":29.935989292598578}]
[null,"HV",{"$f":"(SUM('FBPQ LR1'!D86:M86)-SUM('FBPQ LR1'!D114:M114))","v":9.6943771821511007}]
[null,"EHV",{"$f":"(SUM('FBPQ LR1'!D90:M90)-SUM('FBPQ LR1'!D118:M118))","v":0}]
[null,"132 kV",{"$f":"(SUM('FBPQ LR1'!D94:M94)-SUM('FBPQ LR1'!D122:M122))","v":0}]
[]
[null,"Cell Ref B36"]
[null,"Connections Capex 2005/06 -2014/15 (£m)"]
[null,"Connections spend minus customer contributions (from FBPQ LR1 v5 opt3)"]
[]
[null,"LV",{"$f":"SUM('FBPQ LR1'!D82:M82)-SUM('FBPQ LR1'!D110:M110)","v":29.935989292598578}]
[null,"LV/HV",{"$f":"(SUM('FBPQ LR1'!D86:M86)-SUM('FBPQ LR1'!D114:M114))*C55","v":2.3811685205236506}]
[null,"HV",{"$f":"(SUM('FBPQ LR1'!D86:M86)-SUM('FBPQ LR1'!D114:M114))*(1-C55)","v":7.3132086616274492}]
[null,"EHV",{"$f":"(SUM('FBPQ LR1'!D90:M90)-SUM('FBPQ LR1'!D118:M118))","v":0}]
[null,"132 kV",{"$f":"(SUM('FBPQ LR1'!D94:M94)-SUM('FBPQ LR1'!D122:M122))","v":0}]
[]
[]
[]
[]
[]
[]
[]
[]
[]
[null,null,{"$f":"'Calc-Net capex'!C50/'Calc-Net capex'!C51","v":0.24562367192683227}]